{"id":33524,"date":"2020-03-05T08:42:00","date_gmt":"2020-03-05T12:42:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/politica\/20200305\/trump-le-dio-un-shout-out-a-wanda-vazquez\/"},"modified":"2025-07-15T15:30:13","modified_gmt":"2025-07-15T15:30:13","slug":"trump-le-dio-un-shout-out-a-wanda-vazquez","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200305\/trump-le-dio-un-shout-out-a-wanda-vazquez\/","title":{"rendered":"Trump le dio un \u2018shout-out\u2018 a Wanda V\u00e1zquez"},"content":{"rendered":"<p>La gobernadora Wanda V\u00e1zquez Garced comparti\u00f3 \u00abagradecida\u00bb el saludo que le dio el presidente Donald Trump mientras ambos participaban esta semana de la reuni\u00f3n del Latino Coalition.<\/p>\n<p>Al saludar a varias personas en el sal\u00f3n, y luchando contra las luces y contra la pronunciaci\u00f3n del apellido de la Gobernadora, Trump la mencion\u00f3, lo que dej\u00f3 a la Mandataria \u00abagradecida del reconocimiento\u00bb.<\/p>\n<p>https:\/\/twitter.com\/wandavazquezg\/status\/1235312777885110275<\/p><div class=\"notic-content-middle\" id=\"notic-378945058\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>En la reuni\u00f3n del grupo, orientado hacia los hispanos que son due\u00f1os de negocio en los Estados Unidos, a la Gobernadora se le concedi\u00f3 espacio para hablar sobre c\u00f3mo su administraci\u00f3n ha promovido las empresas lideradas por mujeres. Adem\u00e1s, el nuevo coordinador de Casa Blanca para la reconstrucci\u00f3n de Puerto Rico, el contralmirante Peter Brown, habl\u00f3 sobre su reci\u00e9n iniciada gesti\u00f3n.<\/p>\n<p>https:\/\/twitter.com\/LatinoCoalition\/status\/1235214921962606592<\/p>","protected":false},"excerpt":{"rendered":"<p>La gobernadora Wanda V\u00e1zquez Garced comparti\u00f3 \u00abagradecida\u00bb el saludo que le dio el presidente Donald Trump mientras ambos participaban esta semana de la reuni\u00f3n del Latino Coalition. Al saludar a varias personas en el sal\u00f3n, y luchando contra las luces y contra la pronunciaci\u00f3n del apellido de la Gobernadora, Trump la mencion\u00f3, lo que dej\u00f3 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":350950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-33524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=33524"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33524\/revisions"}],"predecessor-version":[{"id":350951,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33524\/revisions\/350951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/350950"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=33524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=33524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=33524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}