{"id":33314,"date":"2014-10-22T00:00:00","date_gmt":"2014-10-22T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20141022\/cuestionan-destino-mas-de-1-millon-que-eran-para-servicios-a-ninos-de-educ\/"},"modified":"2025-07-15T15:46:01","modified_gmt":"2025-07-15T15:46:01","slug":"cuestionan-destino-mas-de-1-millon-que-eran-para-servicios-a-ninos-de-educ","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20141022\/cuestionan-destino-mas-de-1-millon-que-eran-para-servicios-a-ninos-de-educ\/","title":{"rendered":"Cuestionan destino m\u00e1s de $1 mill\u00f3n que eran para servicios a ni\u00f1os de educ"},"content":{"rendered":"<p>Un mill\u00f3n treinta y dos mil d\u00f3lares que estaban destinados para proveer equipo y materiales a 10 centros de educaci\u00f3n f\u00edsica adaptada para estudiantes de educaci\u00f3n especial, nunca fueron asignados al Departamento de Recreaci\u00f3n y Deportes (DRD).<\/p>\n<p>Las declaraciones las realiz\u00f3 la licenciada Nilda D\u00edaz, directora de la Divisi\u00f3n Legal del DRD, quien represent\u00f3 al secretario Ram\u00f3n Orta a una vista p\u00fablica de la Comisi\u00f3n de Educaci\u00f3n, Formaci\u00f3n y Desarrollo del Individuo del Senado.<\/p>\n<p>La revelaci\u00f3n se produjo en una vista p\u00fablica presidida por la senadora Maritere Gonz\u00e1lez L\u00f3pez, en virtud de la Resoluci\u00f3n del Senado 246, que ordena una investigaci\u00f3n sobre los centros de educaci\u00f3n f\u00edsica adaptada en varios centros a saber: Aguada, Arecibo, Bayam\u00f3n, Cabo Rojo, Corozal, Fajardo, Guayama, Gurabo, San Juan y Vieques, establecidos mediante un convenio suscrito en el a\u00f1o 2010 por el DRD y el Departamento de Educaci\u00f3n.<\/p>\n<p>Seg\u00fan reza la exposici\u00f3n de motivos de la resoluci\u00f3n, de la autor\u00eda de la senadora Mar\u00eda de Lourdes Santiago Negr\u00f3n, &#8216;informes de prensa se\u00f1alan que el DRD, durante la incumbencia de Henry Newman, la agencia desvi\u00f3 el dinero para proveer dichos servicios a otro programa de la agencia, quedando desprovistos de materiales y recursos los diez (10) centros establecidos a trav\u00e9s de la Isla para ofrecer tan importante servicio&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-3411087832\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Por su parte, la senadora destac\u00f3 que &#8216;en este se contrat\u00f3 a la empresa Educational Consulting Company, que cobr\u00f3, pero no se constat\u00f3 el trabajo en los centros de educaci\u00f3n f\u00edsica adaptada. Esta servidora tiene un compromiso serio y en\u00e9rgico con asegurarle al Pa\u00eds que se cumpla con esta poblaci\u00f3n necesitada. El pr\u00f3ximo paso es a concluir con el proceso de hallazgos y presentar un informe parcial con referidos y recomendaciones&#8217;.<\/p>\n<p>De igual forma, la Comisi\u00f3n atendi\u00f3 la Resoluci\u00f3n del Senado 242, para investigar los servicios vocacionales disponibles a la poblaci\u00f3n de educaci\u00f3n especial. En cuanto a los hallazgos de la misma la senadora dijo estar &#8216;consciente de la importancia de estos ofrecimientos a los miles y miles de ni\u00f1os y j\u00f3venes de educaci\u00f3n especial que tienen el derecho de recibir estas ayudas vocacionales para integrarse de manera correcta al mundo laboral y\/o universitario&#8217;.<\/p>\n<p>Por otro lado mediante, la Resoluci\u00f3n del Senado 243 se investigan los casos que pudieran constituir maltrato institucional por parte del DE. La presidenta de la Comisi\u00f3n opin\u00f3 que &#8216;el Departamento de Educaci\u00f3n debe establecer y aclarar cu\u00e1les son los protocolos de prevenci\u00f3n, educaci\u00f3n y manejo de posibles casos de maltrato institucional, si es que existe alg\u00fan protocolo&#8217;.<\/p>\n<p>En conclusi\u00f3n, Gonz\u00e1lez expuso que seg\u00fan el censo del 2010 m\u00e1s de una quinta parte de la poblaci\u00f3n tiene uno o m\u00e1s impedimentos, &#8216;y eso no se debe traducir en segregaci\u00f3n y olvido, sino en mayores y mejores servicios a este segmento de nuestra poblaci\u00f3n&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un mill\u00f3n treinta y dos mil d\u00f3lares que estaban destinados para proveer equipo y materiales a 10 centros de educaci\u00f3n f\u00edsica adaptada para estudiantes de educaci\u00f3n especial, nunca fueron asignados al Departamento de Recreaci\u00f3n y Deportes (DRD). Las declaraciones las realiz\u00f3 la licenciada Nilda D\u00edaz, directora de la Divisi\u00f3n Legal del DRD, quien represent\u00f3 al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":352085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=33314"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33314\/revisions"}],"predecessor-version":[{"id":352086,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/33314\/revisions\/352086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/352085"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=33314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=33314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=33314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}