{"id":32769,"date":"2018-05-12T00:00:00","date_gmt":"2018-05-12T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/cine\/pop\/20180512\/solo-a-star-wars-story-radiografia-del-origen-de-han-solo\/"},"modified":"2025-07-15T16:24:24","modified_gmt":"2025-07-15T16:24:24","slug":"solo-a-star-wars-story-radiografia-del-origen-de-han-solo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/entretenimiento\/cine\/20180512\/solo-a-star-wars-story-radiografia-del-origen-de-han-solo\/","title":{"rendered":"&#8216;Solo: A Star Wars Story&#8217;: radiograf\u00eda del origen de Han Solo"},"content":{"rendered":"<p><i>Anticipan para 2019 la novena pel\u00edcula<\/i><\/p>\n<p>La multimillonaria franquicia de &#8216;Star Wars&#8217; present\u00f3 hoy en Pasadena (California) &#8216;Solo: A Star Wars Story&#8217;, la segunda entrega de su universo derivado, esta vez con una inmersi\u00f3n en la juventud de Han Solo que permite conocer el origen del car\u00e1cter complicado, canalla y p\u00edcaro del personaje.<\/p>\n<p>&#8216;Antes del rodaje de la pel\u00edcula fui a hablar con Harrison Ford, quer\u00eda mostrarle mi respeto y tener su bendici\u00f3n&#8217;, explic\u00f3 Alden Ehrenreich, el actor encargado de encarnar al joven Solo, que no duda en recrear con gran fidelidad algunos de los gestos y manierismos m\u00e1s reconocibles del celebre contrabandista.<\/p>\n<p>&#8216;Harrison vio la pel\u00edcula y le encant\u00f3&#8217;, agreg\u00f3 entre risas el actor, que acudi\u00f3 a la presentaci\u00f3n del filme en el Centro de Convenciones de Pasadena (California) junto a Emilia Clarke, Donald Glover, Woody Harrelson, Thandie Newton, Phoebe Waller-Bridge, Paul Bettany y el director del filme, Ron Howard.<\/p>\n<p>&#8216;He hecho muchas pel\u00edculas en mi vida, pero el fervor que hay por &#8216;Star Wars&#8217; es algo inigualable. Es una sensaci\u00f3n parecida a la que ten\u00eda rodando el documental sobre The Beatles. \u00a1Sab\u00eda que no pod\u00eda cagarla! Son obras que importan de verdad a los fans&#8217;, declar\u00f3 el realizador, que reemplaz\u00f3 a Phil Lord y Christopher Miller, despedidos por Lucasfilm.<\/p>\n<p>Lord y Miller fueron despedidos tras haber trabajado en la pel\u00edcula durante cuatro meses y medio. El d\u00fao mantuvo importantes &#8216;diferencias creativas&#8217; con Lawrence Kasdan, guionista de la cinta junto a su hijo, Jonathan.<\/p>\n<p>&#8216;Cuando me incorpore, lo m\u00e1s importante estaba hecho, que era tener el gui\u00f3n y el reparto listo. Soy una persona que ama colaborar con los dem\u00e1s. La clave aqu\u00ed era ver c\u00f3mo el resto de personajes impactan en la forma de ser de Han. Aqu\u00ed logramos comprender por que se comporta como lo hace en el futuro&#8217;, dijo Howard al respecto.<\/p>\n<p>La cinta, de estreno el d\u00eda 25, arranca con un golpe que tratan de ejecutar Han y Qi&#8217;ra (Clarke), pero la pareja no logra culminar su escapada y se ven separados a la fuerza. A\u00f1os despues, Han, tratando de mostrar su val\u00eda como piloto, volver\u00e1 a reencontrarse con su amada, aunque la personalidad de la joven ha cambiado tras formar parte de una red de criminales.<\/p>\n<p>En ese viaje, Han conocer\u00e1 a su futuro copiloto, Chewbacca, y al cazarrecompensas Lando Calrissian, con quien forja una complicada amistad.<\/p><div class=\"notic-content-middle\" id=\"notic-2545520670\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Han es un personaje que siempre he amado&#8217;, reconoci\u00f3 Lawrence Kasdan. &#8216;Es temerario, c\u00ednico, no conf\u00eda en nadie y es un poco est\u00fapido, algo que me encanta. Hace y dice cosas que no deber\u00eda, pero es parte de su encanto. Y aqu\u00ed le presentamos dentro de un grupo donde cada uno quiere algo en concreto&#8217;, se\u00f1al\u00f3 el guionista.<\/p>\n<p>&#8216;Dentro de el hay un gran conflicto: sus ideales y sus deseos est\u00e1n en guerra permanentemente&#8217;, indic\u00f3.<\/p>\n<p>Thandie Newton, que interpreta a una experta ladrona en el filme, dijo que &#8216;los personajes de esta franquicia tienen una carisma especial&#8217; y elogi\u00f3 el candor con el que se trazan los personajes m\u00e1s infantiles.<\/p>\n<p>&#8216;Es el material de que est\u00e1n hechos los sue\u00f1os&#8217;, sostuvo la brit\u00e1nica, quien se emocion\u00f3 recordando c\u00f3mo uno de sus hijos dio un abrazo a uno de los robots que aparecen en la pel\u00edcula.<\/p>\n<p>La cinta es la segunda cinta escindida del universo &#8216;Star Wars&#8217; tras &#8216;Rogue One&#8217;, estrenada en 2016.<\/p>\n<p>La franquicia, una m\u00e1quina de hacer dinero para Disney, seguir\u00e1 viento en popa con el noveno cap\u00edtulo de &#8216;Star Wars&#8217;, previsto para 2019.<\/p>\n<p>Adem\u00e1s, Rian Johnson, director y guionista de &#8216;Star Wars VIII: The Last Jedi&#8217;, se har\u00e1 cargo de una nueva trilog\u00eda que prescindir\u00e1 de los Skywalker y apostar\u00e1 por nuevos personajes.<\/p>\n<p>David Benioff y D.B. Weiss, creadores de la serie &#8216;Game of Thrones&#8217;, tambien escribir\u00e1n una serie de pel\u00edculas independientes de la saga Skywalker.<\/p>\n<p>Y, por si fuera poco, Jon Favreau, se encargar\u00e1 de escribir la primera serie de acci\u00f3n real basada en personajes cl\u00e1sicos de la saga.<\/p>","protected":false},"excerpt":{"rendered":"<p>Anticipan para 2019 la novena pel\u00edcula La multimillonaria franquicia de &#8216;Star Wars&#8217; present\u00f3 hoy en Pasadena (California) &#8216;Solo: A Star Wars Story&#8217;, la segunda entrega de su universo derivado, esta vez con una inmersi\u00f3n en la juventud de Han Solo que permite conocer el origen del car\u00e1cter complicado, canalla y p\u00edcaro del personaje. &#8216;Antes del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":355393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-32769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/32769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=32769"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/32769\/revisions"}],"predecessor-version":[{"id":355396,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/32769\/revisions\/355396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/355393"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=32769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=32769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=32769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}