{"id":31750,"date":"2016-04-19T00:00:00","date_gmt":"2016-04-19T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20160419\/inivitan-a-reconocer-a-las-figuras-del-rock-n-roll-boricua\/"},"modified":"2025-07-15T17:46:57","modified_gmt":"2025-07-15T17:46:57","slug":"inivitan-a-reconocer-a-las-figuras-del-rock-n-roll-boricua","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160419\/inivitan-a-reconocer-a-las-figuras-del-rock-n-roll-boricua\/","title":{"rendered":"Inivitan a reconocer a las figuras del rock n&#8217; roll boricua"},"content":{"rendered":"<p>Cientos de figuras de la m\u00fasica popular boricua se dar\u00e1n cita este s\u00e1bado en la quinta edici\u00f3n de la premiaci\u00f3n del Sal\u00f3n de la Fama del Rock N&#8217; Roll en Puerto Rico.<\/p>\n<p>&#8216;Nos sentimos honrados con la participaci\u00f3n de artistas que deleitar\u00e1n a los presentes en esta edici\u00f3n. Feliz es poco; no tengo palabras para expresar mi gratitud ante todo el componente de esta fundaci\u00f3n y todo el trabajo que este equipo ha realizado para fomentar y documentar el Rock N&#8217; Roll en nuestro terru\u00f1o&#8217;, expres\u00f3 la tambi\u00e9n coordinadora de la organizaci\u00f3n, Mariliana Gonz\u00e1lez-Deitrick.<\/p>\n<p>Por su parte, el confundador del evento, Joey Barbosa indic\u00f3 que el mismo se celebrar\u00e1 en Shannan&#8217;s Pub en Guaynabo a partir de las 6:00 p.m., con la presencia en tarima de Vivanativa, The Classics, Child, RPM, Vodoo Lounge: The Rolling Stones Tribute, The All Star Band, y The Caribbean Blues Brothers, entre otros.<\/p>\n<p>Adem\u00e1s del junte musical, se presentar\u00e1n visuales de la historia del rock n&#8217; roll en el pa\u00eds y se exaltar\u00e1n a varios artistas como Vivanativa, Los Diamantes, Los H\u00e9roes del Rock N&#8217; Roll, Osvaldo Alcaraz, Joe V\u00e1zquez y Alcides Figueroa, con el &#8216;Lifetime Achievement Award&#8217;. Figueroa tambi\u00e9n fungir\u00e1 como director musical del evento.<\/p>\n<p>El evento es abierto al p\u00fablico general. Los boletos se vender\u00e1n en la entrada a $25.<\/p>\n<p>La Puerto Rico Rock N&#8217;Roll Hall of Fame (PRRRHF) es una fundaci\u00f3n sin fines de lucro creada en el 2012 por Barbosa y Gonz\u00e1lez-Deitrick, junto a pioneros de este g\u00e9nero en el pa\u00eds. A este organismo pertenecen m\u00fasicos de varias generaciones desde la llegada del g\u00e9nero a Puerto Rico. Su misi\u00f3n es documentar la historia y la trayectoria del rock, exaltar el talento de quienes han laborado desde hace cinco d\u00e9cadas a promover el g\u00e9nero, crear empleos para los m\u00fasicos, y desarrollar proyectos como la \u00c9gida del M\u00fasico, en el cual trabajan.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cientos de figuras de la m\u00fasica popular boricua se dar\u00e1n cita este s\u00e1bado en la quinta edici\u00f3n de la premiaci\u00f3n del Sal\u00f3n de la Fama del Rock N&#8217; Roll en Puerto Rico. &#8216;Nos sentimos honrados con la participaci\u00f3n de artistas que deleitar\u00e1n a los presentes en esta edici\u00f3n. Feliz es poco; no tengo palabras para [&hellip;]<\/p>","protected":false},"author":0,"featured_media":362041,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-31750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=31750"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31750\/revisions"}],"predecessor-version":[{"id":362043,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31750\/revisions\/362043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/362041"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=31750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=31750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=31750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}