{"id":31179,"date":"2014-04-09T00:00:00","date_gmt":"2014-04-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20140409\/activa-plan-para-atender-perdida-de-bioluminiscencia-en-bahia-de-vieques\/"},"modified":"2025-07-15T18:29:35","modified_gmt":"2025-07-15T18:29:35","slug":"activa-plan-para-atender-perdida-de-bioluminiscencia-en-bahia-de-vieques","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140409\/activa-plan-para-atender-perdida-de-bioluminiscencia-en-bahia-de-vieques\/","title":{"rendered":"Activa plan para atender p\u00e9rdida de bioluminiscencia en bah\u00eda de Vieques"},"content":{"rendered":"<p>La secretaria del Departamento de Recursos Naturales y Ambientales, Carmen Guerrero Perez, inform\u00f3 el miercoles, que se ha registrado una reducci\u00f3n significativa de bioluminiscencia en la bah\u00eda de Mosquito en Vieques, por lo que se implementar\u00e1 un plan dirigido a descubrir las causas y las acciones que se deben implementar.<\/p>\n<p>&#8216;Esta circunstancia, que tanto preocupa a los viequenses y a todos los puertorrique\u00f1os, servir\u00e1 de laboratorio para la investigaci\u00f3n y para adiestrar personal de la agencia en el tema de bioluminiscencia, tomando en consideraci\u00f3n que Puerto Rico, es de los pocos lugares en el mundo con cuerpos de agua bioluminiscentes. Puerto Rico, afortunadamente, cuenta con m\u00e1s de un cuerpo de agua bioluminiscente que cautiva a los turistas locales e internacionales&#8217;, manifest\u00f3 Guerrero P\u00e9rez en un comunicado de prensa.<\/p>\n<p>Guerrero P\u00e9rez indic\u00f3 que contact\u00f3 un equipo de cient\u00edficos y especialistas que investigar\u00e1n las circunstancias que provocan la p\u00e9rdida de brillo de esa bah\u00eda, que es uno de los principales atractivos de Vieques a nivel internacional y motor econ\u00f3mico.<\/p>\n<p>Asimismo, la titular dio la bienvenida a las universidades, empresas y organizaciones que se quieran unir para proteger el extraordinario recurso de incalculable valor ecol\u00f3gico, tur\u00edstico y socioecon\u00f3mico. Personal del DRNA trabaja en identificar los fondos para sufragar las investigaciones.<\/p>\n<p>La secretaria, adem\u00e1s, orden\u00f3 al Cuerpo de Vigilantes reforzar la vigilancia para evitar la entrada de comerciantes no bonafides que transportan en kayaks a los visitantes por la bah\u00eda y que comprometen su capacidad e impactan los recursos.<\/p>\n<p>Mencion\u00f3 que a principios de enero de 2014 se report\u00f3 otro evento de reducci\u00f3n de bioluminiscencia en Bah\u00eda Mosquito por un breve periodo que los cient\u00edficos concluyeron se debi\u00f3 a los fuertes oleajes y marejadas caracter\u00edsticos de ese \u00e9poca del a\u00f1o.<\/p>\n<p>Cuando la comunidad alert\u00f3 de este segundo episodio, la secretaria tom\u00f3 la decisi\u00f3n de ampliar el \u00e1mbito de investigaci\u00f3n con un equipo de cient\u00edficos locales e internacionales, en directa colaboraci\u00f3n con el Fideicomiso de Historia y Conservaci\u00f3n de Vieques, entidad con la que la agencia tiene varios acuerdos de colaboraci\u00f3n para la protecci\u00f3n y conservaci\u00f3n de la Bah\u00eda Mosquito en Vieques.<\/p>\n<p>En Puerto Rico, existen varios cuerpos de aguas biolumniscentes debido a la presencia de los microorganismos conocidos como dinoflageldos que producen ese fen\u00f3meno.<\/p>\n<p>Durante el pasado mes de noviembre de 2013, se detect\u00f3 una reducci\u00f3n en la bioluminscencia en la Laguna Grande de Fajardo y la conclusi\u00f3n cient\u00edfica para esa reducci\u00f3n se debi\u00f3 a un evento de marejadas de gran magnitud y de larga duraci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La secretaria del Departamento de Recursos Naturales y Ambientales, Carmen Guerrero Perez, inform\u00f3 el miercoles, que se ha registrado una reducci\u00f3n significativa de bioluminiscencia en la bah\u00eda de Mosquito en Vieques, por lo que se implementar\u00e1 un plan dirigido a descubrir las causas y las acciones que se deben implementar. &#8216;Esta circunstancia, que tanto preocupa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31179","post","type-post","status-publish","format-standard","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=31179"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31179\/revisions"}],"predecessor-version":[{"id":365359,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/31179\/revisions\/365359"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=31179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=31179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=31179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}