{"id":30975,"date":"2013-11-18T00:00:00","date_gmt":"2013-11-18T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20131118\/indios-vinieron-de-atras-para-vencer-en-caguas\/"},"modified":"2025-07-15T18:47:21","modified_gmt":"2025-07-15T18:47:21","slug":"indios-vinieron-de-atras-para-vencer-en-caguas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20131118\/indios-vinieron-de-atras-para-vencer-en-caguas\/","title":{"rendered":"Indios vinieron de atr\u00e1s para vencer en Caguas"},"content":{"rendered":"<p>Un ramillete de cuatro anotaciones en el octavo episodio condujo a los Indios de Mayag\u00fcez sobre los Criollos de Caguas con pizarra final de 5-3, ante unos 5,000 fan\u00e1ticos que dijeron presentes en el Estadio Yldefonso Sol\u00e1 Morales de esta ciudad.<\/p>\n<p>La combinaci\u00f3n de victoria y derrota de ambos equipos, devuelve a los ganadores al primer lugar con marca de 6-3, mientras que Caguas desciende al segundo puesto con r\u00e9cord de 7-5. El otro juego entre Ponce y Carolina est\u00e1 en desarrollo, lo que implica que el resultado define la segunda y tercera posici\u00f3n de la tabla global.<\/p>\n<p>Sencillo abridor de Aaron Bates en la segunda entrada comenz\u00f3 el ataque de los locales, adelantando a segunda con batazo en el cuadro de Ram\u00f3n \u2018Bigote&#8217; Castro. Dos errores al hilo de Danny Gonz\u00e1lez e Irving Fal\u00fa en roletines de Jorge Padilla y Edgardo B\u00e1ez llenaron las bases, anotando los primeros dos con sencillo de Luis Mateo, sumando una carrera adicional con otro hit impulsador de Juan Silva que dej\u00f3 el marcador 3-0.<\/p>\n<p>El cubano Fernando Hern\u00e1ndez tir\u00f3 las primeras cinco entradas en cero por los Criollos, pero en el sexto episodio Mayag\u00fcez libr\u00f3 la blanqueada con pasaporte a Irving Fal\u00fa, llegando a segunda con rodado de Kenny Vargas. Luego de que Randy Ruiz fuera ponchado, Jerry Sands recibi\u00f3 otro boleto gratis, al tiempo que Fal\u00fa se robaba la tercera base, lo que provoc\u00f3 la salida del iniciador. Luis \u2018Wicho&#8217; Figueroa recibi\u00f3 al zurdo Luis Enrique Gonz\u00e1lez con sencillo al izquierdo para la primera anotaci\u00f3n de los occidentales.<\/p><div class=\"notic-content-middle\" id=\"notic-1808515123\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>En el octavo los Indios tomaron el comando con ramillete de cuatro carreras con imparables de Kenny Vargas y Randy Ruiz, quien fue sustituido por el corredor emergente Noel Cuevas. Luego de un out, el dirigente criollo Pedro L\u00f3pez trajo a relevar al zurdo Ryan O&#8217;Rourke, que permiti\u00f3 sencillo de \u2018Wicho&#8217; Figueroa que congestion\u00f3 el tr\u00e1nsito.<\/p>\n<p>El importado Chris Curley limpi\u00f3 las bases con doblete en un batazo que le pas\u00f3 la pelota por encima del patrullero derecho Juan Silva, anotando la cuarta carrera los visitantes gracias a un tejano al central del bate de Ren\u00e9 Rivera, quien hab\u00eda entrado a la receptor\u00eda en la entrada anterior.<\/p>\n<p>La victoria fue Nelvin Fuentes (2-0) a pesar de solo realizar un out, con juego salvado para Tyler Herron, su quinto de la temporada. El derrotado fue Ryan O&#8217;Rourke (0-1) al permitir las dos carreras que decidieron el juego a favor de los Indios.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un ramillete de cuatro anotaciones en el octavo episodio condujo a los Indios de Mayag\u00fcez sobre los Criollos de Caguas con pizarra final de 5-3, ante unos 5,000 fan\u00e1ticos que dijeron presentes en el Estadio Yldefonso Sol\u00e1 Morales de esta ciudad. La combinaci\u00f3n de victoria y derrota de ambos equipos, devuelve a los ganadores al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-30975","post","type-post","status-publish","format-standard","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=30975"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30975\/revisions"}],"predecessor-version":[{"id":366735,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30975\/revisions\/366735"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=30975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=30975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=30975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}