{"id":30928,"date":"2013-12-09T00:00:00","date_gmt":"2013-12-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20131209\/siete-arrestados-por-drogas-y-armas-en-barriada-morales\/"},"modified":"2025-07-15T18:50:44","modified_gmt":"2025-07-15T18:50:44","slug":"siete-arrestados-por-drogas-y-armas-en-barriada-morales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20131209\/siete-arrestados-por-drogas-y-armas-en-barriada-morales\/","title":{"rendered":"Siete arrestados por drogas y armas en barriada Morales"},"content":{"rendered":"<p>Agentes adscritos a la Divisi\u00f3n de Drogas y Narc\u00f3ticos del \u00e1rea de Caguas arrestaron a seis hombres y una mujer la ma\u00f1ana del s\u00e1bado en la barriada Morales de Caguas, por delitos de armas y drogas. De acuerdo con la Polic\u00eda, los arrestados fueron identificados como Nidia Marie De Jes\u00fas Moyet de 26 a\u00f1os; Alejandro Rodr\u00edguez Navarro, de 33; Dervin Joel Neris Arroyo, de 26; Wilfredo Hern\u00e1ndez Massa, de 23; Josue Marrero R\u00edos, de 19 y Emanuel Laboy Delgado, tambien de 19.<\/p>\n<p>A los sujetos, residentes del citado pueblo, se les ocuparon 19 bolsas de coca\u00edna, tres bolsas de marihuana, 20 c\u00e1psulas de crack, 776 d\u00f3lares en efectivo y una pistola Glock calibre 9 mil\u00edmetros y su cargador con 15 municiones.<\/p><div class=\"notic-content-middle\" id=\"notic-543177656\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El agente Arturo Pomales Alicea de la Divisi\u00f3n Drogas Caguas consultar\u00eda el caso con el fiscal de turno para la posible radicaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Agentes adscritos a la Divisi\u00f3n de Drogas y Narc\u00f3ticos del \u00e1rea de Caguas arrestaron a seis hombres y una mujer la ma\u00f1ana del s\u00e1bado en la barriada Morales de Caguas, por delitos de armas y drogas. De acuerdo con la Polic\u00eda, los arrestados fueron identificados como Nidia Marie De Jes\u00fas Moyet de 26 a\u00f1os; Alejandro [&hellip;]<\/p>","protected":false},"author":0,"featured_media":367006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-30928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=30928"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30928\/revisions"}],"predecessor-version":[{"id":367008,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/30928\/revisions\/367008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/367006"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=30928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=30928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=30928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}