{"id":29318,"date":"2014-12-10T00:00:00","date_gmt":"2014-12-10T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20141210\/cielo-parcialmente-nublado-y-pocos-aguaceros\/"},"modified":"2025-07-15T21:01:20","modified_gmt":"2025-07-15T21:01:20","slug":"cielo-parcialmente-nublado-y-pocos-aguaceros","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20141210\/cielo-parcialmente-nublado-y-pocos-aguaceros\/","title":{"rendered":"Cielo parcialmente nublado y pocos aguaceros"},"content":{"rendered":"<p>El Servicio Nacional de Meteorolog\u00eda (SNM) espera que cielo parcialmente nublado contin\u00fae hoy con poca actividad de aguaceros. Los vientos podr\u00edan traer algunas nubes con aguaceros leves a los sectores costeros del este de la isla temprano en la ma\u00f1ana.<\/p>\n<p>Durante el d\u00eda, uno o dos aguaceros aislados podr\u00edan desarrollarse mayormente sobre partes del oeste interior de Puerto Rico. En el resto del \u00e1rea se espera poca o ninguna lluvia. Se pronostica nuevamente condiciones placenteras y temperaturas frescas de la temporada durante los pr\u00f3ximos d\u00edas.<\/p><div class=\"notic-content-middle\" id=\"notic-357509129\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Una vigilancia de inundaciones costeras est\u00e1 en efecto a lo largo de las costas del norte de Puerto Rico y las Islas V\u00edrgenes Americanas. Una advertencia de resaca fuerte tambi\u00e9n est\u00e1 en efecto. Adem\u00e1s, advertencias para los operadores de embarcaciones peque\u00f1as est\u00e1 en efecto. Oleaje hasta de nueve pies y vientos hasta de 14 nudos se esperan sobre las aguas costeras.<\/p>\n<p>El cielo prevaleci\u00f3 parcialmente nublado a trav\u00e9s de Puerto Rico, Culebra y Vieques durante el transcurso de la noche. Algunos aguaceros pasajeros fueron notados mayormente sobre los sectores del sureste de la isla. Los vientos estuvieron leves y variables.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Servicio Nacional de Meteorolog\u00eda (SNM) espera que cielo parcialmente nublado contin\u00fae hoy con poca actividad de aguaceros. Los vientos podr\u00edan traer algunas nubes con aguaceros leves a los sectores costeros del este de la isla temprano en la ma\u00f1ana. Durante el d\u00eda, uno o dos aguaceros aislados podr\u00edan desarrollarse mayormente sobre partes del oeste [&hellip;]<\/p>","protected":false},"author":0,"featured_media":377215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-29318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=29318"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29318\/revisions"}],"predecessor-version":[{"id":377216,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29318\/revisions\/377216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/377215"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=29318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=29318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=29318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}