{"id":29104,"date":"2014-01-29T00:00:00","date_gmt":"2014-01-29T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140129\/pareja-intenta-suicidarse-luego-de-que-familia-removiera-a-sus-hijas\/"},"modified":"2025-07-15T21:20:02","modified_gmt":"2025-07-15T21:20:02","slug":"pareja-intenta-suicidarse-luego-de-que-familia-removiera-a-sus-hijas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140129\/pareja-intenta-suicidarse-luego-de-que-familia-removiera-a-sus-hijas\/","title":{"rendered":"Pareja intenta suicidarse luego de que Familia removiera a sus hijas"},"content":{"rendered":"<p>Una pareja se encuentra en condici\u00f3n de cuidado recibiendo asistencia medica en el Hospital Dr. Federico Trilla de la UPR en Carolina, luego de ingerir veneno en un intento de suicidio.<\/p>\n<p>La Polic\u00eda indic\u00f3 que la pareja se comunic\u00f3 con un familiar inform\u00e1ndole su intenci\u00f3n de quitarse la vida, quien al llegar a la residencia los encontr\u00f3 inconscientes en el suelo.<\/p>\n<p>Aunque todav\u00eda no se ha establecido motivo, la hermana del hombre indic\u00f3 a las autoridades que la pareja tiene una hija de 12 a\u00f1os, quien fue removida el martes a las 3:00 p.m. a la salida de la escuela a la que asiste.<\/p>\n<p>Asimismo, la hermana sostuvo que la pareja vive en un peque\u00f1o apartamento, aleda\u00f1o a un local que sirve como sal\u00f3n de actividades. Hasta el momento, los detalles provistos por la mujer es que el due\u00f1o del lugar les permite vivir en el apartamento mientras ellos cuidaban del sal\u00f3n, aunque la Polic\u00eda no confirm\u00f3 esta informaci\u00f3n.<\/p>\n<p>Entretanto,NotiCelse comunic\u00f3 con la oficina deprensa delDepartamento de la Familia (DF),quea trav\u00e9s de la portavozLinetteMoreno, confirm\u00f3 que tanto la menor como su hermana de 17 a\u00f1os fueron removidas del hogar luego de que una trabajadora social encontrara fundamentos por un referido de maltrato y negligencia.<\/p><div class=\"notic-content-middle\" id=\"notic-1855162621\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Ambas menores se encuentran en custodia delDFy est\u00e1n protegidas y cuidadas. Al momento, se descart\u00f3 que la intervenci\u00f3n haya tenido en consideraci\u00f3n la calidad o falta de hogar de la pareja.<\/p>\n<p>Hasta que no concluya la investigaci\u00f3n, Familia no estar\u00e1 dando detalles del caso, m\u00e1s all\u00e1 de los ya confirmados.<\/p>\n<p>La pareja est\u00e1 compuesta de un hombre de 36 a\u00f1os y una mujer de 39 a\u00f1os.<\/p>\n<p>El agente Elliot V\u00e9lez investiga el caso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una pareja se encuentra en condici\u00f3n de cuidado recibiendo asistencia medica en el Hospital Dr. Federico Trilla de la UPR en Carolina, luego de ingerir veneno en un intento de suicidio. La Polic\u00eda indic\u00f3 que la pareja se comunic\u00f3 con un familiar inform\u00e1ndole su intenci\u00f3n de quitarse la vida, quien al llegar a la residencia [&hellip;]<\/p>","protected":false},"author":0,"featured_media":378784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-29104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=29104"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29104\/revisions"}],"predecessor-version":[{"id":378787,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/29104\/revisions\/378787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/378784"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=29104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=29104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=29104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}