{"id":28543,"date":"2017-06-04T00:00:00","date_gmt":"2017-06-04T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/vida\/20170604\/lo-que-llevo-a-cien-anos-de-soledad-a-la-fama-mundial\/"},"modified":"2025-07-15T22:16:18","modified_gmt":"2025-07-15T22:16:18","slug":"lo-que-llevo-a-cien-anos-de-soledad-a-la-fama-mundial","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20170604\/lo-que-llevo-a-cien-anos-de-soledad-a-la-fama-mundial\/","title":{"rendered":"Lo que llev\u00f3 a &#8216;Cien a\u00f1os de soledad&#8217; a la fama mundial"},"content":{"rendered":"<p>La publicaci\u00f3n de &#8216;Cien a\u00f1os de soledad&#8217;, hace 50 a\u00f1os, estuvo rodeada de una serie de coyunturas favorables que le permitieron alcanzar el olimpo literario para ser considerado ahora uno de los libros m\u00e1s importantes del siglo XX.<\/p>\n<p>El 5 de junio de 1967 la argentina Editorial Sudamericana public\u00f3 la obra -que se hab\u00eda acabado de imprimir el 30 de mayo- de un autor colombiano residente en M\u00e9xico poco conocido que convertir\u00eda el pueblo ficticio de Macondo en un lugar m\u00e1gico para millones de lectores de la novela.<\/p>\n<p>&#8216;En el momento de su publicaci\u00f3n hubo una coincidencia de factores que allanaron el terreno para el futuro \u00e9xito mundial de esta gran obra&#8217;, explic\u00f3 en una entrevista con Efe \u00c1lvaro Santana, un investigador espa\u00f1ol que lleva ocho a\u00f1os estudiando esta novela y que a finales de a\u00f1o publicar\u00e1 su libro &#8216;Ascenso a la gloria: la transformaci\u00f3n de &#8216;Cien a\u00f1os de soledad&#8217; en un cl\u00e1sico global&#8217;.<\/p>\n<p>El experto, doctorado en Sociolog\u00eda por la Universidad de Harvard e investigador invitado en el Harry Ransom Center de Austin (Texas, EEUU), que alberga el archivo de Garc\u00eda M\u00e1rquez, lleg\u00f3 a la conclusi\u00f3n de que la uni\u00f3n de varios factores en el momento del nacimiento de la obra fueron determinantes para su \u00e9xito inmediato.<\/p>\n<p>En 1967 la industria editorial espa\u00f1ola alcanz\u00f3 su punto m\u00e1s \u00e1lgido de la d\u00e9cada para obras nuevas, despu\u00e9s de que cinco a\u00f1os antes el dictador Francisco Franco suavizara la censura y abriera las puertas a la publicaci\u00f3n de grandes autores hispanoamericanos, como Carlos Fuentes, Mario Vargas Llosa o Jos\u00e9 Donoso.<\/p>\n<p>Adem\u00e1s, a mediados de los sesenta se produjo el colapso de los grandes estilos literarios predominantes del momento, incluyendo el indigenismo latinoamericano, tachado de demasiado localista, el realismo social espa\u00f1ol, visto como predecible y con un lenguaje austero, y la nueva novela francesa, que despert\u00f3 cr\u00edticas por su exc\u00e9ntrica manera de contar historias.<\/p>\n<p>Para el investigador tinerfe\u00f1o, &#8216;Gabo&#8217;, como era popularmente conocido, consigui\u00f3 armar un discurso en &#8216;Cien a\u00f1os de soledad&#8217; que trascend\u00eda esos tres estilos a la vez, lo que permiti\u00f3 que las diferentes audiencias coincidieran en alabar lo novedoso de su obra.<\/p>\n<p>En Am\u00e9rica Latina los lectores la vieron como una novela cosmopolita que se alejaba del localismo indigenista, en Espa\u00f1a se encontraron con un libro que era un volc\u00e1n ling\u00fc\u00edstico y pura fantas\u00eda, lejos del austero lenguaje del realismo social, y los lectores internacionales apreciaron el regreso a la narraci\u00f3n m\u00e1s cl\u00e1sica que supon\u00eda la obra, a diferencia del movimiento franc\u00e9s.<\/p><div class=\"notic-content-middle\" id=\"notic-2050829192\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Por \u00faltimo, el guatemalteco Miguel \u00c1ngel Asturias se convirti\u00f3 en 1967 en el segundo autor latinoamericano en recibir el Premio Nobel de Literatura, despu\u00e9s de Gabriela Mistral (1945).<\/p>\n<p>&#8216;Entonces, lo m\u00e1s vanguardista era la novela hispanoamericana y &#8216;Cien a\u00f1os de soledad&#8217; era el gran superventas en 1967 en Latinoam\u00e9rica&#8217;, explic\u00f3 Santana, que tambi\u00e9n es profesor asistente en el colegio universitario Whitman, en el estado de Washington.<\/p>\n<p>Todos esos factores prepararon el terreno para el veloz \u00e9xito de la obra de Garc\u00eda M\u00e1rquez que, de haberse publicado diez o veinte a\u00f1os antes, &#8216;no hubiera alcanzado semejante \u00e9xito inicial&#8217; de ventas, seg\u00fan consider\u00f3 Santana.<\/p>\n<p>Era la obra de un autor &#8216;muy poco conocido&#8217; fuera de los c\u00edrculos literarios de Argentina, Colombia y M\u00e9xico, que viv\u00eda en un pa\u00eds que no era el suyo, que era colombiano -pa\u00eds que entonces contaba con escasa reputaci\u00f3n literaria internacional- y que narraba una historia muy compleja, repleta de personajes.<\/p>\n<p>La investigaci\u00f3n de Santana tambi\u00e9n se centra en el descubrimiento de siete cap\u00edtulos olvidados del libro, episodios sueltos que Garc\u00eda M\u00e1rquez difundi\u00f3 para sondear al p\u00fablico antes de terminar la novela.<\/p>\n<p>El autor public\u00f3 estos siete cap\u00edtulos, que representan m\u00e1s de un tercio de la novela, en peri\u00f3dicos y revistas que circulaban en m\u00e1s de veinte pa\u00edses para medir la reacci\u00f3n de los lectores, poder perfeccionar el relato, promocionar el libro y disipar sus dudas respecto a la calidad del texto.<\/p>\n<p>Los episodios cayeron en el olvido porque se cre\u00eda que eran id\u00e9nticos a los publicados en la primera edici\u00f3n de 1967, pero no es as\u00ed: desde la primera p\u00e1gina hay cambios en el lenguaje, la estructura, la ambientaci\u00f3n y la descripci\u00f3n de los personajes.<\/p>\n<p>&#8216;De ah\u00ed que estos cap\u00edtulos olvidados sean de un gran valor literario para entender c\u00f3mo fue escrita la novela&#8217;, dijo Santana, que afirm\u00f3 que el perfeccionismo de Garc\u00eda M\u00e1rquez como escritor ha sido lo que m\u00e1s le ha impactado durante sus a\u00f1os de investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La publicaci\u00f3n de &#8216;Cien a\u00f1os de soledad&#8217;, hace 50 a\u00f1os, estuvo rodeada de una serie de coyunturas favorables que le permitieron alcanzar el olimpo literario para ser considerado ahora uno de los libros m\u00e1s importantes del siglo XX. El 5 de junio de 1967 la argentina Editorial Sudamericana public\u00f3 la obra -que se hab\u00eda acabado [&hellip;]<\/p>","protected":false},"author":0,"featured_media":382927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17,69],"tags":[],"class_list":["post-28543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=28543"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28543\/revisions"}],"predecessor-version":[{"id":382929,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28543\/revisions\/382929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/382927"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=28543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=28543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=28543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}