{"id":28276,"date":"2020-03-04T18:00:00","date_gmt":"2020-03-04T22:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/musica\/pop\/20200304\/zion-explica-la-causa-que-lo-llevo-a-ser-hospitalizado-en-mexico\/"},"modified":"2025-07-15T22:48:48","modified_gmt":"2025-07-15T22:48:48","slug":"zion-explica-la-causa-que-lo-llevo-a-ser-hospitalizado-en-mexico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/entretenimiento\/musica\/20200304\/zion-explica-la-causa-que-lo-llevo-a-ser-hospitalizado-en-mexico\/","title":{"rendered":"Zion explica la causa que lo llevo a ser hospitalizado en M\u00e9xico"},"content":{"rendered":"<h3>El artista hab\u00eda sido aislado.<\/h3>\n<p>Un desgaste f\u00edsico severo provoc\u00f3 que el cantante Zion, del d\u00fao urbano Zion y Lenox, fuera recluido de emergencia en M\u00e9xico.<\/p>\n<p>Una foto en la que aparec\u00eda el cantante postrado en una cama de hospital, acompa\u00f1ado de un doctor y una enfermera revolucion\u00f3 las redes sociales durante la ma\u00f1ana del mi\u00e9rcoles, despu\u00e9s de que fuera colgada en la p\u00e1gina oficial de los artistas. En la publicaci\u00f3n se solicitaba una cadena de oraci\u00f3n para su pronta recuperaci\u00f3n, pero no se ofrec\u00edan detalles adicionales.<\/p>\n<p><strong id=\"strong-95a5cd8a346b6fba28da279bed5e3382\">Mira tambi\u00e9n<\/strong>: <a href=\"https:\/\/noticel.com\/en\/pop\/musica\/20200304\/piden-oracion-para-el-cantante-urbano-zion-ante-complicacion-de-salud\/\" id=\"link-769d56f7fcb3f187b23403c33335ad56\">Piden oraci\u00f3n para el cantante urbano Zion ante complicaci\u00f3n de salud<\/a><\/p>\n<p>\u201cPedimos una cadena de oraci\u00f3n por nuestro hermano @zionylennoxpr, que Dios tenga el control y que todo salga bien\u201d, lee la publicaci\u00f3n, que fue colocada en las cuentas de Twitter, Instagram y Facebook del d\u00fao.<\/p>\n<p>Ante la falta de detalles en la imagen, los fan\u00e1ticos comenzaron a preguntar qu\u00e9 le hab\u00eda pasado al artista y de inmediato comenzaron las especulaciones relacionadas a un derrame cerebral y un contagio de coronavirus.<\/p>\n<p>Sin embargo, el artista realiz\u00f3 un video desde M\u00e9xico para aclarar lo que le ocurri\u00f3 y, aunque s\u00ed temi\u00f3 que tuviera coronavirus, asegur\u00f3 que se trat\u00f3 de un caso severo de desgaste que no le permit\u00eda respirar de manera apropiada.<\/p><div class=\"notic-content-middle\" id=\"notic-1321242703\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u201cMe estaba sintiendo mal durante la tarde. Llego al aeropuerto y en el vuelo empec\u00e9 a sentirme mal. No pod\u00eda respirar y se complic\u00f3 la cosa. Llegamos a Ciudad de M\u00e9xico, fuimos a urgencias y cre\u00edan que ven\u00eda con s\u00edntomas de coronavirus y me aislaron. No les miento, me sent\u00ed asustado porque hemos estado viajando mucho en las pasadas semanas, pero me dio un desgaste f\u00edsico y los dolores abdominales eran bien fuertes y no pod\u00eda respirar\u201d, relat\u00f3 desde el balc\u00f3n de lo que parece ser un hotel.<\/p>\n<p>El cantante se\u00f1al\u00f3 que le hicieron pruebas de todo tipo y se le diagnostic\u00f3 el desgaste severo, a ra\u00edz de la gran cantidad de trabajo que ha tenido en los pasados meses.<\/p>\n<p>\u201cGracias al apoyo masivo. Me siento s\u00faper contento por eso. Hay que aprender a valorar lo que somos, lo que hacemos, y m\u00e1s todav\u00eda hay que manejar los enojos y el estr\u00e9s\u2026 Hay Z para largo\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Previo a esta publicaci\u00f3n, apenas tres horas antes, Zion hab\u00eda colgado en su cuenta personal de Instagram un agradecimiento a su p\u00fablico de Costa Rica, en donde acababa de presentarse ante 30 mil personas.<\/p>\n<p>\u201cCosta Ricaaaa Gracias por una noche incre\u00edble, por su energ\u00eda y por cantarlas TODAS, un abrazo!\u201d, escribi\u00f3 el cantante.<\/p>","protected":false},"excerpt":{"rendered":"<p>El artista hab\u00eda sido aislado. Un desgaste f\u00edsico severo provoc\u00f3 que el cantante Zion, del d\u00fao urbano Zion y Lenox, fuera recluido de emergencia en M\u00e9xico. Una foto en la que aparec\u00eda el cantante postrado en una cama de hospital, acompa\u00f1ado de un doctor y una enfermera revolucion\u00f3 las redes sociales durante la ma\u00f1ana del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":385352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-28276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=28276"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28276\/revisions"}],"predecessor-version":[{"id":385356,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/28276\/revisions\/385356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/385352"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=28276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=28276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=28276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}