{"id":27948,"date":"2013-08-10T00:00:00","date_gmt":"2013-08-10T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/en-serio\/mundo\/20130810\/checos-reconocen-legalmente-a-los-pastafaris\/"},"modified":"2025-07-15T23:21:14","modified_gmt":"2025-07-15T23:21:14","slug":"checos-reconocen-legalmente-a-los-pastafaris","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20130810\/checos-reconocen-legalmente-a-los-pastafaris\/","title":{"rendered":"Checos reconocen legalmente a los &#8216;pastafaris&#8217;"},"content":{"rendered":"<p>Praga &#8211; Un joven checo con un colador en la cabeza como s\u00edmbolo religioso &#8216;pastafari&#8217;. Un &#8216;creyente&#8217; de la irreverente iglesia del Monstruoso Espagueti Volador ha logrado incluir semejante foto en su documento de identidad en la Rep\u00fablica Checa.<\/p>\n<p>Este &#8216;culto&#8217;, que ya cuenta con su evangelio, lo invent\u00f3 en 2005 un f\u00edsico de EEUU para parodiar la ense\u00f1anza en las aulas de Kansas de las ideas &#8216;creacionistas&#8217;, que plantean una alternativa b\u00edblica a la teor\u00eda de la evoluci\u00f3n de Charles Darwin.<\/p>\n<p>El inform\u00e1tico Lukas Novy, de 28 a\u00f1os, promotor en la Rep\u00fablica Checa de este credo, cuyos adeptos se hacen llamar &#8216;pastafaris&#8217;, cuenta a Efe que se siente feliz por la popularidad alcanzada y anunci\u00f3 un pulso al Estado para ver reconocido su &#8216;culto&#8217;.<\/p>\n<p>Su documento de identidad provisional ha salido en numerosos medios debido a su particular tocado en forma de colador de pasta, y ahora espera que ese s\u00edmbolo religioso sea reconocido, al igual que lo es el velo isl\u00e1mico o la cruz cristiana colgada en el cuello.<\/p>\n<p>El trasfondo de su actuaci\u00f3n es la protesta contra lo que considera la discriminaci\u00f3n de los laicos frente a los creyentes, y utiliz\u00f3 la prerrogativa dada a estos \u00faltimos para ir tocados por un s\u00edmbolo en un documento para ponerlo de manifiesto.<\/p>\n<p>&#8216;Si la ley dice que s\u00f3lo es posible tener la cabeza cubierta en el documento de identidad por alg\u00fan motivo religioso, yo lo entiendo como una discriminaci\u00f3n&#8217;, sostiene.<\/p>\n<p>Para poder hacer uso del derecho de llevar tambi\u00e9n un tocado en un documento oficial se declar\u00f3 seguidor de la iglesia del Monstruoso Espagueti Volador, y que el colador representaba a ese credo.<\/p>\n<p>Esa deidad es una parodia representada por una monta\u00f1a de espaguetis sobre dos alb\u00f3ndigas y que reina en un para\u00edso lleno de volcanes de cerveza helada.<\/p>\n<p>El programador reconoce que se inspir\u00f3 en el empresario austr\u00edaco Niko Alm, de 37 a\u00f1os, un &#8216;ateo militante&#8217; que logr\u00f3 en 2011 fotografiarse con un colador en el carn\u00e9 de conducir tras argumentar ser tambi\u00e9n seguidor de la misma iglesia.<\/p>\n<p>&#8216;Hace tiempo le\u00ed de Niko en Austria. Hice un apunte mental para el futuro. Y cuando perd\u00ed mi documento de identidad empec\u00e9 este proceso, esta broma, tal como ten\u00eda planeado&#8217;, explica el checo.<\/p>\n<p>Al solicitar en el ayuntamiento de Brno un nuevo documento con un colador de pasta en la cabeza, dej\u00f3 a los funcionarios perplejos, pero le expidieron un documento provisional con validez para 30 d\u00edas.<\/p><div class=\"notic-content-middle\" id=\"notic-1305603790\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Debe verse la cara, aunque en casos de fe religiosa los funcionaros aceptan alg\u00fan atuendo en la cabeza o alg\u00fan otro peque\u00f1o tocado de esa identificaci\u00f3n religiosa&#8217;, explic\u00f3 Sonya Halubova, portavoz del ayuntamiento.<\/p>\n<p>Al tratarse del primer caso y que &#8216;no hay ley o regulaci\u00f3n que lo contemple&#8217;, el consistorio decidi\u00f3 otorgarle la c\u00e9dula provisional, pero pidi\u00f3 el 1 de agosto el dictamen del Ministerio del Interior, &#8216;para que defina qu\u00e9 es una tocado en la cabeza por razones religiosas o de salud&#8217;, precis\u00f3 Halubova.<\/p>\n<p>&#8216;Se puede percibir subjetivamente como una bufonada, pero no est\u00e1 en mi competencia hacer una valoraci\u00f3n semejante&#8217;, se\u00f1al\u00f3 la portavoz, cuyo cabildo sigue a la espera del dictamen de Interior.<\/p>\n<p>Novy da por descontado que tendr\u00e1 que recurrir al Tribunal Superior Administrativo, pero no cejar\u00e1 en su empe\u00f1o.<\/p>\n<p>Considera que su esfuerzo va tambi\u00e9n a facilitar el registro oficial de la iglesia del Monstruoso Espagueti Volador: &#8216;Hemos decidido darle un impulso medi\u00e1tico mayor al tema, para que se pueda registrar m\u00e1s f\u00e1cilmente. S\u00ed, vamos a registrarla&#8217;.<\/p>\n<p>Adem\u00e1s de luchar contra las &#8216;malas leyes&#8217;, reconoci\u00f3 que detr\u00e1s de esta campa\u00f1a hay una estrategia electoral para los pr\u00f3ximos comicios legislativos como candidato del Partido Pirata checo, defensor de la libertad en internet, y del que es el responsable inform\u00e1tico.<\/p>\n<p>&#8216;Me gusta jugar con el Estado. Me gusta atraer la atenci\u00f3n. Soy un pol\u00edtico. Y creo que esta popularidad medi\u00e1tica me va a beneficiar en las elecciones&#8217;, confiesa.<\/p>\n<p>Novy conf\u00eda en mejorar la posici\u00f3n de su Partido Pirata en las pr\u00f3ximas elecciones anticipadas, previstas para octubre, despu\u00e9s de haber obtenido 42.323 papeletas, el 0,80 %, en la \u00faltima convocatoria de 2010.<\/p>\n<p>El joven aclar\u00f3 que no coordina sus pasos con nadie, ni siquiera con la comunidad pastafari evang\u00e9lica de EEUU, quienes confirmaron a Efe que Novy les resulta un desconocido, pero que siguen su caso con inter\u00e9s.<\/p>\n<p>&#8216;S\u00f3lo estoy en contacto con Niko, porque fue el primero en dejarse fotografiar con colador (en la cabeza) para el carn\u00e9 de conducir&#8217;, confirm\u00f3 el inform\u00e1tico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Praga &#8211; Un joven checo con un colador en la cabeza como s\u00edmbolo religioso &#8216;pastafari&#8217;. Un &#8216;creyente&#8217; de la irreverente iglesia del Monstruoso Espagueti Volador ha logrado incluir semejante foto en su documento de identidad en la Rep\u00fablica Checa. Este &#8216;culto&#8217;, que ya cuenta con su evangelio, lo invent\u00f3 en 2005 un f\u00edsico de EEUU [&hellip;]<\/p>","protected":false},"author":0,"featured_media":387615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-27948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=27948"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27948\/revisions"}],"predecessor-version":[{"id":387617,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27948\/revisions\/387617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/387615"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=27948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=27948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=27948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}