{"id":27674,"date":"2017-08-10T00:00:00","date_gmt":"2017-08-10T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/politica\/20170810\/la-palma-se-prepara-para-historica-convencion-documento\/"},"modified":"2025-07-15T23:51:29","modified_gmt":"2025-07-15T23:51:29","slug":"la-palma-se-prepara-para-historica-convencion-documento","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170810\/la-palma-se-prepara-para-historica-convencion-documento\/","title":{"rendered":"La Palma se prepara para hist\u00f3rica convenci\u00f3n (documento)"},"content":{"rendered":"<p>Cincuenta a\u00f1os de lucha por la igualdad es el lema que enmarca la convenci\u00f3n anual del Partido Nuevo Progresista (PNP), que comienza ma\u00f1ana, viernes, 11 de agosto en el hotel Conquistador de Fajardo.<\/p>\n<p>La convenci\u00f3n que dura hasta el domingo, 13 de agosto, incluir\u00e1 una exposici\u00f3n de memorabilia del partido y talleres a cargo de la Delegaci\u00f3n Congresionalde Puerto Rico. Tambi\u00e9n se anticipa la aprobaci\u00f3n del nuevo reglamento de la colectividad durante su Asamblea General.<\/p>\n<p>&#8216;Este ser\u00e1 el reglamento m\u00e1s inclusivo en la historia pol\u00edtica de Puerto Rico, que promover\u00e1 y permitir\u00e1 m\u00e1s participaci\u00f3n en todos los organismos del partido, reconoce con m\u00e1s fuerza la participaci\u00f3n de la mujer a todos los niveles, y crea la Organizaci\u00f3n Estadista de la Comunidad LGBTT, la Organizaci\u00f3n de Base de Fe, y la Organizaci\u00f3n del Equipo Legal Estadista&#8217;, expreso el secretario general, Rafael &#8216;June&#8217; Rivera Ortega, en comunicado de prensa.<\/p>\n<p>El tambi\u00e9n legislador por el Distrito 28 explic\u00f3 que &#8216;ser\u00e1 una convenci\u00f3n bien movida, amena, de mucho trabajo, pero tambi\u00e9n hist\u00f3rica. Tendremos una exposici\u00f3n con memorabilia de los 50 a\u00f1os del Partido Nuevo Progresista, talleres sobre gobernanza, Estadidad, PROMESA, asuntos electorales, entre muchos otros temas, y contaremos con la participaci\u00f3n de nuestros gobernadores Carlos Romero Barcel\u00f3, Pedro Rossell\u00f3, Luis Fortu\u00f1o y Ricardo Rossell\u00f3, as\u00ed como las Primeras Damas, Tiody de Jes\u00fas, Kate Donnelly, Maga Nevares, Luc\u00e9 Vela y Beatriz Rossell\u00f3&#8217;.<\/p>\n<p>Entre los artistas que se dar\u00e1n cita el fn de semana en Fajardo destacan el merenguero Oscarito Serrano, los comediantes Alfonso Alem\u00e1n &#8216;El guitarre\u00f1o&#8217; y Miguel Morales &#8216;Bejuco&#8217;, el grupo Sanc8, la Tribu de Abrante, Michael Stuart y el fil\u00f3sofo del rap Vico C.<\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/09\/14\/b6bd84234678cb382fc81349c635f78e_8553408_ver1.0.pdf\" target=\"_blank\"> Agenda de Convenci\u00f3n PNP _26598<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Cincuenta a\u00f1os de lucha por la igualdad es el lema que enmarca la convenci\u00f3n anual del Partido Nuevo Progresista (PNP), que comienza ma\u00f1ana, viernes, 11 de agosto en el hotel Conquistador de Fajardo. La convenci\u00f3n que dura hasta el domingo, 13 de agosto, incluir\u00e1 una exposici\u00f3n de memorabilia del partido y talleres a cargo de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":389951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-27674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=27674"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27674\/revisions"}],"predecessor-version":[{"id":389953,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/27674\/revisions\/389953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/389951"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=27674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=27674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=27674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}