{"id":26882,"date":"2013-10-08T00:00:00","date_gmt":"2013-10-08T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20131008\/tenis-boricuas-arrasan-en-campeonatos-de-la-usta\/"},"modified":"2025-07-16T01:15:59","modified_gmt":"2025-07-16T01:15:59","slug":"tenis-boricuas-arrasan-en-campeonatos-de-la-usta","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20131008\/tenis-boricuas-arrasan-en-campeonatos-de-la-usta\/","title":{"rendered":"Tenis: Boricuas arrasan en campeonatos de la USTA"},"content":{"rendered":"<p>Dos equipos puertorrique\u00f1os que representan al cap\u00edtulo del Caribe de la United States Tennis Association (USTA) reclamaron t\u00edtulos nacionales en el recien concluido Campeonato de Liga Nacional de la USTA, efectuado en el Jim Reffkin Tennis Center.<\/p>\n<p>Uno de los cetros lo gan\u00f3 un equipo de San Juan en el rengl\u00f3n femenino de Adulto 40 + y Sobre 3.0, y el otro fue un equipo de Ponce que gan\u00f3 el campeonato de la Divisi\u00f3n de Adultos 18+ y Sobre 2.5.<\/p>\n<p>El primer equipo, el femenino, estuvo capitaneado por Norma Rol\u00f3n y Michelle Santiago, y contaba con las jugadoras Michelle Herger, Robyn Reagan, Yaritza Matos, Nilda March\u00e1n, Liza Medina, Michelle Norrevik, Elaine Mora y Giovanna Ram\u00edrez.<\/p>\n<p>Este equipo venci\u00f3 primero a un equipo de USTA Medio Oeste de Ohio, 3-0, y posteriormente, en la final, a una escuadra de la USTA Florida, 3-2. Las boricuas hab\u00edan llegado a este punto del torneo tras ganar los eventos de \u2018round robin&#8217; el viernes y s\u00e1bado.<\/p><div class=\"notic-content-middle\" id=\"notic-3805254883\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Los campeones de Ponce, mientras tanto, vencieron primero a un equipo de Sammamish, Washington en las semifinales y en la final derrotaron a una escuadra de Pelhalm, Alabama, 3-0, en el juego del campeonato.<\/p>\n<p>El equipo del Club Deportivo de la Ciudad Se\u00f1orial estaba capitaneado por Juan Marrero y Johnny Mej\u00edas, y contaba en su escuadra con Wilson V\u00e9lez, Jos\u00e9 Mej\u00edas, Manuel Jos\u00e9 Marrero Torres, Rey Gonz\u00e1lez, \u00c1ngel Llavona Floguera, Wilfredo Gonz\u00e1lez y Raymond Mart\u00ednez.<\/p>\n<p><a href=\"http:\/\/www.caribbean.usta.com\/\">Para m\u00e1s informaci\u00f3n, visite la p\u00e1gina de Caribbean USTA, pulsando aqu\u00ed.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dos equipos puertorrique\u00f1os que representan al cap\u00edtulo del Caribe de la United States Tennis Association (USTA) reclamaron t\u00edtulos nacionales en el recien concluido Campeonato de Liga Nacional de la USTA, efectuado en el Jim Reffkin Tennis Center. Uno de los cetros lo gan\u00f3 un equipo de San Juan en el rengl\u00f3n femenino de Adulto 40 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":396010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-26882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/26882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=26882"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/26882\/revisions"}],"predecessor-version":[{"id":396012,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/26882\/revisions\/396012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/396010"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=26882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=26882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=26882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}