{"id":25192,"date":"2015-01-16T00:00:00","date_gmt":"2015-01-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20150116\/se-muda-el-tribunal-de-apelaciones\/"},"modified":"2025-07-16T04:16:19","modified_gmt":"2025-07-16T04:16:19","slug":"se-muda-el-tribunal-de-apelaciones","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20150116\/se-muda-el-tribunal-de-apelaciones\/","title":{"rendered":"Se muda el Tribunal de Apelaciones"},"content":{"rendered":"<p>La Oficina de Administraci\u00f3n de Tribunales (OAT) as\u00ed como el Tribunal de Apelaciones se apretaron el cintur\u00f3n para ahorrar unos $10 millones al a\u00f1o, luego de decidir que mudar\u00e1n su sede a un edificio de la Autoridad para el Financiamiento de Infraestructura (AFI).<\/p>\n<p>Desde diciembre, la Rama Judicial hace ajustes para reducir su presupuesto. Por ello, la OAT intent\u00f3 resolver en el foro judicial una controversia con el arrendador que le alberga, por una supuesta deuda, a la vez que persegu\u00eda rebajar la cuant\u00eda del alquiler. La OAT paga casi medio mill\u00f3n de d\u00f3lares al mes por el edificio que ocupa el Tribunal de Apelaciones en Hato Rey. Esa edificaci\u00f3n, cuya empresa propietaria es Cecort Realty Development Inc., paga $422,603 mensuales, cifra que suma a $5,071,236 al a\u00f1o.<\/p>\n<p>La empresa arrendadora hab\u00eda solicitado que la dependencia de gobierno pagara $51,406,676 por una orden de cambio que la OAT aprob\u00f3 en el contrato y que, seg\u00fan se alega, ese ente no pag\u00f3. Tambi\u00e9n pidieron un aumento de 15 por ciento en el pago mensual del alquiler tras vencerse el contrato de diez a\u00f1os establecido en el 2003.<\/p><div class=\"notic-content-middle\" id=\"notic-2210322569\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El 31 de mayo de 2015 se vence el contrato de arrendamiento de ambos edificios. Las conversaciones con Cecort Realty Development Inc. para atemperar el precio del arrendamiento con la situaci\u00f3n fiscal no dieron frutos, por lo que procedieron a identificar el edificio de la AFI. El jueves en la tarde, la directora de la OAT, Isabel Llompart Zeno, suscribi\u00f3 el contrato con la Autoridad, seg\u00fan confirm\u00f3 NotiCel a trav\u00e9s de fuentes oficiales.<\/p>\n<p>Vea tambi\u00e9n<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/noticia\/170067\/oat-busca-pagar-menos-por-tribunal-de-apelaciones.html\/\" target=\"_blank\">OAT busca pagar menos por Tribunal de Apelaciones<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Oficina de Administraci\u00f3n de Tribunales (OAT) as\u00ed como el Tribunal de Apelaciones se apretaron el cintur\u00f3n para ahorrar unos $10 millones al a\u00f1o, luego de decidir que mudar\u00e1n su sede a un edificio de la Autoridad para el Financiamiento de Infraestructura (AFI). Desde diciembre, la Rama Judicial hace ajustes para reducir su presupuesto. Por [&hellip;]<\/p>","protected":false},"author":0,"featured_media":408348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/25192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=25192"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/25192\/revisions"}],"predecessor-version":[{"id":408350,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/25192\/revisions\/408350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/408348"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=25192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=25192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=25192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}