{"id":24334,"date":"2015-05-26T00:00:00","date_gmt":"2015-05-26T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20150526\/empresario-de-estacionamientos-vinculado-con-fraude-bancario\/"},"modified":"2025-07-16T06:03:44","modified_gmt":"2025-07-16T06:03:44","slug":"empresario-de-estacionamientos-vinculado-con-fraude-bancario","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20150526\/empresario-de-estacionamientos-vinculado-con-fraude-bancario\/","title":{"rendered":"Empresario de estacionamientos vinculado con fraude bancario"},"content":{"rendered":"<p>El empresario Rolando Cabral Veras, miembro de una familia vinculada en el pasado con esquemas de favores gubernamentales y donativos pol\u00edticos en Puerto Rico, ha sido imputado de fraude bancario y lavado de dinero en su natal Rep\u00fablica Dominicana.<\/p>\n<p>La imputaci\u00f3n contra Cabral Veras, otros 13 dominicanos y tres ciudadanos venezolanos por el fraude de unos $31 millones ($1,400 millones de pesos dominicanos) a trav\u00e9s del Banco Peravia ha dominado la atenci\u00f3n de la opini\u00f3n p\u00fablica quisqueyana en los \u00faltimos d\u00edas, seg\u00fan se constata en rese\u00f1as de medios como el Diario Libre.<\/p>\n<p>La denuncia civil fue hecha el lunes 18 de mayo por el Banco Central y la Superintendencia de Bancos de la Rep\u00fablica Dominicana e incluye falsificaci\u00f3n de documentos p\u00fablicos y privados, asociaci\u00f3n de malhechores, abuso de confianza, estafa, y lavado de dinero. Seg\u00fan Diario Libre, la investigaci\u00f3n detect\u00f3 tambi\u00e9n &#8216;operaciones fraudulentas en cuentas contables y tentativa de capitalizaci\u00f3n fraudulenta, fraude en m\u00e1s de un 95% de las tarjetas de cr\u00e9dito&#8217;.<\/p>\n<p>Asimismo, se les imputa la comisi\u00f3n de fraudes en operaciones en efectivo, manejo fraudulento de captaciones de dep\u00f3sitos, robo de identidad, entre otras manifestaciones propias del crimen organizado.<\/p><div class=\"notic-content-middle\" id=\"notic-1019391242\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>En Puerto Rico, Cabral Veras maneja junto a su hermano, Miguel, la compa\u00f1\u00eda American Parking Systems y la desarrolladora Casta Developers, entre otras. Por lo menos hasta 2012, fue presidente de la Confederaci\u00f3n H\u00edpica de Puerto Rico y est\u00e1 asociado con negocios de veh\u00edculos de motor en Florida.<\/p>\n<p>Rolando, Miguel, Ram\u00f3n, y Julio Cabral Veras, todos hermanos, cobraron notoriedad en Puerto Rico por manejos de negocios con el Gobierno que han sido cuestionados o han sido objetos de procesos judiciales. Ram\u00f3n estuvo pr\u00f3fugo por un fraude en la Autoridad de los Puertos, a Julio se le han cuestionado negocios con el Departamento de Educaci\u00f3n a trav\u00e9s de Editorial Panamericana y alquiler de locales a agencias p\u00fablicas, <a href=\"https:\/\/noticel.com\/en\/noticia\/119812\/de-castro-font-carlos-diaz-es-parte-de-mi-equipo.html\/\">Miguel fue cuestionado por fiscales como parte del caso de corrupci\u00f3n del exsenador Jorge de Castro Font<\/a>, a quien \u00e9l y Rolando le daban donativos pol\u00edticos, y Rolando tambi\u00e9n aparece como donante del senador dem\u00f3crata Bob Men\u00e9ndez, recientemente acusado a nivel federal por corrupci\u00f3n.<\/p>\n<p>En los registros de la Oficina de la Contralora, American Parking System aparece con un contrato vigente con la Compa\u00f1\u00eda de Parques Nacionales por $792,000 hasta el 2016.<\/p>\n<p>Los venezolanos involucrados en el caso del Banco Peravia son Jos\u00e9 Luis Santoro, Gabriel Jim\u00e9nez Aray y Daniel Morales Santoro, mientras que los dominicanos, adem\u00e1s de Cabral Veras, son: Nelson Serret Sugra\u00f1ez, Carlos Alberto Serret Sugra\u00f1ez, Jorge Serret Sugra\u00f1ez, Luis Manuel Pe\u00f1a, Nelson Cabral Veras (hermano de Rolando), Yesenia Serret, Jocelyn Leal, la contadora p\u00fablica autorizada G\u00e9nova Isabel Torres, y el notario p\u00fablico Mois\u00e9s Barinas Villalona.<\/p>","protected":false},"excerpt":{"rendered":"<p>El empresario Rolando Cabral Veras, miembro de una familia vinculada en el pasado con esquemas de favores gubernamentales y donativos pol\u00edticos en Puerto Rico, ha sido imputado de fraude bancario y lavado de dinero en su natal Rep\u00fablica Dominicana. La imputaci\u00f3n contra Cabral Veras, otros 13 dominicanos y tres ciudadanos venezolanos por el fraude de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":415006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/24334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=24334"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/24334\/revisions"}],"predecessor-version":[{"id":415009,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/24334\/revisions\/415009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/415006"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=24334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=24334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=24334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}