{"id":23339,"date":"2014-09-14T00:00:00","date_gmt":"2014-09-14T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20140914\/el-grupo-chino-alibaba-sale-a-bolsa-en-wall-street-con-una-oferta-historica\/"},"modified":"2025-07-16T08:04:03","modified_gmt":"2025-07-16T08:04:03","slug":"el-grupo-chino-alibaba-sale-a-bolsa-en-wall-street-con-una-oferta-historica","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20140914\/el-grupo-chino-alibaba-sale-a-bolsa-en-wall-street-con-una-oferta-historica\/","title":{"rendered":"El grupo chino Alibaba sale a bolsa en Wall Street con una oferta hist\u00f3rica"},"content":{"rendered":"<p>Nueva York &#8211; Wall Street vivir\u00e1 el pr\u00f3ximo viernes una jornada hist\u00f3rica con la salida a bolsa del grupo chino de comercio electr\u00f3nico Alibaba, la mayor hasta ahora y que dejar\u00e1 una marca indeleble en los mercados financieros de Nueva York.<\/p>\n<p>La ambiciosa oferta p\u00fablica inicial del grupo de comercio electr\u00f3nico busca captar entre $21,000 y $24,000 millones entre potenciales compradores de los 320 millones de acciones que ofrecer\u00e1 al mercado como American Depositary Shares (ADS).<\/p>\n<p>Esa suma toma en cuenta el promedio del precio que fue fijado el pasado 5 de septiembre, entre los $60 y los $66, un rango que, sin embargo, puede que se revise a \u00faltima hora, teniendo en cuenta que las reservas de compra se cerrar\u00e1n antes de lo previsto.<\/p>\n<p>&#8216;Todas las se\u00f1ales indican que los inversores est\u00e1n hambrientos por esta oferta p\u00fablica inicial&#8217;, afirm\u00f3 esta semana Carson Block, fundador de la firma financiera Muddy Waters.<\/p>\n<p>No s\u00f3lo es una cantidad sin precedentes, sino que se trata de una compa\u00f1\u00eda extranjera, con un negocio enfocado fundamentalmente en China y con un equipo de direcci\u00f3n que no esconde los lazos con el Gobierno de Pek\u00edn.<\/p>\n<p>En un mercado tan receloso de cualquier se\u00f1al, esos lazos no dejan de ser preocupantes para algunos analistas.<\/p>\n<p>&#8216;En una situaci\u00f3n en la que la capacidad para usar los lazos del gobierno puede ayudar a una compa\u00f1\u00eda, el \u00e9xito puede estar en peligro por el hecho de que un nuevo competidor tenga lazos mejores&#8217;, sostiene el directivo de la firma DRD Donald Didon.<\/p>\n<p>Alibaba tiene el 80 por ciento del mercado electr\u00f3nico en China, con una fuerte expansi\u00f3n impulsada por su fundador, Jack Ma, que ha creado un imperio surgido hace dos d\u00e9cadas aprovechando los primeros pasos de China por liberalizar su econom\u00eda.<\/p>\n<p>Ma y otros directivos de la compa\u00f1\u00eda comenzaron el pasado lunes un &#8216;roadshow&#8217; (gira) por Estados Unidos para convencer a los potenciales inversores, que comenz\u00f3 con una exposici\u00f3n a puerta cerrada en el famoso Waldorf Astoria de Nueva York.<\/p>\n<p>Los \u00faltimos informes indican que los agentes colocadores comenzar\u00e1n a cerrar las \u00f3rdenes de compra el pr\u00f3ximo martes, antes de lo previsto, teniendo en cuenta que la demanda a los niveles actuales del precio es suficiente.<\/p><div class=\"notic-content-middle\" id=\"notic-3388637338\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Eso abre la posibilidad de que, como ha ocurrido en otras ocasiones con las ofertas p\u00fablicas iniciales, pueda haber otra ronda a un precio por encima del rango fijado el 5 de septiembre, que se cree puede estar en torno a los $70.<\/p>\n<p>Aunque las firmas que llevan esta oferta no lo han confirmado, todo parece indicar que el precio final de salida ser\u00e1 anunciado el jueves pr\u00f3ximo, y que las acciones de Alibaba, con el s\u00edmbolo de BABA, saldr\u00e1n al parqu\u00e9 neoyorquino el viernes.<\/p>\n<p>Los an\u00e1lisis financieros indican que la compa\u00f1\u00eda china comenzar\u00e1 su vida burs\u00e1til con un precio que ser\u00e1 24 veces los ingresos calculados para el a\u00f1o que viene.<\/p>\n<p>Las tablas publicadas por The Wall Street Journal comparan esa relaci\u00f3n con la de Facebook (35 veces) y Amazon (71 veces), las salidas a bolsa en el sector tecnol\u00f3gico m\u00e1s renombradas en los \u00faltimos a\u00f1os.<\/p>\n<p>Esa relaci\u00f3n es clave para saber c\u00f3mo valora Alibaba su propia compa\u00f1\u00eda y tambi\u00e9n para saber si los inversores que compren sus acciones tendr\u00e1n una ganancia si se quieren desprender de ellas a corto o medio plazo.<\/p>\n<p>Seg\u00fan se acercan las fechas, Alibaba sigue con su &#8216;roadshow&#8217;.<\/p>\n<p>Completada la etapa en Estados Unidos (Nueva York y Boston), contin\u00faan en Asia y Europa, con la idea de cerrar el proceso en la misma ciudad donde comenz\u00f3.<\/p>\n<p>Aunque Alibaba tiene a la firma Yahoo como uno de los principales socios, no se conocen muchos planes sobre c\u00f3mo se desarrollar\u00e1 en Estados Unidos a partir de su salida a bolsa en Nueva York.<\/p>\n<p>&#8216;Ese es el tema clave, y es algo que no queda claro cuando present\u00f3 los documentos&#8217; ante el regulador burs\u00e1til estadounidense, sostiene el estratega de la firma MorningStar R. J. Hottoby.<\/p>\n<p>&#8216;Tienen una fuerte presencia y cuentan con fuertes ventajas competitivas en el mercado de China, pero si van a irrumpir en otras regiones eso es algo que todav\u00eda est\u00e1 por verse&#8217;, agreg\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nueva York &#8211; Wall Street vivir\u00e1 el pr\u00f3ximo viernes una jornada hist\u00f3rica con la salida a bolsa del grupo chino de comercio electr\u00f3nico Alibaba, la mayor hasta ahora y que dejar\u00e1 una marca indeleble en los mercados financieros de Nueva York. La ambiciosa oferta p\u00fablica inicial del grupo de comercio electr\u00f3nico busca captar entre $21,000 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":422573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-23339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=23339"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23339\/revisions"}],"predecessor-version":[{"id":422574,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23339\/revisions\/422574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/422573"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=23339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=23339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=23339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}