{"id":23337,"date":"2018-03-16T00:00:00","date_gmt":"2018-03-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/top-stories\/20180316\/puente-que-colapso-en-miami-fue-construido-en-6-horas\/"},"modified":"2025-07-16T08:04:12","modified_gmt":"2025-07-16T08:04:12","slug":"puente-que-colapso-en-miami-fue-construido-en-6-horas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20180316\/puente-que-colapso-en-miami-fue-construido-en-6-horas\/","title":{"rendered":"Puente que colaps\u00f3 en Miami fue construido en 6 horas"},"content":{"rendered":"<p><i>Utilizando el proceso Accelerated Bridge&#8230;<\/i><\/p>\n<p>Un puente peatonal que <a href=\"http:\/\/Coalici\u00f3n reclama participaci\u00f3n de cooperativas. http:\/\/www.noticel.com\/ahora\/gobierno\/piden-al-gobierno-que-lo-coja-suave-con-privatizacin-de-aee\/716923302\" target=\"_blank\">colaps\u00f3 en la Universidad Internacional de Florida<\/a> (FIU por sus siglas en ingles) en Miami hoy fue construido utilizando una tecnolog\u00eda conocida como &#8216;Accelerated Bridge Construction&#8217; (ABC).<\/p>\n<p>De acuerdo a un reportaje de Reuters, esta estructura fue construida en solo 6 horas.<\/p>\n<p>Seg\u00fan un comunicado emitido por la instituci\u00f3n, este metodo acelera el proceso de construcci\u00f3n haciendolo m\u00e1s costo efectivo para los constructores.<\/p>\n<p>El uso de ABC deja construir puentes entre 48 a 72 horas, seg\u00fan la Administraci\u00f3n Federal de Autopistas (FHA por sus siglas en ingles).<\/p>\n<p>Adem\u00e1s de ser m\u00e1s costo efectivo, el tiempo acelerado reduce retrasos en el tr\u00e1fico y cierres de carreteras que irritan a los transe\u00fantes.<\/p>\n<p>Entre otros beneficios tambien se mencionan zonas de trabajos m\u00e1s seguras, menos impacto ambiental, reducci\u00f3n en riesgos por retrasos debido al clima, y puentes que son generalmente m\u00e1s duraderos que aquellos construidos utilizando metodos convencionales, seg\u00fan la FHA.<\/p>\n<p>&#8216;Esta innovaci\u00f3n llega cuando aproximadamente un 25% de los puentes en nuestra naci\u00f3n requieren reparaciones o reemplazos, y nuestras autopistas est\u00e1n ya congestionadas sin el peso adicional de cierres de carreteras&#8217;, inform\u00f3 la agencia federal.<\/p><div class=\"notic-content-middle\" id=\"notic-1609344640\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Hay diversos tiposde tecnolog\u00edas ABC, incluyendo elementos y sistemas de puentes prefabricados (PBES por sus siglas en ingles), el cual permite a las compa\u00f1\u00edas constructoras a prefabricar elementos fuera del \u00e1rea de construcci\u00f3n y transportarlos a la localizaci\u00f3n, donde son ensamblados r\u00e1pidamente.<\/p>\n<p>La mencionada tecnica fue la utilizada para el puente peatonal en FIU.<\/p>\n<p>El presidente del departamento de Ingenier\u00eda Civil y Ambiental de la Universidad, Atorod Azizinamini, celebr\u00f3 la conclusi\u00f3n del puente el pasado 10 de marzo, enfocando el metodo de construcci\u00f3n.<\/p>\n<p>&#8216;Este proyecto es un ejemplo perfecto del metodo ABC&#8217;, dijo en ese entonces Azizinamini.<\/p>\n<p>El puente pesaba unas 950 toneladas y conectaba el campus escolar con el vecindario de Sweetwater, hogar para muchos estudiantes de FIU.<\/p>\n<p>El costo de construcci\u00f3n fue de $14.2 millones y fue costeado por una ayuda del Departamento de Transportaci\u00f3n de Estados Unidos de $19.4. Seg\u00fan un documento, estaba dise\u00f1ado para aguantar un hurac\u00e1n categor\u00eda 5 y durar\u00eda m\u00e1s de 100 a\u00f1os.<\/p>\n<p>Fue dise\u00f1ado por ingenieros de FIGG Bridge Engineers en Tallahassee y construido por MCM en Miami.<\/p>\n<p>Vea c\u00f3mo se construy\u00f3 el puente aqu\u00ed:<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"716903324\" embed-content-groupid=\"593030471\" embed-content-id=\"716903871\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"subStoryType\" height=\"240px\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2018\/03\/15\/Pedestrian%20bridge%20collapse_1521145153136.jpg.jpg.jpg_10702910_ver1.0_160_90.jpg\" style=\"width:100%;\" width=\"360px\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>Utilizando el proceso Accelerated Bridge&#8230; Un puente peatonal que colaps\u00f3 en la Universidad Internacional de Florida (FIU por sus siglas en ingles) en Miami hoy fue construido utilizando una tecnolog\u00eda conocida como &#8216;Accelerated Bridge Construction&#8217; (ABC). De acuerdo a un reportaje de Reuters, esta estructura fue construida en solo 6 horas. Seg\u00fan un comunicado emitido [&hellip;]<\/p>","protected":false},"author":0,"featured_media":422581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-23337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=23337"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23337\/revisions"}],"predecessor-version":[{"id":422583,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23337\/revisions\/422583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/422581"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=23337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=23337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=23337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}