{"id":23205,"date":"2018-05-06T00:00:00","date_gmt":"2018-05-06T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/english\/inteligencia-social\/opiniones\/politica\/top-stories\/video\/20180506\/que-destapo-el-lio-del-chat-pnp\/"},"modified":"2025-07-16T08:17:32","modified_gmt":"2025-07-16T08:17:32","slug":"que-destapo-el-lio-del-chat-pnp","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20180506\/que-destapo-el-lio-del-chat-pnp\/","title":{"rendered":"\u00bfQu\u00e9 destap\u00f3 el l\u00edo del chat PNP?"},"content":{"rendered":"<p><i>El profesor Jorge Schmidt Nieto explica.<\/i><\/p>\n<p>El profesor en Ciencias Pol\u00edticas de la Universidad de Puerto Rico Recinto Universitario de Mayag\u00fcez (UPR-RUM), Jorge Schmidt Nieto, explica las implicaciones del esc\u00e1ndalo del chat PNP que oblig\u00f3 la renuncia de su posici\u00f3n de juez al expresidente de la Comisi\u00f3n Estatal de Elecciones (CEE), Rafael Ramos S\u00e1enz.\u00bbTodo el proceso de&#8230;<\/p>\n<p><iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 destap\u00f3 el l\u00edo del chat PNP?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/FM8zH794gko?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>El profesor Jorge Schmidt Nieto explica. El profesor en Ciencias Pol\u00edticas de la Universidad de Puerto Rico Recinto Universitario de Mayag\u00fcez (UPR-RUM), Jorge Schmidt Nieto, explica las implicaciones del esc\u00e1ndalo del chat PNP que oblig\u00f3 la renuncia de su posici\u00f3n de juez al expresidente de la Comisi\u00f3n Estatal de Elecciones (CEE), Rafael Ramos S\u00e1enz.\u00bbTodo el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":423567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[48,7,2,61],"tags":[],"class_list":["post-23205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones","category-politica","category-ultima-hora","category-video"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=23205"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23205\/revisions"}],"predecessor-version":[{"id":423570,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/23205\/revisions\/423570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/423567"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=23205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=23205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=23205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}