{"id":22599,"date":"2020-03-03T21:18:00","date_gmt":"2020-03-04T01:18:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20200303\/escoltas-de-wanda-vazquez-sufren-accidente-de-transito\/"},"modified":"2025-07-16T09:27:37","modified_gmt":"2025-07-16T09:27:37","slug":"escoltas-de-wanda-vazquez-sufren-accidente-de-transito","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20200303\/escoltas-de-wanda-vazquez-sufren-accidente-de-transito\/","title":{"rendered":"Escoltas de Wanda V\u00e1zquez sufren accidente de tr\u00e1nsito"},"content":{"rendered":"<p>Un accidente de tr\u00e1nsito donde estuvieron involucrados una motora y un veh\u00edculo oficial, ambos pertenecientes a la flota de la escolta de la gobernadora de Puerto Rico, Wanda V\u00e1zquez Garced, se report\u00f3 a las 6:00 de la tarde en el Expreso Mu\u00f1oz Rivera kil\u00f3metro 78 en San Juan.<\/p>\n<p>Seg\u00fan la informaci\u00f3n suministrada, el agente que result\u00f3 lesionado en el accidente es Jos\u00e9 Rafael Rodr\u00edguez Collazo, manejaba una motora oficial, cuando impact\u00f3 con la misma una guagua Chevrolet Suburbian color negra, conducida por el agente Edgardo Sevilla Robles. De acuerdo a la investigaci\u00f3n preliminar, la motora choc\u00f3 con el lado derecho a la parte frontal lateral de la guagua mientras transitaban por el carril exclusivo de la AMA y luego que le dieran paso a un peat\u00f3n que cruzaba en el lugar.<\/p><div class=\"notic-content-middle\" id=\"notic-2256858978\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El agente Rodr\u00edguez Collazo recibi\u00f3 traumas en la clav\u00edcula siendo transportado a la Sala de Emergencias del Centro M\u00e9dico de R\u00edo Piedras donde es atendido siendo su condici\u00f3n estable.<\/p>\n<p>La sargento Mary Castillo Morales, de la Divisi\u00f3n de Patrullas de Carreteras de San Juan, investiga.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un accidente de tr\u00e1nsito donde estuvieron involucrados una motora y un veh\u00edculo oficial, ambos pertenecientes a la flota de la escolta de la gobernadora de Puerto Rico, Wanda V\u00e1zquez Garced, se report\u00f3 a las 6:00 de la tarde en el Expreso Mu\u00f1oz Rivera kil\u00f3metro 78 en San Juan. Seg\u00fan la informaci\u00f3n suministrada, el agente que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":428451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-22599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/22599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=22599"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/22599\/revisions"}],"predecessor-version":[{"id":428453,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/22599\/revisions\/428453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/428451"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=22599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=22599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=22599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}