{"id":214324,"date":"2025-02-18T12:59:41","date_gmt":"2025-02-18T16:59:41","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/20250218\/arturo-garffer-no-vislumbra-escollos-en-su-confirmacion\/"},"modified":"2025-07-11T05:43:36","modified_gmt":"2025-07-11T05:43:36","slug":"arturo-garffer-no-vislumbra-escollos-en-su-confirmacion","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20250218\/arturo-garffer-no-vislumbra-escollos-en-su-confirmacion\/","title":{"rendered":"Arturo Garffer no vislumbra escollos en su confirmaci\u00f3n"},"content":{"rendered":"<h3>El designado  secretario del Departamento de Seguridad P\u00fablica (DSP), estar\u00e1 instalado en Puerto Rico a partir de abril.<\/h3>\n<p>El designado secretario al Departamento de Seguridad P\u00fablica (DSP), Arturo Garffer, asegur\u00f3 hoy, martes, que su supervisi\u00f3n y desempe\u00f1o no se ha afectado a pesar de que todav\u00eda labora como jefe de staff del estado mayor de las fuerzas de la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte (OTAN) en Kosovo.<\/p>\n<p>As\u00ed lo dej\u00f3 Garffer saber durante la vista de confirmaci\u00f3n en el Senado.<\/p>\n<p>A pesar de su trayectoria en la milicia, Garffer ha sido objeto de cr\u00edticas por parte de varios senadores y gremios del DSP al entender que est\u00e1 descuidando las responsabilidades en Puerto Rico.<\/p>\n<p>Sin embargo, asegur\u00f3 que trabaja desde el primer d\u00eda con las responsabilidades ejecutando cambios dentro la agencia a la vez que mantiene comunicaci\u00f3n por medio de la tecnolog\u00eda.<\/p>\n<p>\u201cBueno, con la tecnolog\u00eda existente, no me he ido. O sea, llevo trabajando 22 horas al d\u00eda. La milicia nos ense\u00f1a a ser multifac\u00e9ticos y especialmente al nivel en que estoy. Estoy trabajando de lejos y aqu\u00ed, como pueden ver, estoy en Puerto Rico. Estar\u00e9 dos semanas trabajando temas en persona. Me regresar\u00e9 de nuevo a donde estoy destacado (Kosovo), pero volver\u00e9 en marzo de nuevo por dos semanas m\u00e1s y ya cuando regrese en abril, ya es de lleno y aqu\u00ed presencialmente\u201d, expres\u00f3 en un aparte con la prensa.<\/p>\n<p>Garffer descart\u00f3 la idea de que su destaque en Kosovo sea desfavorable para su confirmaci\u00f3n en el Senado.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/policiacas\/la-calle\/ahora\/20250106\/justicia-de-la-calle-se-encargo-del-sospechoso-de-brutal-paliza-a-nonagenario-de-sabana-grande\/\" id=\"link-2a55110ea8119317cf998f0fe0c10de3\" target=\"_blank\">Justicia de la calle se encarg\u00f3 del sospechoso de brutal paliza a nonagenario de Sabana Grande<\/a><\/p>\n<p>\u201cEntiendo que no. Se me va a evaluar por mis credenciales, mis criterios, mi trabajo, 31 a\u00f1os en el Ej\u00e9rcito y el sector privado y dentro del andamiaje de seguridad, tanto p\u00fablica como internacional y otras agencias federales. En eso es en lo que me van a evaluar\u201d, sostuvo.<\/p>\n<p>El Sindicato del Cuerpo de Bomberos le solicit\u00f3 a la gobernadora Jenniffer Gonz\u00e1lez que retire el nombramiento de Garffer tras no estar completamente disponible para el cargo.<\/p>\n<p>\u201cMe gustar\u00eda obviamente en alg\u00fan momento sentarme con Jos\u00e9 Tirado (presidente del sindicato). \u00c9l tiene que entender que la tecnolog\u00eda modernizada, que ya no estamos con pajaritos llevando papeles en las patitas y que s\u00ed podemos comunicarnos por otros medios, mi gente en el DSP se ha comunicado y se ha sentado con \u00e9l a discutir diferentes temas de importancia para los bomberos\u201d, contest\u00f3 a preguntas de <strong id=\"strong-25c9df23029b92427c34413e8e5adb14\">NotiCel<\/strong>.<\/p>\n<p>\u201cEstoy todos los d\u00edas hablando con el comisionado (Josu\u00e9 Iv\u00e1n) Pi\u00f1ero sobre varios temas, entre ellos c\u00f3mo podemos mejorar no solamente el retiro de los primeros respondedores y los bomberos, sino tambi\u00e9n c\u00f3mo podemos mejorar el d\u00eda a d\u00eda de los bomberos en Puerto Rico\u201d, agreg\u00f3.<\/p>\n<p>Entre sus prioridades, seg\u00fan le contest\u00f3 a este medio digital, est\u00e1 llevar al DSP a una administraci\u00f3n privada y que cumplan cabalmente con todas las m\u00e9tricas establecidas.<\/p>\n<p>\u201cLo que estoy buscando es llevar al DSP a m\u00e1s o menos una instituci\u00f3n privada, militar y nuestros clientes son los Comisionados y sus Negociados\u201d, sostuvo.<\/p>\n<p>En cu\u00e1nto a la documentaci\u00f3n sometida en el Senado, Garffer expres\u00f3 que solo le falta el informe financiero y que entend\u00eda que ya durante la tarde de hoy, su contable le estar\u00eda entregando el informe.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/20250130\/renuncia-secretario-de-seguridad-publica-alexis-torres\/\" id=\"link-8559933f2a99a078d1f0bdd3465d6b3f\" target=\"_blank\">Renuncia secretario de Seguridad P\u00fablica, Alexis Torres<\/a><\/p>\n<p>\u201cTengo toda la documentaci\u00f3n, lo que me falta es el estado financiero, que me lo completan esta tarde. Todas mis instituciones financieras, bancarias, no est\u00e1n en Puerto Rico, entonces para yo poder consolidar toda esa documentaci\u00f3n me tom\u00f3 tiempo, pero ya mi CPA tiene esa informaci\u00f3n y entiendo que esta tarde me lo dar\u00e1n\u201d, indic\u00f3.<\/p>\n<p>Garffer puntualiz\u00f3 que estar\u00e1 entregando el informe esta semana y que tan pronto lo citen en el Senado ya sea en marzo o abril estar\u00e1  \u201cdispuesto a sentarme\u201d.<\/p>\n<p>Historia relacionada:<a href=\"https:\/\/ntc.us.dashboard.navigacloud.com\" id=\"link-6ade7aa2384d11d1e2efc8768df2d2d0\" target=\"_blank\"> Millonaria asignaci\u00f3n para agencias integradas al sistema de emergencias<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El designado secretario del Departamento de Seguridad P\u00fablica (DSP), estar\u00e1 instalado en Puerto Rico a partir de abril. El designado secretario al Departamento de Seguridad P\u00fablica (DSP), Arturo Garffer, asegur\u00f3 hoy, martes, que su supervisi\u00f3n y desempe\u00f1o no se ha afectado a pesar de que todav\u00eda labora como jefe de staff del estado mayor de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":215232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-214324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=214324"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214324\/revisions"}],"predecessor-version":[{"id":215233,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214324\/revisions\/215233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/215232"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=214324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=214324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=214324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}