{"id":214293,"date":"2025-02-17T12:54:45","date_gmt":"2025-02-17T16:54:45","guid":{"rendered":"https:\/\/www.noticel.com\/pop\/top-stories\/20250217\/fallece-la-cantante-mexicana-paquita-la-del-barrio\/"},"modified":"2025-07-11T05:45:28","modified_gmt":"2025-07-11T05:45:28","slug":"fallece-la-cantante-mexicana-paquita-la-del-barrio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20250217\/fallece-la-cantante-mexicana-paquita-la-del-barrio\/","title":{"rendered":"Fallece la cantante mexicana Paquita la del Barrio"},"content":{"rendered":"<h3>La cantante reconocida por sus temas \u00abRata de dos patas\u00bb y \u00abLa culebra\u00bb, muri\u00f3 hoy a la edad de 77 a\u00f1os.<\/h3>\n<p>CIUDAD DE MEXICO \u2014 La cantante mexicana Paquita la del Barrio, conocida por su canci\u00f3n &#8216;Rata de dos patas&#8217; falleci\u00f3 este lunes a sus 77 a\u00f1os de edad, seg\u00fan un comunicado oficial en las redes de la familia de la artista.<\/p>\n<p>\u00abCon profundo dolor y tristeza, confirmamos el fallecimiento de nuestra querida Paquita la del Barrio, en su hogar en Veracruz, siendo una artista \u00fanica e irrepetible que nos dejar\u00e1 una huella imborrable en el coraz\u00f3n de todos los que la conocimos y disfrutamos de su m\u00fasica\u00bb, estableci\u00f3 el texto de su familia.<\/p>\n<p>La familia no detall\u00f3 las causas del deceso de la artista, nacida el 2 de abril de 1947 en el oriental estado de Veracruz y una de las cantantes m\u00e1s emblem\u00e1ticas del g\u00e9nero regional mexicano.<\/p>\n<p>Paquita la del Barrio fue una cantante mexicana muy conocida por su estilo \u00fanico dentro de la m\u00fasica ranchera, con una fuerte identidad y una gran presencia en la m\u00fasica popular mexicana. Naci\u00f3 bajo el nombre de Francisca Viveros Barradas.<\/p>\n<p>A lo largo de su carrera, Paquita gan\u00f3 gran notoriedad por sus interpretaciones de canciones que hablan de desamor, venganza y empoderamiento, temas que tocaban profundamente a las mujeres de su \u00e9poca.<\/p>\n<p>Es famosa por su estilo vocal muy caracter\u00edstico, su actitud desafiante y sus letras, en las cuales se refiere en muchos casos a la figura del \u00abmacho\u00bb o \u00abhombre infiel\u00bb, lo que la hizo muy popular entre las mujeres. Paquita la del Barrio es conocida especialmente por canciones como \u00abRata de dos patas\u00bb, \u00abLa culebra\u00bb y \u00abLas mujeres que nos est\u00e1n gobernando\u00bb, entre otras.<\/p>\n<p>Tambi\u00e9n se le conoce como &#8216;la Reina del Pueblo&#8217; o &#8216;la Guerrillera del Bolero&#8217;, y ha destacado que sus canciones se expresan contra la cultura machista.<\/p><div class=\"notic-content-middle\" id=\"notic-2839183932\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Otros \u00e9xitos en su carrera, que comenz\u00f3 en 1970, incluyen &#8216;Tres veces te enga\u00f1\u00e9&#8217;, &#8216;El consejo&#8217;, &#8216;Me saludas a la tuya&#8217;, &#8216;Las mujeres mandan&#8217;, &#8216;Viejo rabo verde&#8217;, &#8216;Hombres malvados&#8217; y &#8216;Pobre pistolita&#8217;.<\/p>\n<p>Le sobreviven tres hijos tras dos matrimonios, con Miguel Gerardo, un exfuncionario local de quien se divorci\u00f3 en 1975, y Alfonso Mart\u00ednez, ya fallecido.<\/p>\n<p>La cantante recibi\u00f3 el premio a la Trayectoria Art\u00edstica durante los Premios Billboard de la M\u00fasica Latina que se realiz\u00f3 en 2021 en Miami, donde reconocieron su \u00abtrayectoria excepcional, abarcando contribuciones art\u00edsticas y personales que han marcado el desarrollo de la m\u00fasica latina en el mundo\u00bb.<\/p>\n<p>La organizaci\u00f3n de los Billboard destac\u00f3 que la mexicana llevaba m\u00e1s de 50 a\u00f1os como int\u00e9rprete de m\u00fasica ranchera y de boleros, con temas que denuncian especialmente la cultura y actitudes machistas.<\/p>\n<p>Descubri\u00f3 desde ni\u00f1a su potente voz y talento para la m\u00fasica mientras cantaba con frecuencia en los festivales escolares.<\/p>\n<p>En la d\u00e9cada de 1970 form\u00f3 el dueto &#8216;Las Golondrinas&#8217; junto a su hermana Viola y en 1984 grab\u00f3 su primer disco, &#8216;El Barrio de los faroles&#8217;, con el que recibi\u00f3 el famoso sobrenombre de Paquita la del Barrio.<\/p>\n<p>Su popularidad creci\u00f3 r\u00e1pidamente y su restaurante &#8216;Casa Paquita&#8217;, donde ella cantaba, se convirti\u00f3 en parada obligatoria para artistas y figuras de la m\u00fasica, desde Joaqu\u00edn Sabina hasta Luis Miguel.<\/p>","protected":false},"excerpt":{"rendered":"<p>La cantante reconocida por sus temas \u00abRata de dos patas\u00bb y \u00abLa culebra\u00bb, muri\u00f3 hoy a la edad de 77 a\u00f1os. CIUDAD DE MEXICO \u2014 La cantante mexicana Paquita la del Barrio, conocida por su canci\u00f3n &#8216;Rata de dos patas&#8217; falleci\u00f3 este lunes a sus 77 a\u00f1os de edad, seg\u00fan un comunicado oficial en las [&hellip;]<\/p>","protected":false},"author":0,"featured_media":215272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-214293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=214293"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214293\/revisions"}],"predecessor-version":[{"id":214582,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214293\/revisions\/214582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/215272"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=214293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=214293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=214293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}