{"id":214080,"date":"2025-02-10T14:52:58","date_gmt":"2025-02-10T18:52:58","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/gobierno\/20250210\/alcaldesa-de-gurabo-declina-oferta-para-procuradora-de-las-mujeres\/"},"modified":"2025-07-11T06:01:08","modified_gmt":"2025-07-11T06:01:08","slug":"alcaldesa-de-gurabo-declina-oferta-para-procuradora-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20250210\/alcaldesa-de-gurabo-declina-oferta-para-procuradora-de-las-mujeres\/","title":{"rendered":"Alcaldesa de Gurabo declina oferta para Procuradora de las Mujeres"},"content":{"rendered":"<h3>La gobernadora Jenniffer Gonz\u00e1lez reconoci\u00f3 que Rosachely Rivera no se hizo disponible para el cargo.<\/h3>\n<p>La gobernadora Jenniffer Gonz\u00e1lez no est\u00e1 en posici\u00f3n de nominar a una persona para la Procuradur\u00eda de las Mujeres. Sin embargo, reconoci\u00f3 que la alcaldesa de Gurabo, Rosachely Rivera, figur\u00f3 en la corta lista de candidatas para el puesto.<\/p>\n<p>\u00abYa hemos entrevistado para ese puesto a m\u00e1s de una persona. Me hubiese encantado que fuese la alcaldesa, pero ella (Rivera) sali\u00f3 abrumadoramente favorecida por la gente de Gurabo con m\u00e1s del 74% del voto. Ella me dijo que no va a defraudar a su gente y tiene mucho trabajo por hacer\u00bb, respondi\u00f3 Gonz\u00e1lez durante una rueda de prensa al concluir una visita al Departamento de Hacienda.<\/p>\n<p>Se ha especulado que el nombramiento de la Procuradora de las Mujeres ocurrir\u00e1 una la Asamblea Legislativa determine el futuro de Janet Parra, designada secretaria del Departamento de Justicia. Gonz\u00e1lez no entr\u00f3 en los potenciales nombres que tiene bajo su consideraci\u00f3n. Madeline Berm\u00fadez es la procuradora interina.<\/p><div class=\"notic-content-middle\" id=\"notic-661531575\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u00abNo han ocurrido una negociaci\u00f3n. El Senado muy diligentemente ha pautado vistas p\u00fablicas los s\u00e1bados y han estado aprobando nombramientos. La persona que est\u00e1 (Berm\u00fadez), hace un trabajo. En su momento, har\u00e9 el nombramiento\u00bb, insisti\u00f3.<\/p>\n<p>La alcaldesa de Gurabo, por su parte, anunci\u00f3 que no aceptar\u00e1 el puesto en una publicaci\u00f3n en sus redes sociales. Rivera Santana explic\u00f3 que su prioridad sigue siendo el municipio que la eligi\u00f3 con casi un 80% de los votos.<\/p>\n<p>\u00abMe siento profundamente agradecida con la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, por la deferencia de haberme considerado para dirigir la Oficina de la Procuradora de la Mujer. Para m\u00ed, este reconocimiento, es un reflejo de a\u00f1os de trabajo incansable en favor de los derechos de las mujeres, siempre promoviendo la educaci\u00f3n, la ayuda y los servicios necesarios para la prevenci\u00f3n de la violencia contra la mujer. Sin embargo, en estos momentos mi mayor compromiso sigue siendo con el pueblo de Gurabo, que me eligi\u00f3 como Alcaldesa con casi un 80% de los votos para servirles con entrega y dedicaci\u00f3n. Desde esta posici\u00f3n, continuar\u00e9 trabajando con el mismo \u00edmpetu por los m\u00e1s vulnerables, asegurando que nuestras comunidades sigan avanzando hacia un futuro de igualdad y justicia. \u00a1Gracias por esta muestra de confianza! Sigamos construyendo juntos un Puerto Rico donde todas y todos podamos vivir con dignidad y seguridad\u00bb, indic\u00f3 la alcaldesa mediante sus redes sociales.<\/p>","protected":false},"excerpt":{"rendered":"<p>La gobernadora Jenniffer Gonz\u00e1lez reconoci\u00f3 que Rosachely Rivera no se hizo disponible para el cargo. La gobernadora Jenniffer Gonz\u00e1lez no est\u00e1 en posici\u00f3n de nominar a una persona para la Procuradur\u00eda de las Mujeres. Sin embargo, reconoci\u00f3 que la alcaldesa de Gurabo, Rosachely Rivera, figur\u00f3 en la corta lista de candidatas para el puesto. \u00abYa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":215616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-214080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=214080"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214080\/revisions"}],"predecessor-version":[{"id":215617,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/214080\/revisions\/215617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/215616"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=214080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=214080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=214080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}