{"id":213465,"date":"2025-01-22T05:15:00","date_gmt":"2025-01-22T09:15:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=213465"},"modified":"2025-07-11T06:33:17","modified_gmt":"2025-07-11T06:33:17","slug":"estudio-de-asore-revela-que-hay-leyes-han-afectado-desarrollo-de-esa-industria","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20250122\/estudio-de-asore-revela-que-hay-leyes-han-afectado-desarrollo-de-esa-industria\/","title":{"rendered":"Estudio de ASORE revela que hay leyes han afectado desarrollo de esa industria"},"content":{"rendered":"<h3>El presidente de ASORE, Carlos Budet, hizo un llamado urgente al gobierno para detener la implementaci\u00f3n de leyes y reglamentos que impactan negativamente el desarrollo econ\u00f3mico de la industria.<\/h3>\n<p>La Asociaci\u00f3n de Restaurantes de Puerto Rico (ASORE) present\u00f3 el estudio \u201cProyecciones 2025\u201d, revelando un panorama mixto para la industria, pero enfatizando la necesidad de un ambiente legislativo que no obstaculice el desarrollo econ\u00f3mico de esta industria.<\/p>\n<p>Carlos Budet, presidente de ASORE, hizo un llamado urgente a la legislatura y al gobierno para detener la implementaci\u00f3n de leyes y reglamentos que impactan negativamente el desarrollo econ\u00f3mico de la industria.<\/p>\n<p>\u201cLos hallazgos de este informe nos muestran c\u00f3mo estas pol\u00edticas est\u00e1n afectando de manera desproporcionada a los restaurantes, que ya lideran las quiebras en el sector comercial del pa\u00eds. Aunque los m\u00e1rgenes de ganancia han bajado, sigue habiendo espacio para el crecimiento, pero necesitamos un ambiente legislativo que fomente el crecimiento, no que lo obstaculice\u201d, enfatiz\u00f3.<\/p>\n<p>\u00abLos retos que enfrentamos son reales y significativos, pero con la colaboraci\u00f3n entre la industria, el gobierno y nuestros aliados, podemos encontrar soluciones que fomenten un desarrollo sostenible para los restaurantes de Puerto Rico\u00bb, a\u00f1adi\u00f3 el presidente de ASORE.<\/p>\n<p>Asimismo, ASORE destac\u00f3 una reducci\u00f3n en los m\u00e1rgenes de ganancia y un entorno econ\u00f3mico desafiante y el informe resalt\u00f3 que los restaurantes siguen siendo una opci\u00f3n de negocio viable. Seg\u00fan el an\u00e1lisis, la clave radica en la implementaci\u00f3n de estrategias innovadoras, pr\u00e1cticas administrativas s\u00f3lidas y la apuesta por la educaci\u00f3n continua para enfrentar los retos actuales.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/economia\/ahora\/20241209\/https-www-noticel-com-economia-ahora-20241209-asore-obtiene-un-triunfo-en-el-tribunal-de-apelaciones-sobre-los-plasticos-de-un-solo-uso\/\" id=\"link-1dc1220935b83c1de3b9d6aa7d904284\" target=\"_blank\">ASORE obtiene un triunfo en el Tribunal de Apelaciones sobre los pl\u00e1sticos de un uso<\/a><\/p>\n<p>Tambi\u00e9n se present\u00f3 el an\u00e1lisis EAT; estudio de r\u00e9cord que presenta toda la informaci\u00f3n actualizada del consumidor que la industria de restaurantes necesita saber para tomar decisiones m\u00e1s informadas y enfocadas.<\/p>\n<p>El evento cont\u00f3 con la presencia de la nueva secretaria del Departamento de Asuntos del Consumidor (DACO), Natalia Catoni, y el secretario del Departamento de Desarrollo Econ\u00f3mico y Comercio (DDEC), Sebasti\u00e1n Negr\u00f3n.<\/p>\n<p>\u00abUstedes son una parte muy importante de nuestra econom\u00eda. Sin duda, esta econom\u00eda no es solo vital en el punto de vista econ\u00f3mico, sino tambi\u00e9n como un pilar fundamental de nuestra cultura y nuestras tradiciones gastron\u00f3micas\u00bb, dijo Negr\u00f3n.<\/p>\n<p>Respecto al EAT, Catoni expres\u00f3 que \u00abes importante, ese es el negocio de los restaurantes, conocer el consumo\u00bb.<\/p>\n<p>\u00abSi ellos no saben lo que se consume, no pueden venderle al consumidor. Esto es una relaci\u00f3n simbi\u00f3tica. Yo puedo vender la Coca-Cola, pero si la gente no est\u00e1 tomando Coca-Cola, por decirlo as\u00ed, pues, \u00bfqu\u00e9 voy a hacer vendiendo refrescos? T\u00fa tienes que saber qu\u00e9 espera el consumidor. Y, en parte, por eso yo estoy aqu\u00ed. Porque yo defiendo los derechos del consumidor. Ahora, lo que consume, eso es la decisi\u00f3n de cada cual\u00bb, indic\u00f3.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/economia\/top-stories\/20241019\/disminuyen-los-ingresos-para-restaurantes-en-2024\/\" id=\"link-9b879bac41d82c8bd31961122dc44c08\" target=\"_blank\">Disminuyen los ingresos para restaurantes en 2024<\/a><\/p>\n<p>Por otro lado, el informe revel\u00f3 que el porcentaje de restaurantes que reportaron un aumento en ventas disminuy\u00f3 de 55.8% en 2023 a 48.2% en 2024, mientras que aquellos con ventas m\u00e1s bajas aumentaron de 32.4% a 43.8% en el mismo per\u00edodo. Adem\u00e1s, el 43% de los encuestados indic\u00f3 que sus m\u00e1rgenes de ganancia son menores al 8%, un aumento significativo respecto al 37% reportado en 2022. Estos datos reflejan las dif\u00edciles condiciones operativas a las que se enfrentan los negocios de comida en Puerto Rico.<\/p>\n<p>Otros datos significativos del informe incluyen:<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/la-calle\/economia\/top-stories\/20240908\/crece-el-negocio-de-food-trucks-pero-nadie-sabe-cuantos-son\/\" id=\"link-acad71dfc045600c61623f0efb2d1ff9\" target=\"_blank\">Crece el negocio de \u00abfood trucks\u00bb, pero nadie sabe cu\u00e1ntos son<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de ASORE, Carlos Budet, hizo un llamado urgente al gobierno para detener la implementaci\u00f3n de leyes y reglamentos que impactan negativamente el desarrollo econ\u00f3mico de la industria. La Asociaci\u00f3n de Restaurantes de Puerto Rico (ASORE) present\u00f3 el estudio \u201cProyecciones 2025\u201d, revelando un panorama mixto para la industria, pero enfatizando la necesidad de un [&hellip;]<\/p>","protected":false},"author":0,"featured_media":216499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-213465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=213465"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213465\/revisions"}],"predecessor-version":[{"id":216500,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213465\/revisions\/216500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/216499"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=213465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=213465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=213465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}