{"id":213362,"date":"2025-01-18T11:25:27","date_gmt":"2025-01-18T15:25:27","guid":{"rendered":"https:\/\/www.noticel.com\/estados-unidos\/mundo\/top-stories\/20250118\/milei-bukele-y-noboa-entre-los-invitados-a-la-investidura-de-trump\/"},"modified":"2025-07-11T07:13:46","modified_gmt":"2025-07-11T07:13:46","slug":"milei-bukele-y-noboa-entre-los-invitados-a-la-investidura-de-trump","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/estados-unidos\/20250118\/milei-bukele-y-noboa-entre-los-invitados-a-la-investidura-de-trump\/","title":{"rendered":"Milei, Bukele y Noboa, entre los invitados a la investidura de Trump"},"content":{"rendered":"<h3>La toma de posesi\u00f3n del presidente de los Estados Unidos, Donald Trump, ser\u00e1 el pr\u00f3ximo 20 de enero.<\/h3>\n<p><strong id=\"strong-c32425d40b5015e4f8378610cd000f9d\">WASHINGTON <\/strong>\u2014 El presidente electo de Estados Unidos, Donald Trump, ha invitado a su toma de posesi\u00f3n a mandatarios con los que comparte afinidad pol\u00edtica, como el argentino Javier Milei; el salvadore\u00f1o Nayib Bukele; y el ecuatoriano Daniel Noboa; dejando afuera a otros l\u00edderes como la mexicana Claudia Sheinbaum.<\/p>\n<p>No es habitual que los presidentes estadounidenses inviten a l\u00edderes extranjeros a su toma de posesi\u00f3n, pero Trump ha optado por rodearse de pol\u00edticos que comparten su ideolog\u00eda, a excepci\u00f3n del chino Xi Jinping, que tambi\u00e9n fue invitado pese a su rivalidad.<\/p>\n<p><strong id=\"strong-cb9d32ec2dcc00cf93066e54d0b753d3\">De Javier Milei a Xi Jinping<\/strong><\/p>\n<p>La invitaci\u00f3n a Milei es la primera que recibe un presidente argentino a una investidura en Estados Unidos, destac\u00f3 el portavoz de la Casa Rosada, Manuel Adorni, en una rueda de prensa el 16 de diciembre.<\/p>\n<p>El mandatario libertario de Argentina, que profesa una gran admiraci\u00f3n por Trump, se vio por \u00faltima vez con el republicano en una cena en su mansi\u00f3n de Florida poco despu\u00e9s de que este ganara las elecciones del 5 de noviembre.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/estados-unidos\/mundo\/top-stories\/20250106\/congreso-certifica-el-triunfo-de-donald-trump\/\" id=\"link-f58b3464b4d0cb5b2d81433145c07512\">Congreso certifica el triunfo de Donald Trump<\/a><\/p>\n<p>Seg\u00fan Adorni, tambi\u00e9n fueron invitados a la toma de posesi\u00f3n el 20 de enero Bukele y la primera ministra italiana, Giorgia Meloni, quien recientemente se reuni\u00f3 con Trump en Florida.<\/p>\n<p>El Gobierno ecuatoriano anunci\u00f3 el domingo que Noboa estar\u00e1 en la investidura un d\u00eda despu\u00e9s de participar en un debate electoral por las presidenciales en Ecuador.<\/p>\n<p>Noboa, nacido en Miami, ha viajado en numerosas ocasiones al pa\u00eds norteamericano desde que asumi\u00f3 su mandato, tanto en visitas oficiales como de car\u00e1cter personal.<\/p>\n<p>Se espera adem\u00e1s la presencia del primer ministro h\u00fangaro, Viktor Orb\u00e1n, el \u00fanico l\u00edder europeo que ha respaldado abiertamente a Trump desde las elecciones que este gan\u00f3 en 2016.<\/p>\n<p>El presidente chino, Xi Jinping, tambi\u00e9n fue invitado, seg\u00fan confirm\u00f3 el equipo de Trump el pasado 12 de diciembre, aunque su presencia es poco probable dado que son pocos los viajes al extranjero que realiza el mandatario del gigante asi\u00e1tico.<\/p><div class=\"notic-content-middle\" id=\"notic-1620596202\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/estados-unidos\/elecciones\/mundo\/top-stories\/20241106\/trump-logra-la-victoria-en-estados-unidos\/\" id=\"link-b6210eaa139df2681db3ad67e24132c1\">Trump logra la victoria en Estados Unidos<\/a><\/p>\n<p>La pr\u00f3xima portavoz de la Casa Blanca, Karoline Leavitt, explic\u00f3 que la invitaci\u00f3n a Xi es una demostraci\u00f3n de que Trump busca mantener un \u00abdi\u00e1logo abierto\u00bb no solo con aliados, sino tambi\u00e9n con adversarios.<\/p>\n<p><strong id=\"strong-cef8623ac824f3d5ebe0c9bd39c486e0\">Ni Sheinbaum, ni Lula ni S\u00e1nchez<\/strong><\/p>\n<p>En medio de las amenazas arancelarias de Trump contra M\u00e9xico, la presidenta de ese pa\u00eds, Claudia Sheinbaum, confirm\u00f3 este martes que no ha recibido la invitaci\u00f3n a la investidura, pero rest\u00f3 importancia a esta cuesti\u00f3n.<\/p>\n<p>\u00abNo, pero no pasa nada, no pasa nada, est\u00e1 ah\u00ed el embajador de M\u00e9xico en Estados Unidos, no hay problema\u00bb, dijo en su rueda de prensa matutina.<\/p>\n<p>Tampoco consta invitaci\u00f3n para otro l\u00edder de la izquierda regional, el presidente brasile\u00f1o Luiz In\u00e1cio Lula da Silva, pero s\u00ed para el expresidente de ese pa\u00eds Jair Bolsonaro.<\/p>\n<p>Bolsonaro solicit\u00f3 el viernes autorizaci\u00f3n a la Justicia para viajar a Estados Unidos, pues tiene prohibido salir de Brasil debido a que est\u00e1 investigado por un supuesto intento de golpe de Estado.<\/p>\n<p>En el caso de Espa\u00f1a, ser\u00e1 la embajadora en Washington, \u00c1ngeles Moreno, la que acudir\u00e1 a la investidura, confirm\u00f3 el lunes el ministro espa\u00f1ol de Exteriores, Jos\u00e9 Manuel Albares, quien record\u00f3 que en estos actos \u00abno se suele invitar a los jefes de Estado, de Gobierno o ministros\u00bb.<\/p>\n<p>Est\u00e1 descartada, por tanto, la participaci\u00f3n del presidente del Gobierno espa\u00f1ol Pedro S\u00e1nchez.<\/p>\n<p>S\u00ed estar\u00e1 en cambio el l\u00edder de Vox, Santiago Abascal, como parte de una delegaci\u00f3n invitada de la coalici\u00f3n europea Patriotas, de la que su partido es integrante.<\/p>\n<p>La ceremonia en la escalinata del Capitolio contar\u00e1 con la presencia del presidente saliente de Estados Unidos, Joe Biden, y todos los exmandatarios vivos del pa\u00eds: Bill Clinton, George W. Bush y Barack Obama. Michelle Obama no acompa\u00f1ar\u00e1 a su esposo al evento, informaron este martes medios locales.<\/p>","protected":false},"excerpt":{"rendered":"<p>La toma de posesi\u00f3n del presidente de los Estados Unidos, Donald Trump, ser\u00e1 el pr\u00f3ximo 20 de enero. WASHINGTON \u2014 El presidente electo de Estados Unidos, Donald Trump, ha invitado a su toma de posesi\u00f3n a mandatarios con los que comparte afinidad pol\u00edtica, como el argentino Javier Milei; el salvadore\u00f1o Nayib Bukele; y el ecuatoriano [&hellip;]<\/p>","protected":false},"author":0,"featured_media":217176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[16,17],"tags":[],"class_list":["post-213362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados-unidos","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=213362"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213362\/revisions"}],"predecessor-version":[{"id":217177,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213362\/revisions\/217177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/217176"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=213362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=213362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=213362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}