{"id":213035,"date":"2025-01-07T16:37:43","date_gmt":"2025-01-07T20:37:43","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/la-calle\/policiacas\/20250107\/nonagenario-que-fue-agredido-el-sabana-grande-sufre-infarto\/"},"modified":"2025-07-11T07:43:56","modified_gmt":"2025-07-11T07:43:56","slug":"nonagenario-que-fue-agredido-el-sabana-grande-sufre-infarto","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20250107\/nonagenario-que-fue-agredido-el-sabana-grande-sufre-infarto\/","title":{"rendered":"Nonagenario que fue agredido el Sabana Grande sufre infarto"},"content":{"rendered":"<h3>Don William Torres Torres hab\u00eda sido llevado de vuelta a una instituci\u00f3n hospitalaria tras experimentar una crisis nerviosa.<\/h3>\n<p>Don William Torres Torres, el nombre de 90 a\u00f1os que fue agredido el domingo en su hogar en Sabana Grande en medio de un robo, sufri\u00f3 un infarto hoy luego de experimentar una crisis nerviosa.<\/p>\n<p>La informaci\u00f3n fue adelantada por Telenoticias de Telemundo de Puerto Rico.<\/p><div class=\"notic-content-middle\" id=\"notic-2563883840\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Torres Torres hab\u00eda sido dado de alta el lunes, pero a su llegada a su hogar, tuvo una crisis nerviosa que oblig\u00f3 su ingreso al Hospital de la Concepci\u00f3n en San Germ\u00e1n.<\/p>\n<p>All\u00ed, Don William, seg\u00fan se inform\u00f3, sufri\u00f3 el infarto mientras esperaba una habitaci\u00f3n en el hospital. Ahora ser\u00e1 transferido a la unidad de cuidados intensivos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Don William Torres Torres hab\u00eda sido llevado de vuelta a una instituci\u00f3n hospitalaria tras experimentar una crisis nerviosa. Don William Torres Torres, el nombre de 90 a\u00f1os que fue agredido el domingo en su hogar en Sabana Grande en medio de un robo, sufri\u00f3 un infarto hoy luego de experimentar una crisis nerviosa. La informaci\u00f3n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":217892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15,2],"tags":[],"class_list":["post-213035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=213035"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213035\/revisions"}],"predecessor-version":[{"id":217893,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/213035\/revisions\/217893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/217892"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=213035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=213035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=213035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}