{"id":211767,"date":"2024-11-24T06:00:00","date_gmt":"2024-11-24T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=211767"},"modified":"2025-07-11T09:28:51","modified_gmt":"2025-07-11T09:28:51","slug":"mucho-mas-que-11-dias-el-precio-de-servir-de-un-funcionario-electoral","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/elecciones\/elecciones-2024\/20241124\/mucho-mas-que-11-dias-el-precio-de-servir-de-un-funcionario-electoral\/","title":{"rendered":"Mucho m\u00e1s que 11 d\u00edas: El precio de servir de un funcionario electoral"},"content":{"rendered":"<h3>Desde el balc\u00f3n de un segundo piso, donde se contempla el universo que compone un escrutinio general, NotiCel se dedic\u00f3 a observar, descifrar y compartir con los m\u00e1s interesantes rostros, desde los que guardan largos a\u00f1os de experiencia e historia en el servicio p\u00fablico, hasta aquellos j\u00f3venes que se involucran en el primero de muchos eventos eleccionarios.<\/h3>\n<p>Los s\u00e1bados son los d\u00edas m\u00e1s lentos. Aunque muchos preferir\u00edan descansar, ya han pasado 11 d\u00edas de escrutinio general, y el peso de saber que ning\u00fan precinto ha sido contabilizado en su totalidad, acumula, en los hombros y las mesas de los funcionarios electorales, cajas y cajas con papeletas que esperan por ser ratificados como si de una olla de presi\u00f3n se tratara.<\/p>\n<p>La temperatura del ambiente no es tan notable hasta que transcurren las horas, y sigues en el edificio. El contraste de colores, partidistas o no partidistas, que porta cada voluntario, va perdi\u00e9ndose entre monta\u00f1as de cajas marrones que, hasta cierto punto, pueden hacer tropezar a quien sea, en cualquier pasillo.<\/p>\n<p>Ya no se escuchan pleitos, como era usual en los primeros d\u00edas de trabajo. De vez en cuando, entre anuncios y recuentos, se oyen aplausos a coro, risas que contagian hasta a los que no tienen ni la menor idea de lo que ocurre y \u201ccumplea\u00f1os felices\u201d que disipan los aires de tensi\u00f3n y provocan sonrisas poco recurrentes en un proceso que siempre es tomado con la m\u00e1s intensa seriedad.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/elecciones\/top-stories\/20241122\/siguen-sin-dar-abasto-las-mesas-en-javaa-para-contar-el-voto-a-domicilio\/\" id=\"link-23172ae764281544e3ab4221b53dad41\" target=\"_blank\">Siguen sin dar abasto las mesas en JAVAA para contar el voto a domicilio<\/a><\/p>\n<p>\u201cNos hacemos compa\u00f1eros. Dejas a un lado las ideolog\u00edas pol\u00edticas y te pones a trabajar\u201d, cont\u00f3 un funcionario con m\u00e1s de 30 a\u00f1os de servicio que, en conversaci\u00f3n con <strong id=\"strong-ba1e96bc51906e0387b5cc5cdb8c530a\">NotiCel<\/strong>, prefiri\u00f3 no identificarse. \u201cAqu\u00ed no se viene a hacer amigos, pero todos estamos haciendo patria como lo entendemos mejor\u201d, abund\u00f3.<\/p>\n<p>En efecto, mientras se redacta esta nota, el fr\u00edo se intensifica y un abrigo se vuelve una herramienta esencial. Ya es la hora del almuerzo, y los funcionarios no pierden ni un minuto para despejar su mente y saciar el hambre. Quedan muchos maletines por abrir y contar.<\/p>\n<p>Con todos en el comedor, es m\u00e1s f\u00e1cil divisar las \u00e1reas que componen el proceso del escrutinio general. Mesas de control de actas, estad\u00edsticas, voto regular, a\u00f1adido a mano y las exclusivas de cada partido. El olor de las cajas de pizza, no de papeletas, es bastante notable en cualquier rinc\u00f3n del edificio.<\/p><div class=\"notic-content-middle\" id=\"notic-3540982658\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>\u201cAntes que funcionario, uno es servidor p\u00fablico, y si no entiendes eso, no puedes estar aqu\u00ed. Se trata de defender el derecho de un puertorrique\u00f1o como t\u00fa y como yo\u201d, narr\u00f3 una empleada de 52 a\u00f1os a <strong id=\"strong-e7583c443542e13baba48e836a0800f2\">NotiCel<\/strong>.<\/p>\n<p>\u201cSi me preguntas, yo no cambiar\u00eda nada de lo que he hecho, porque me gusta. He aprendido m\u00e1s estando en el \u2018field\u2019 que dejando que me lo cuenten\u201d, agreg\u00f3.<\/p>\n<p>Ya estando a la orilla de la \u00e9poca navide\u00f1a, cada d\u00eda son m\u00e1s los que recorren el piso de operaciones con un gorrito, un \u2018ugly sweater\u2019 o con orejitas de elfo. Asimismo, las mesas vuelven a llenarse de funcionarios con energ\u00edas recargadas para continuar la labor, recibir nuevas instrucciones o cuestionar si hay alg\u00fan otro cambio en el proceso que, durante 11 d\u00edas, han tratado de seguir fielmente.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/elecciones\/top-stories\/20241120\/deberia-extenderse-el-horario-para-los-funcionarios-del-escrutinio-general\/\" id=\"link-37efc757f88710f06a7fb6b9290c34ce\" target=\"_blank\">\u00bfDeber\u00eda extenderse el horario para los funcionarios del escrutinio general?<\/a><\/p>\n<p>A medida que cae el sol, disminuye el eco y el ruido en el ocasional campo de batalla conocido, m\u00e1s bien, como el Centro de Operaciones Electorales de la CEE, en Hato Rey. Los funcionarios, por fin, podr\u00e1n descansar unas horas y disfrutar de un domingo libre de papeletas, descuadres, revisiones y supervisi\u00f3n.<\/p>\n<p>Sin embargo, el tiempo pasa sin descanso, y la posibilidad de que el escrutinio cierre sus mesas entre el 20 y 22 de diciembre, antes de la Navidad, como es expectativa de la presidenta de la CEE, Jessika Padilla Rivera, provoca gestos dudosos en los comisionados electorales, quienes d\u00eda y tarde recorren las estaciones de recuento entre entrevistas, dudas por atender y convocatorias del pleno organizacional.<\/p>\n<p>S\u00ed, para los funcionarios electorales, han sido m\u00e1s que 11 d\u00edas. Para el escrutinio, a\u00fan no se sabe.<\/p>","protected":false},"excerpt":{"rendered":"<p>Desde el balc\u00f3n de un segundo piso, donde se contempla el universo que compone un escrutinio general, NotiCel se dedic\u00f3 a observar, descifrar y compartir con los m\u00e1s interesantes rostros, desde los que guardan largos a\u00f1os de experiencia e historia en el servicio p\u00fablico, hasta aquellos j\u00f3venes que se involucran en el primero de muchos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":220652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-211767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=211767"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211767\/revisions"}],"predecessor-version":[{"id":220655,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211767\/revisions\/220655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/220652"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=211767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=211767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=211767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}