{"id":211228,"date":"2024-11-06T06:42:28","date_gmt":"2024-11-06T10:42:28","guid":{"rendered":"https:\/\/www.noticel.com\/elecciones\/estados-unidos\/mundo\/20241106\/trump-se-atribuye-la-victoria-en-estados-unidos\/"},"modified":"2025-07-11T10:15:31","modified_gmt":"2025-07-11T10:15:31","slug":"trump-logra-la-victoria-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/elecciones\/elecciones-2024\/20241106\/trump-logra-la-victoria-en-estados-unidos\/","title":{"rendered":"Trump logra la victoria en Estados Unidos"},"content":{"rendered":"<h3>Trump logr\u00f3 la victoria sobre la vicepresidenta dem\u00f3crata, Kamala Harris, con 277 delegados frente a 224.<\/h3>\n<p>Washington (EFE).- El candidato republicano a la Casa Blanca, Donald Trump, se proclam\u00f3 este mi\u00e9rcoles ganador de las elecciones presidenciales en Estados Unidos con un total por el momento de 277 votos electorales frente a los 224 de su rival, la dem\u00f3crata Kamala Harris, seg\u00fan las proyecciones de los principales medios del pa\u00eds.<\/p>\n<p>El expresidente ya se hab\u00eda atribuido la victoria frente a la vicepresidenta Harris durante un mitin ante sus seguidores en Palm Beach (Florida), tras obtener buenos resultados parciales y ganar el voto popular, seg\u00fan el escrutinio preliminar.<\/p>\n<p>Ser\u00e1 la primera vez en m\u00e1s de un siglo que un antiguo presidente vuelve a serlo (ya gobern\u00f3 entre 2017 y 2021) despu\u00e9s de perder unas elecciones (las de 2020) y tambi\u00e9n la primera ocasi\u00f3n en que un criminal convicto llega a la Presidencia del pa\u00eds.<\/p>\n<p>El Colegio Electoral es un \u00f3rgano integrado por 538 delegados que eligen los estados en funci\u00f3n de su poblaci\u00f3n. El candidato ganador en cada estado, aunque sea por un solo voto, se lleva todos sus compromisarios con la excepci\u00f3n de Nebraska y Maine. El aspirante que llega a 270 gana las elecciones.<\/p>\n<p>Acompa\u00f1ado de su familia y directivos de su campa\u00f1a, el expresidente asegur\u00f3 desde Palm Beach que gobernar\u00e1 para todos y que \u00abjuntos\u00bb har\u00e1n un Estados Unidos mejor.<\/p>\n<p>\u00abEl \u00e9xito nos va a unir, y vamos a empezar poniendo a Estados Unidos en primer lugar. No los defraudar\u00e9\u00bb, dijo durante un discurso de menos de media hora en el centro de convenciones de Palm Beach (en la costa este de Florida).<\/p>\n<p>El expresidente republicano agradeci\u00f3 a cada uno de los miembros de su familia y a los estadounidenses en un pronunciamiento que tuvo un tono mayormente conciliador y en el que invit\u00f3 a \u00abponer atr\u00e1s las divisiones de los \u00faltimos a\u00f1os\u00bb.<\/p>\n<p>Trump celebr\u00f3 sus buenos resultados en estados clave como Carolina del Norte, Georgia, Pensilvania y Wisconsin, y se preci\u00f3 de haber recobrado la mayor\u00eda en el Senado para los republicanos.<\/p>\n<p>Antes de finalizar el recuento y tras conocerse algunos datos importantes sobre la tendencia de voto en todo el pa\u00eds, Harris decidi\u00f3 cancelar el discurso que estaba previsto que ofreciera al final de la jornada electoral y lo pospuso hasta este mi\u00e9rcoles, seg\u00fan su campa\u00f1a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Trump logr\u00f3 la victoria sobre la vicepresidenta dem\u00f3crata, Kamala Harris, con 277 delegados frente a 224. Washington (EFE).- El candidato republicano a la Casa Blanca, Donald Trump, se proclam\u00f3 este mi\u00e9rcoles ganador de las elecciones presidenciales en Estados Unidos con un total por el momento de 277 votos electorales frente a los 224 de su [&hellip;]<\/p>","protected":false},"author":10,"featured_media":221847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9,16,17],"tags":[],"class_list":["post-211228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024","category-estados-unidos","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=211228"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211228\/revisions"}],"predecessor-version":[{"id":221848,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211228\/revisions\/221848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/221847"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=211228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=211228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=211228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}