{"id":211189,"date":"2024-11-05T14:14:09","date_gmt":"2024-11-05T18:14:09","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/elecciones\/20241105\/estamos-ganando-ampliamente-asegura-jesus-manuel-ortiz-sobre-el-voto-a-domicilio\/"},"modified":"2025-07-11T10:20:57","modified_gmt":"2025-07-11T10:20:57","slug":"estamos-ganando-ampliamente-asegura-jesus-manuel-ortiz-sobre-el-voto-a-domicilio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20241105\/estamos-ganando-ampliamente-asegura-jesus-manuel-ortiz-sobre-el-voto-a-domicilio\/","title":{"rendered":"\u201cEstamos ganando ampliamente\u201d, asegura Jes\u00fas Manuel Ortiz sobre el voto a domicilio"},"content":{"rendered":"<h3>El aspirante a la gobernaci\u00f3n sostuvo adem\u00e1s que la lucha por acaparar la mayor\u00eda del voto correo permanece entre el Partido Nuevo Progresista y el Partido Popular, dejando fuera a la denominada Alianza de Pa\u00eds entre el Movimiento Victoria Ciudadana y el Partido Independentista.<\/h3>\n<p>El candidato a la gobernaci\u00f3n Jes\u00fas Manuel Ortiz afirm\u00f3 este martes, a su llegada a un centro en Cupey para ejercer su derecho en el d\u00eda de elecci\u00f3n general, que el Partido Popular Democr\u00e1tico (PPD) \u201cest\u00e1 ganando ampliamente\u201d el voto a domicilio y asegur\u00f3 que muchos de los votos adelantados, que a\u00fan no se contabilizan, se emitieron a favor de su colectividad.<\/p>\n<p>\u201cTe lo voy a decir con toda claridad. Nosotros estamos ganando ampliamente el voto a domicilio, y eso lo saben los dem\u00e1s partidos\u201d, sostuvo Ortiz.<\/p>\n<p>\u201cEn el voto por correo, estamos en la lucha con el PNP (Partido Nuevo Progresista). Yo lo que te puedo garantizar es que esa batalla es entre el PPD y el PNP, porque los otros partidos no hicieron una gran cantidad de trabajo ah\u00ed\u201d, agreg\u00f3.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/elecciones\/ahora\/top-stories\/20241105\/jesus-manuel-ortiz-confronta-problemas-con-maquina-de-escrutinio-a-la-hora-de-votar\/\" id=\"link-d6b66eb04252353cc779a9d402c7345b\" target=\"_blank\"><strong id=\"strong-c85a2774eacd8a92418971e0b6c06210\">Jes\u00fas Manuel Ortiz confronta problemas con m\u00e1quina de escrutinio a la hora de votar<\/strong><\/a><\/p>\n<p>Ortiz dijo a los medios que sobre 200,000 votos adelantados presentaron problemas con las m\u00e1quinas de Dominion Voting Systems, empresa que provee, una vez m\u00e1s, los instrumentos de escrutinio electr\u00f3nico a la Comisi\u00f3n Estatal de Elecciones (CEE).<\/p>\n<p>\u201cNosotros entre 80,000 y 100,000 votos adelantados que trabajamos, porque como presidente (del PPD) yo me asegur\u00e9 de que no nos ocurriera lo que nos ocurri\u00f3 en el 2020. Por eso es que el PNP y los dem\u00e1s partidos han estado poniendo trabas para que se cuente ese voto, porque se supone que, una vez cierren los colegios a las 5:00 p.m., ese voto estuviera contado y se entrara\u201d, indic\u00f3 el legislador popular, quien se mostr\u00f3 confiado en que el trabajo de los funcionarios de su colectividad le \u201casegur\u00f3\u201d una ventaja.<\/p><div class=\"notic-content-middle\" id=\"notic-2080558837\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>A las alegaciones de que el alcalde de Caguas, William \u201cWillito\u201d Miranda Torres, \u201csimpatizaba\u201d con las posturas de su oponente a la gobernaci\u00f3n y l\u00edder de la Alianza de Pa\u00eds, Juan Dalmau, Ortiz arremeti\u00f3 con que el mandatario municipal \u201cno dijo eso\u201d.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/elecciones\/top-stories\/20241105\/juan-dalmau-y-griselle-morales-llegan-juntos-a-votar\/\" id=\"link-cda455c6151b9b3f129d43a9168dac6c\" target=\"_blank\"><strong id=\"strong-5f21de58c85dd861e3115c6506bbd8e2\">Juan Dalmau y Griselle Morales llegan juntos a votar<\/strong><\/a><\/p>\n<p>\u201cWillito dijo que era un voto \u00edntegro (&#8230;) Willito Miranda Torres ha sido un colaborador de mi campa\u00f1a, est\u00e1 haciendo un gran trabajo en Caguas, su equipo electoral y estructura est\u00e1 \u2018amol\u00e1\u2019. Va a ganar muy bien en Caguas \u201d, contest\u00f3 el aspirante.<\/p>\n<p>Sobre las figuras s\u00f3lidos del PPD que han expresado p\u00fablicamente su intenci\u00f3n de apoyar a la Alianza, Ortiz se\u00f1al\u00f3 que \u201chay fuga en todos los partidos\u201d<\/p>\n<p>\u201cYo tengo muchos estadistas que van a votar por m\u00ed. Aqu\u00ed est\u00e1n todos los partidos pidiendo votos de electores de otros partidos. Lo que demuestra esta elecci\u00f3n es que todo el mundo sabe que no gana solo con sus electores\u201d, concluy\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>El aspirante a la gobernaci\u00f3n sostuvo adem\u00e1s que la lucha por acaparar la mayor\u00eda del voto correo permanece entre el Partido Nuevo Progresista y el Partido Popular, dejando fuera a la denominada Alianza de Pa\u00eds entre el Movimiento Victoria Ciudadana y el Partido Independentista. El candidato a la gobernaci\u00f3n Jes\u00fas Manuel Ortiz afirm\u00f3 este martes, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":221958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9,2],"tags":[],"class_list":["post-211189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=211189"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211189\/revisions"}],"predecessor-version":[{"id":221964,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/211189\/revisions\/221964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/221958"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=211189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=211189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=211189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}