{"id":210432,"date":"2024-10-12T10:59:59","date_gmt":"2024-10-12T14:59:59","guid":{"rendered":"https:\/\/www.noticel.com\/fama\/pop\/top-stories\/20241012\/actos-funebres-de-eddie-miro-comenzaran-el-lunes\/"},"modified":"2025-07-11T11:21:53","modified_gmt":"2025-07-11T11:21:53","slug":"actos-funebres-de-eddie-miro-comenzaran-el-lunes","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/entretenimiento\/fama\/20241012\/actos-funebres-de-eddie-miro-comenzaran-el-lunes\/","title":{"rendered":"Actos f\u00fanebres de Eddie Mir\u00f3 comenzar\u00e1n el lunes"},"content":{"rendered":"<h3>El sepelio ser\u00e1 el martes en el cementerio de Morovis.<\/h3>\n<p>Los actos f\u00fanebres del recordado presentador de televisi\u00f3n Eddie Mir\u00f3 comenzar\u00e1n este lunes, 14 de octubre, inform\u00f3 su familia.<\/p>\n<p>El veterano animador falleci\u00f3 el pasado 9 de octubre, tras haber estado ingresado en el Hospital Centro M\u00e9dico desde el 26 de agosto, luego de sufrir una ca\u00edda. Aunque Eddie mostr\u00f3 signos iniciales de mejor\u00eda, su estado de salud se complic\u00f3 debido a una neumon\u00eda por aspiraci\u00f3n, lo que finalmente deriv\u00f3 en un fallo respiratorio.<\/p>\n<p>De acuerdo con el itinerario de los actos, habr\u00e1 actividades privadas y para el p\u00fablico general.<\/p>\n<p><strong id=\"strong-451552efbc07b7f8695edf114783b9a7\">Lunes 14 de octubre<\/strong><\/p>\n<p><em id=\"emphasis-fef624d88c0f1b0c294bccd89376c5ba\">11:00 am &#8211; 2:00 pm &#8211; <\/em>Recibimiento y Guardia de Honor en Telemundo. *Evento privado para la familia, clase art\u00edstica y empleados del canal.<\/p>\n<p><em id=\"emphasis-fa3e18e179a34b9b618706af5a8117b3\">2:00 pm &#8211; <\/em>Traslado de Telemundo a Funeraria Ehret.<\/p><div class=\"notic-content-middle\" id=\"notic-529707044\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p><em id=\"emphasis-d0b6d46f4a966748d18e18f2b11322ab\">3:00 pm- 8:00 pm &#8211; <\/em>Velatorio en la Funeraria Ehret en San Juan. *Abierto al p\u00fablico general.<\/p>\n<p><strong id=\"strong-7eb793cb12646ee8c6cc2a6240d5ad9e\">Martes 15 de octubre<\/strong><\/p>\n<p><em id=\"emphasis-bd1213b2874438efb50ec6bfa85037d1\">10:00 am &#8211; <\/em>Misa en la Funeraria Ehret de San Juan.<\/p>\n<p><em id=\"emphasis-10eeaec8f395f42bf3ef6f79c461e160\">12:00 pm &#8211; <\/em>Salida de Funeraria Ehret a Morovis.<\/p>\n<p><em id=\"emphasis-7cb1ea04c23f6969df5bf5c8f0b61d07\">2:00 pm &#8211; <\/em>Sepelio en el Cementerio Nacional en Morovis. *Abierto al p\u00fablico general<\/p>\n<p>Vea: <a href=\"https:\/\/noticel.com\/en\/pop\/top-stories\/20241009\/se-apaga-el-hombre-de-la-eterna-sonrisa-eddie-miro\/\" id=\"link-4871eb98ae81bfe6da6e513d9a260ced\" target=\"_blank\">Se apaga el &#8216;hombre de la eterna sonrisa&#8217; Eddie Mir\u00f3<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El sepelio ser\u00e1 el martes en el cementerio de Morovis. Los actos f\u00fanebres del recordado presentador de televisi\u00f3n Eddie Mir\u00f3 comenzar\u00e1n este lunes, 14 de octubre, inform\u00f3 su familia. El veterano animador falleci\u00f3 el pasado 9 de octubre, tras haber estado ingresado en el Hospital Centro M\u00e9dico desde el 26 de agosto, luego de sufrir [&hellip;]<\/p>","protected":false},"author":0,"featured_media":223566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-210432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=210432"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210432\/revisions"}],"predecessor-version":[{"id":223567,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210432\/revisions\/223567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/223566"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=210432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=210432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=210432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}