{"id":210114,"date":"2024-10-02T09:54:43","date_gmt":"2024-10-02T13:54:43","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/educacion\/vida\/20241002\/para-la-naturaleza-presenta-libro-sobre-la-flora-boricua\/"},"modified":"2025-07-11T11:47:09","modified_gmt":"2025-07-11T11:47:09","slug":"para-la-naturaleza-presenta-libro-sobre-la-flora-boricua","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20241002\/para-la-naturaleza-presenta-libro-sobre-la-flora-boricua\/","title":{"rendered":"Para la Naturaleza presenta libro sobre la flora boricua"},"content":{"rendered":"<h3>\u00abFlora Borinqueniana: tres siglos de ilustraciones bot\u00e1nicas\u00bb se present\u00f3 primero como exhibici\u00f3n.<\/h3>\n<p>Luego de una exitosa presentaci\u00f3n en el Museo de Arte del Recinto Universitario de Mayag\u00fcez y el Museo de Historia, Antropolog\u00eda y Arte de la Universidad de Puerto Rico (UPR), Recinto de R\u00edo Piedras, la exhibici\u00f3n \u00abFlora Borinqueniana: tres siglos de ilustraciones bot\u00e1nicas\u00bb se transforma en un libro.<\/p>\n<p>La exposici\u00f3n curada por el Dr. Eugenio Santiago Valent\u00edn, explora la construcci\u00f3n del conocimiento bot\u00e1nico del archipi\u00e9lago y su contexto hist\u00f3rico desde finales del siglo 18 hasta las primeras tres d\u00e9cadas del siglo 20.<\/p>\n<p>Santiago Valent\u00edn, catedr\u00e1tico del Departamento de Biolog\u00eda del Recinto de R\u00edo Piedras de la UPR, y director del Herbario del Jard\u00edn Bot\u00e1nico, estuvo a cargo de la redacci\u00f3n del libro, as\u00ed como de la curadur\u00eda de la exhibici\u00f3n. Fiel a los intereses del autor, la publicaci\u00f3n presenta una mirada multidisciplinaria a la construcci\u00f3n del conocimiento bot\u00e1nico en las islas de Puerto Rico, un intercambio de saberes que entrelaza la bot\u00e1nica, el arte, la historia, la cultura y la sociedad en Puerto Rico desde finales del siglo 18 hasta el primer tercio del siglo 20. Esta mirada pluridimensional es novel y narra una historia que no se hab\u00eda contado hasta este proyecto.<\/p>\n<p>El texto profundiza la construcci\u00f3n del conocimiento bot\u00e1nico y sus intersecciones con la historia, la sociedad, la naturaleza y el arte puertorrique\u00f1o. A su vez, presenta documentos hist\u00f3ricos, im\u00e1genes e ilustraciones de algunos de los naturalistas que adelantaron estos saberes cient\u00edficos y que fungen como reflejo de los diferentes momentos hist\u00f3ricos: las expediciones de Mart\u00edn de Sess\u00e9 y Nicol\u00e1s Baudin; as\u00ed como los trabajos de Domingo Bello y Espinosa, Agust\u00edn Stahl, Ana Roqu\u00e9 de Duprey y Frances E. Horne.<\/p>\n<p>\u201cLa publicaci\u00f3n enlaza el conocimiento de contribuciones previas -y dispersas- de otros autores con mi trabajo original, resultado de d\u00e9cadas de investigaci\u00f3n. El trabajo est\u00e1 ilustrado con una selecci\u00f3n representativa de los aproximadamente 250 objetos que se presentaron en la exhibici\u00f3n, la cual incluy\u00f3 ilustraciones bot\u00e1nicas, as\u00ed como objetos arqueol\u00f3gicos, pinturas de artistas reconocidos, mapas, libros, fotograf\u00edas, partituras musicales, espec\u00edmenes de herbario y plantas vivas. Esta publicaci\u00f3n busca inspirar a la ciudadan\u00eda a conocer, valorar y proteger el acervo bot\u00e1nico puertorrique\u00f1o\u201d, coment\u00f3 el doctor Santiago Valent\u00edn.<\/p>\n<p>\u201cLa conexi\u00f3n entre el patrimonio natural y cultural de Puerto Rico est\u00e1 presente en nuestra misi\u00f3n como organizaci\u00f3n. &#8216;Flora borinqueniana: tres siglos de ilustraciones bot\u00e1nicas&#8217; es parte de una larga tradici\u00f3n de proyectos culturales que recalcan la importancia de la conservaci\u00f3n y hacen accesibles al p\u00fablico importantes piezas del patrimonio puertorrique\u00f1o\u201d, indic\u00f3 el presidente de Para la Naturaleza, Fernando Lloveras San Miguel.<\/p>\n<p>El p\u00fablico puede disfrutar de un extracto de la exhibici\u00f3n del 20 al 26 de octubre de 2024, en el Museo de Historia Natural de la Ciudad de Aguadilla. El libro est\u00e1 disponible en versi\u00f3n digital descargable, libre de costo a trav\u00e9s del portal paralanaturaleza.org\/floraborinqueniana<\/p>\n<p>La exhibici\u00f3n \u00abFlora borinqueniana: tres siglos de ilustraciones bot\u00e1nicas\u00bb es una colaboraci\u00f3n de Para la Naturaleza, el Museo de Arte de la Universidad de Puerto Rico, Recinto Universitario de Mayag\u00fcez, el Museo de Historia, Antropolog\u00eda y Arte de la Universidad de Puerto Rico, Recinto de R\u00edo Piedra. Este proyecto fue posible gracias a una subvenci\u00f3n importante del National Endowment for the Humanities: la democracia exige sabidur\u00eda, (proyecto GI-271303-21); y, en parte, gracias a un donativo recibido por el Instituto de Bot\u00e1nico Para la Naturaleza.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00abFlora Borinqueniana: tres siglos de ilustraciones bot\u00e1nicas\u00bb se present\u00f3 primero como exhibici\u00f3n. Luego de una exitosa presentaci\u00f3n en el Museo de Arte del Recinto Universitario de Mayag\u00fcez y el Museo de Historia, Antropolog\u00eda y Arte de la Universidad de Puerto Rico (UPR), Recinto de R\u00edo Piedras, la exhibici\u00f3n \u00abFlora Borinqueniana: tres siglos de ilustraciones bot\u00e1nicas\u00bb [&hellip;]<\/p>","protected":false},"author":0,"featured_media":224237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2,69],"tags":[],"class_list":["post-210114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=210114"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210114\/revisions"}],"predecessor-version":[{"id":224239,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/210114\/revisions\/224239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/224237"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=210114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=210114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=210114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}