{"id":209963,"date":"2024-09-28T06:00:00","date_gmt":"2024-09-28T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=209963"},"modified":"2025-07-11T11:58:31","modified_gmt":"2025-07-11T11:58:31","slug":"cee-admite-que-electores-tuvieron-menos-oportunidad-de-inscribirse-en-este-cuatrienio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20240928\/cee-admite-que-electores-tuvieron-menos-oportunidad-de-inscribirse-en-este-cuatrienio\/","title":{"rendered":"CEE admite que electores tuvieron menos oportunidad de inscribirse en este cuatrienio"},"content":{"rendered":"<h3>Interdicto federal sobre cierre prematuro del registro electoral queda sometido con el testimonio de un elector.<\/h3>\n<p>El secretario de la Comisi\u00f3n Estatal de Elecciones (CEE), Rolando Cuevas Col\u00f3n, admiti\u00f3 bajo juramento que los electores tuvieron menos oportunidades para inscribirse durante este cuatrienio ante la reducci\u00f3n de juntas de inscripci\u00f3n permanente (JIP) y la demora en la activaci\u00f3n del Registro Electr\u00f3nico de Electores (Sistema eRE).<\/p>\n<p>Las JIP se redujeron de 84 por toda la isla en 2021 a 10 en 2022 y luego a 13 en 2023. En ese periodo, hubo menos lugares para inscribirse y tampoco estaba en funci\u00f3n eRE. A preguntas de la jueza, el funcionario indic\u00f3 que, hasta septiembre, la \u00fanica alternativa de los votantes que ten\u00edan problemas con eRE era visitar una JIP y que no sab\u00eda cu\u00e1ntas solicitadas de tr\u00e1mites electorales la CEE hab\u00eda recibido para estas elecciones.<\/p>\n<p>La afirmaci\u00f3n del secretario contrasta con el argumento que ha hecho la candidata a la gobernaci\u00f3n del Partido Nuevo Progresista (PNP), Jenniffer Gonz\u00e1lez Col\u00f3n, y otros miembros de ese partido, de que el registro debe permanecer cerrado porque la poblaci\u00f3n tuvo tres a\u00f1os y medio para realizar sus transacciones.<\/p>\n<p>La afirmaci\u00f3n del secretario a las preguntas del abogado de Movimiento Victoria Ciudadana (MVC), Jos\u00e9 Lamas Rivera, fueron de las pocas posturas concretas que asumi\u00f3 como testigo en la vista ante la jueza federal Mar\u00eda Antongiorgi Jord\u00e1n sobre el recurso de interdicto que someti\u00f3 la Uni\u00f3n Americana de Libertades Civiles (ACLU) para conseguir que el registro electoral sea reabierto hasta el 6 de octubre, como dice el C\u00f3digo Electoral de 2020.<\/p>\n<p>El registr\u00f3 cerr\u00f3 el 21 de septiembre por disposici\u00f3n que tom\u00f3 el expresidente de la CEE, Francisco Rosado Colomer, el a\u00f1o pasado y que no fue impugnada en el tribunal. La falta de impugnaci\u00f3n fue uno de los fundamentos que us\u00f3 el juez superior Ra\u00fal Candelario L\u00f3pez para desestimar la demanda que someti\u00f3 MVC para conseguir lo mismo, una extensi\u00f3n del cierre de registro.<\/p>\n<p>El recurso federal se basa en el derecho constitucional al voto y lo que alega la ACLU es que las decisiones de la CEE, as\u00ed como sus fallas e incumplimiento de la ley, se tradujeron a una limitaci\u00f3n ilegal del derecho al voto de los ciudadanos que no pudieron realizar transacciones electorales antes del cierre. Esto incluye inscribirse, reactivarse, realizar cambios de direcci\u00f3n y otros.<\/p>\n<p>El otro testimonio vertido en sala fue el del joven de 27 a\u00f1os, V\u00edctor Altieri Garc\u00eda, quien relat\u00f3 c\u00f3mo el 9 de septiembre intent\u00f3 usar eRE para inscribirse y no fue hasta el 20 de septiembre, un d\u00eda antes del cierre del registro, que recibi\u00f3 una notificaci\u00f3n de que su solicitud fue rechazada. Este aviso solo le daba como alternativa que llamara al tel\u00e9fono xxx-xxx-xxxx (as\u00ed, con las x en vez de n\u00fameros).<\/p><div class=\"notic-content-middle\" id=\"notic-1575487846\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u201cMe qued\u00e9 bien confundido porque no sab\u00eda a d\u00f3nde dirigirme\u201d, dijo al confirmar que no acudi\u00f3 a ninguna JIP, no consult\u00f3 con el equipo de MVC que lo hab\u00eda instado a inscribirse en una actividad que hicieron a esos efectos y que la nota de rechazo a su solicitud tampoco le avisaba que ten\u00eda cuatro d\u00edas para corregir las deficiencias que el sistema le se\u00f1alaba. Como el cierre del registro era el d\u00eda siguiente y ten\u00eda trabajo, admiti\u00f3 que no hizo m\u00e1s nada despu\u00e9s de recibir el aviso.<\/p>\n<p>Tras unas cinco horas de vista, la jueza concedi\u00f3 unos plazos en el fin de semana para que las partes sometan sus \u00faltimos argumentos y, aunque no adelant\u00f3 una fecha para su determinaci\u00f3n, consign\u00f3 que \u201cel 6 de octubre se acerca (y) los votantes tienen derecho a saber cualquier determinaci\u00f3n que yo tome\u201d.<\/p>\n<p>Esa determinaci\u00f3n podr\u00eda ser que no tiene jurisdicci\u00f3n sobre la controversia o que no se cumplieron con los requisitos para emitir una orden interdictal contra la CEE, como argument\u00f3 el ente electoral a trav\u00e9s del Departamento de Justicia. Si accede al pedido de ACLU, podr\u00eda ordenar que se reabra el registro y que se le d\u00e9 publicidad a ese hecho.<\/p>\n<p>En su intervenci\u00f3n, Cuevas Col\u00f3n no fue preciso sobre cu\u00e1ndo se supone que, por ley, comenzara a funcionar eRE (1 de julio de 2022), cu\u00e1ndo realmente estuvo disponible (fines de octubre de 2023), sobre el voto ausente ni tampoco pudo explicar c\u00f3mo operaba un periodo de gracia de cuatro d\u00edas que la presidenta alterna de la CEE, Jessika Padilla Rivera, concedi\u00f3 el 18 de septiembre para los electores a quienes eRE les hubiera notificado alguna deficiencia en su tr\u00e1mite electoral.<\/p>\n<p>La vista comenz\u00f3 en la ma\u00f1ana, pero la jueza decret\u00f3 un receso temprano porque la CEE pidi\u00f3 tiempo para revisar la demanda enmendada que la ACLU someti\u00f3 el jueves en la noche. Al reanudar en la tarde, dos de los testigos demandantes no hab\u00edan podido regresar porque ten\u00edan citas m\u00e9dicas o estaban indispuestos. La jueza accedi\u00f3 a una petici\u00f3n del gobierno para desestimar las reclamaciones relacionadas con ellos porque no estaban presentes. Tambi\u00e9n acogi\u00f3 una solicitud para que no se permitiera el testimonio pericial del exalcalde de San Juan, H\u00e9ctor Luis Acevedo, como experto electoral y una solicitud para que la vista solo fuera del interdicto y no se combinara con la demanda regular.<\/p>\n<p>Vea:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/tribunales\/ahora\/top-stories\/20240924\/jueza-federal-rechaza-solicitud-urgente-sobre-registro-electoral-y-senala-vista\/\" id=\"link-df807f2c0d470240a032e1c2f8a7ab91\" target=\"_blank\">Jueza federal rechaza solicitud urgente sobre registro electoral y se\u00f1ala vista <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Interdicto federal sobre cierre prematuro del registro electoral queda sometido con el testimonio de un elector. El secretario de la Comisi\u00f3n Estatal de Elecciones (CEE), Rolando Cuevas Col\u00f3n, admiti\u00f3 bajo juramento que los electores tuvieron menos oportunidades para inscribirse durante este cuatrienio ante la reducci\u00f3n de juntas de inscripci\u00f3n permanente (JIP) y la demora en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":224551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9,13,2],"tags":[],"class_list":["post-209963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=209963"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209963\/revisions"}],"predecessor-version":[{"id":224552,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209963\/revisions\/224552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/224551"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=209963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=209963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=209963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}