{"id":209465,"date":"2024-09-13T05:45:00","date_gmt":"2024-09-13T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=209465"},"modified":"2025-07-11T12:35:49","modified_gmt":"2025-07-11T12:35:49","slug":"educacion-deja-puerta-abierta-a-renovacion-de-millonario-contrato-con-colegio-de-moca","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20240913\/educacion-deja-puerta-abierta-a-renovacion-de-millonario-contrato-con-colegio-de-moca\/","title":{"rendered":"Educaci\u00f3n deja puerta abierta a renovaci\u00f3n de millonario contrato con colegio de Moca"},"content":{"rendered":"<h3>Seg\u00fan se le confirm\u00f3 a NotiCel por parte de una portavoz de la secretaria asociada del programa de Educaci\u00f3n Especial, Noelia Cort\u00e9s.<\/h3>\n<p>El contrato vigente de LS Innovative Education Center Inc con el Departamento de Educaci\u00f3n (DE), por una cantidad ascendente de $10.5 millones, puede ser renovado en los pr\u00f3ximos d\u00edas.<\/p>\n<p>Una portavoz de la secretaria asociada del Programa de Educaci\u00f3n Especial, Noelia Cort\u00e9s, dijo a<strong id=\"strong-148eaebdddb7f343ed8924765bc97c50\"> NotiCel<\/strong> que evaluar\u00e1n la alternativa de renovar el contrato del proveedor tan pronto reciban su propuesta.<\/p>\n<p>En s\u00edntesis, sigue sobre la mesa la posibilidad de extender los servicios educativos que ofrece LS Innovative Education Center Inc, a pesar de que parte del componente del programa de Educaci\u00f3n Especial admiti\u00f3 en una vista p\u00fablica esta semana, de que existe disparidad en los costos por los proveedores que le brindan servicios.<\/p>\n<p>La propuesta del proveedor debe estar siendo enviada en los pr\u00f3ximos d\u00edas para su evaluaci\u00f3n, ya que el contrato vence el 30 de septiembre.<\/p>\n<p>El colegio, que est\u00e1 localizado en el municipio de Moca, tiene un contrato multimillonario desde el 1ro de octubre de 2023, para atender hasta 16 estudiantes que necesiten los servicios de educaci\u00f3n especial y que no puedan ser provistos por el DE.<\/p>\n<p>El contrato inicial ascend\u00eda a $4.8 millones. Luego,  para el pasado 10 de enero de 2024, se enmend\u00f3 el contrato para a\u00f1adirle $2 millones adicionales, para un monto de $6.8 millones. El pasado 16 de agosto de 2024, el contrato volvi\u00f3 a enmendarse para a\u00f1adirse $3.7millones, globalizando un contrato con el DE de $10. 5 millones.<\/p>\n<p>El contrato incluye servicios educativos, evaluaciones y terapia.<\/p>\n<p>Historia relacionada: <a href=\"\/en\/Educaci\u00f3n contrat\u00f3 por $10.5 millones un colegio en Moca para atender hasta 16 estudiantes\/\" id=\"link-48fd64b086857d67edf71498e899dab8\" target=\"_blank\">Educaci\u00f3n contrat\u00f3 por $10.5 millones un colegio en Moca para atender hasta 16 estudiantes<\/a><\/p>\n<p>En una vista p\u00fablica de la Comisi\u00f3n Especial para la Monitor\u00eda Legislativa del Programa de Educaci\u00f3n Especial, que preside la senadora Mar\u00eda de Lourdes Santiago Negr\u00f3n, se hab\u00eda solicitado evidencia de los proveedores de servicios al DE.<\/p>\n<p>El propio DE suministr\u00f3 el primer contrato de $4.8 millones con el colegio de Moca, del cual fue cuestionado por la senadora en la vista p\u00fablica.<\/p>\n<p>Sin embargo, <strong id=\"strong-166e167e1a728ee2e43944af0af3f1cc\">NotiCel <\/strong>encontr\u00f3 en la Oficina del Contralor las dos enmiendas antes mencionada, que asciende el contrato a una cantidad mayor.<\/p><div class=\"notic-content-middle\" id=\"notic-1276363470\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Este contrato mantiene servicios a siete estudiantes de Educaci\u00f3n Especial, pero a\u00f1ade nueve estudiantes adicionales como posibles prospectos a obtener los servicios.<\/p>\n<p>El costo de matr\u00edcula por ni\u00f1o y libros para los servicios \u00abone to one\u00bb (que es un solo estudiante con el maestro) es de $5,700. Mientras que la mensualidad por estudiante, incluyendo el servicio del asistente escolar, es de $20,285.<\/p>\n<p>El mismo costo es para estudiantes con servicios en el sal\u00f3n a tiempo completo.<\/p>\n<p>El contrato tambi\u00e9n se extendi\u00f3 para una vigencia hasta el 30 de septiembre.<\/p>\n<p>Esta situaci\u00f3n, seg\u00fan destap\u00f3 la senadora, es un claro ejemplo de la disparidad en los costos de los proveedores de servicios del DE.<\/p>\n<p>El contrato, incluyendo los enmendados, fue firmado el 1 de octubre de 2023 entre la secretaria de Educaci\u00f3n, Yanira Ra\u00edces Vega y el presidente del colegio, C\u00e9sar Augusto Vargas Vel\u00e1zquez.<\/p>\n<p>Como parte de la pol\u00edtica p\u00fablica, para los estudiantes con impedimentos se establece que el Gobierno debe garantizar, hasta donde los recursos del Estado lo permitan, una educaci\u00f3n p\u00fablica, gratuita y dise\u00f1ada a las necesidades individuales de las personas con impedimentos.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/opiniones\/20240829\/otra-vez-el-departamento-de-educacion\/\" id=\"link-f8a6f7dfff6f374af45d4e359043f809\" target=\"_blank\">Otra vez el Departamento de Educaci\u00f3n<\/a><\/p>\n<p>Si el Estado no cuenta con las instalaciones educativas que satisfagan las necesidades del menor, la ley federal IDEA permite que el Estado se responsabilice de cubrir los gastos incurridos por los padres en una instituci\u00f3n privada a la que tuvieron que recurrir en aras de proveerle los servicios.<\/p>\n<p>La contrataci\u00f3n con la escuela LS Innovative Education Center incluye los servicios de evaluaci\u00f3n e intervenci\u00f3n a los ni\u00f1os y j\u00f3venes de 3 a 21 a\u00f1os, seg\u00fan el Programa Educativo Individualizado (PEI). Los servicios de evaluaci\u00f3n e intervenci\u00f3n debe darse dentro del calendario escolar 2023-2024 incluyendo los s\u00e1bados.<\/p>\n<p>Tambi\u00e9n deben ofrecer asistencia a los estudiantes en el sal\u00f3n de clases, entregar informes, entre otras cl\u00e1usulas del contrato.<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan se le confirm\u00f3 a NotiCel por parte de una portavoz de la secretaria asociada del programa de Educaci\u00f3n Especial, Noelia Cort\u00e9s. El contrato vigente de LS Innovative Education Center Inc con el Departamento de Educaci\u00f3n (DE), por una cantidad ascendente de $10.5 millones, puede ser renovado en los pr\u00f3ximos d\u00edas. Una portavoz de la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":225588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-209465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=209465"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209465\/revisions"}],"predecessor-version":[{"id":225589,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/209465\/revisions\/225589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/225588"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=209465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=209465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=209465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}