{"id":20919,"date":"2012-05-25T00:00:00","date_gmt":"2012-05-25T04:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20120525\/kitwara-vuelve-a-una-de-sus-carreras-favoritas\/"},"modified":"2025-07-16T12:34:12","modified_gmt":"2025-07-16T12:34:12","slug":"kitwara-vuelve-a-una-de-sus-carreras-favoritas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120525\/kitwara-vuelve-a-una-de-sus-carreras-favoritas\/","title":{"rendered":"Kitwara vuelve a una de sus carreras favoritas"},"content":{"rendered":"<p>Hoy se anunci\u00f3 que el triple campe\u00f3n de la Carrera Internacional Abraham Rosa (CIAR), el keniano Sammy Kitwara, participar\u00e1 en la 27ma edici\u00f3n del evento que se llevar\u00e1 a cabo este domingo, 27 de mayo a las 5:00 p.m. en el barrio P\u00e1jaros de Toa Baja.<\/p>\n<p>De revalidar Kitwara, quien es el \u00fanico corredor internacional que ha dominado en m\u00e1s de una ocasi\u00f3n, estar\u00eda superando su propia marca con cuatro victorias. Venci\u00f3 en los a\u00f1os 2009, 2010 y 2011.<\/p>\n<p>&#8216;Kitwara est\u00e1 s\u00f3lido, ya se conoce la ruta y tendr\u00e1 una fuerte rivalidad con sus compatriotas Paul Lonyangata que viene de hacer un bueno tiempo (27:21 en 10,000m) durante la parada de Bruselas 2011 de la Liga Diamante, y Mathew Kisorio quien hizo el mejor tiempo en medio en marat\u00f3n del 2011 (58:46 en el 21K Rock and Roll de Filadelfia)&#8217;, opin\u00f3 Jos\u00e9 &#8216;Tito&#8217; Ortiz, presidente del Comit\u00e9 de Atletas Internacionales.<\/p>\n<p>El campe\u00f3n defensor tambi\u00e9n tendr\u00e1 que enfrentarse a m\u00e1s de una decena de corredores internacionales entre los que figuran el et\u00edope Daniel Abera, el marroqu\u00ed Rindouan Harroufi y el estadounidense, Ian Buner.<\/p>\n<p>De otro lado, por los locales el aibonite\u00f1o Luis Rivera, quien ha ganado numerosas carreras en Puerto Rico menos la CIAR, se propondr\u00e1 grabar su nombre en la historia del evento si el domingo sale airoso frente a su compueblano Cesar Lam, el pe\u00f1olano Jos\u00e9 Forn\u00e9s y el orocove\u00f1o Albert Col\u00f3n.<\/p>\n<p>&#8216;Me siento muy bien y tengo mucha confianza en m\u00ed, aunque nunca se puede asegurar cien por ciento nada&#8217;, puntualiz\u00f3 Rivera.<\/p><div class=\"notic-content-middle\" id=\"notic-2496470722\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>En la rama femenina la trujillana Mar\u00eda del Pilar D\u00edaz quien domin\u00f3 las ediciones de 2002, 2009 y 2011, regresa con las ansias de recuperar su trono entre las puertorrique\u00f1as. Si lo logra empatar\u00eda con cuatro victorias junto a Carmen Serrano como las damas que en m\u00e1s n\u00famero de ocasiones han ganado el evento. A D\u00edaz se sumar\u00e1 la bayamonesa Yolanda Mercado.<\/p>\n<p>En conferencia de prensa el presidente del evento Jos\u00e9 &#8216;Cano&#8217; Robles anunci\u00f3 que el homenajeado de la 27ma edici\u00f3n del evento ser\u00e1 el gimnasta toabaje\u00f1o y miembro de los Golden Boys, Angel Ramos.<\/p>\n<p>De otra parte, la CIAR premiar\u00e1 a los fondistas internacionales en la rama masculina, y tambi\u00e9n contar\u00e1 con premiaci\u00f3n en met\u00e1lico para atletas nacionales en ambas ramas esto con $1,200 para el primero, $800 para el segundo; $700 para el tercero; y $600 para el cuarto, y $500 para el quinto lugar. En la categor\u00eda de edades en ambos sexos la bonificaci\u00f3n es la siguiente: 1ero $100; 2do $60; 3ro $50 y 4to $30.<\/p>\n<p>Como parte de las actividades recreativas ma\u00f1ana amenizar\u00e1n en tarima desde las 9:00 p.m. Charlie Sierra y su Orquesta, y NG2. El s\u00e1bado, se llevar\u00e1 a cabo una bicicletada familiar a las 3:00 p.m. y en la noche a las 9:00 p.m. lucir\u00e1n en el escenario Manolito Rodr\u00edguez y su Orquesta. Luego Joseph Fonseca. El domingo habr\u00e1 una feria de salud con la unidad m\u00f3vil de Walgreens de 9:00 a.m. a 4:00 p.m. En la noche luego de la premiaci\u00f3n del 10K, deleitar\u00e1n a los presentes la Orquesta Cimarr\u00f3n desde las 9:00 p.m. y luego Luisito Carri\u00f3n.<\/p>\n<p>El donativo por las inscripciones de la CIAR es de $20. Las mismas estar\u00e1n disponibles en el Centro Recreativo del Barrio P\u00e1jaros de Toa Baja el s\u00e1bado, 26 de mayo de 9:30 a.m. a 6:00 p.m. o el domingo, 27 de 9:00 a.m. a 2:00 p.m. Los participantes deber\u00e1n llegar temprano, pues la carretera #2 y 863 ser\u00e1n cerradas a las 4:15 p.m. Para mayor informaci\u00f3n los interesados pueden comunicarse al tel\u00e9fono (787) 251-0459 de lunes a viernes de 9:00 a.m. a 2:00 p.m.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hoy se anunci\u00f3 que el triple campe\u00f3n de la Carrera Internacional Abraham Rosa (CIAR), el keniano Sammy Kitwara, participar\u00e1 en la 27ma edici\u00f3n del evento que se llevar\u00e1 a cabo este domingo, 27 de mayo a las 5:00 p.m. en el barrio P\u00e1jaros de Toa Baja. De revalidar Kitwara, quien es el \u00fanico corredor internacional [&hellip;]<\/p>","protected":false},"author":0,"featured_media":441646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-20919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=20919"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20919\/revisions"}],"predecessor-version":[{"id":441647,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20919\/revisions\/441647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/441646"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=20919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=20919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=20919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}