{"id":208840,"date":"2024-08-27T05:15:00","date_gmt":"2024-08-27T09:15:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=208840"},"modified":"2025-07-11T13:25:03","modified_gmt":"2025-07-11T13:25:03","slug":"jenniffer-gonzalez-dice-que-luma-energy-manipula-los-datos-de-querellas-emitidas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/elecciones\/elecciones-2024\/20240827\/jenniffer-gonzalez-dice-que-luma-energy-manipula-los-datos-de-querellas-emitidas\/","title":{"rendered":"Jenniffer Gonz\u00e1lez dice que LUMA Energy manipula los datos de querellas emitidas"},"content":{"rendered":"<h3>Tambi\u00e9n asegur\u00f3 que en los primeros 45 d\u00edas de su mandato como gobernadora, legislar\u00e1 para que se convierta en ley el zar de energ\u00eda.<\/h3>\n<p>La candidata a la gobernaci\u00f3n por el Partido Nuevo Progresista (PNP), Jenniffer Gonz\u00e1lez Col\u00f3n, asegur\u00f3 que LUMA Energy manipula la informaci\u00f3n de las querellas recibidas para su conveniencia.<\/p>\n<p>Dijo que est\u00e1 clara que los porcentajes que emite el operador privado sobre el restablecimiento del sistema despu\u00e9s de la tormenta tropical Ernesto no van acorde a las denuncias de las comunidades sin luz.<\/p>\n<p>\u00abPor lo que estoy viendo es claro que la cantidad de personas que se querellan versus las que no tienen luz, no guardan ning\u00fan tipo de relaci\u00f3n. As\u00ed que s\u00ed, yo creo que ellos est\u00e1n manipulando la data y lo podemos ver por ejemplo con las personas que no tienen electricidad\u00bb, expres\u00f3 Gonz\u00e1lez Col\u00f3n en conferencia de prensa.<\/p>\n<p>\u00abCuando me dicen que est\u00e1n a un 97% a 98% con luz y yo recibo llamadas de cada uno de los municipios con luz de 1,000 y 2,000 sin luz, cuando sumas, estamos hablando que hay m\u00e1s gente sin luz, que la que se est\u00e1 reportando\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Los alcaldes asociados tambi\u00e9n han estado denunciado la eliminaci\u00f3n de querellas los \u00faltimos d\u00edas por parte de LUMA.  Sin embargo, la empresa niega que esto est\u00e9 ocurriendo.<\/p>\n<p>Las expresiones de Gonz\u00e1lez las emiti\u00f3 luego de ser invitada a participar en la  pen\u00faltima reuni\u00f3n de matr\u00edcula de la Federaci\u00f3n de Alcaldes en el Hotel Sheraton del Centro de Convenciones.<\/p>\n<p>Asistieron un total de 28 alcaldes federados.<\/p>\n<p>La presidenta del PNP tambi\u00e9n asegur\u00f3 que gracias a la inacci\u00f3n del gobierno de turno, que es de su partido, har\u00e1 legislaci\u00f3n para crear en el ley el zar de energ\u00eda, en los primeros 45 d\u00edas de mandato, de ganar las pr\u00f3ximas elecciones generales.<\/p>\n<p>\u201cLas elecciones son en noviembre 5, el pueblo de Puerto Rico me da un mandato con C\u00e1mara y Senado, por eso necesito C\u00e1mara y Senado para que esto ocurra, y yo te aseguro que dentro de los primeros 45 d\u00edas del Gobierno, esa legislaci\u00f3n la vamos aprobar para poder meter mano desde el d\u00eda uno a esta fiscalizaci\u00f3n\u201d, contest\u00f3 a preguntas de<strong id=\"strong-8b57b855b046594cbd5b837a4eb51866\"> NotiCel<\/strong>.<\/p>\n<p>\u201cYo me voy a encargar de fiscalizarlos y si eso conlleva la cancelaci\u00f3n, pues se har\u00e1. Pero eso tambi\u00e9n conlleva cual es el plan b y cu\u00e1nto le va a costar al pueblo de Puerto Rico\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La presidenta del PNP asegur\u00f3 que, a diferencia del ente fiscalizador que tiene hoy La Fortaleza para evaluar a LUMA, su zar de energ\u00eda, tendr\u00e1 toda la autoridad en ley.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/elecciones\/20240821\/jenniffer-gonzalez-defiende-su-propuesta-del-zar-de-energia-y-asegura-que-no-esta-satisfecha-con-lum\/\" id=\"link-bb7b581ae516bcbd63be258c8fa102ca\" target=\"_blank\">Jenniffer Gonz\u00e1lez defiende su propuesta del zar de energ\u00eda y asegura que no est\u00e1 satisfecha con LUMA<\/a><\/p>\n<p>Tambi\u00e9n resalt\u00f3 que bajo la administraci\u00f3n de Pedro Pierluisi Urrutia, solo en una ocasi\u00f3n el Negociado de Energ\u00eda ha fiscalizado con mano dura al operador privado, cuando el pasado 9 de agosto emiti\u00f3 una notificaci\u00f3n a LUMA para que informara porque las m\u00e9tricas muestran que los servicios est\u00e1n peor que antes de su contrataci\u00f3n.<\/p>\n<p>\u201cYo quiero ver la contestaci\u00f3n de LUMA, es la primera vez y yo felicito al Negociado de Energ\u00eda que por primera vez tenemos una declaraci\u00f3n de esta magnitud en dos a\u00f1os\u2026\u201d, expres\u00f3.<\/p>\n<p>Tambi\u00e9n aprovech\u00f3 para resaltar el mal desempe\u00f1o de la Alianza P\u00fablico Privada (APP) en su papel de fiscalizador.<\/p>\n<p>\u201cHay que hacerle la pregunta al director de las Alianzas P\u00fablico Privadas ( sobre qu\u00e9 ha hecho para fiscalizar) que a mi juicio, no ha hecho el trabajo\u2026 quien no pueda defender el pueblo de Puerto Rico ahora, no lo va a defender el cuatrienio que viene\u2026\u201d, indic\u00f3.<\/p>\n<p>Adem\u00e1s de la aprobaci\u00f3n de un zar de energ\u00eda, Gonz\u00e1lez Col\u00f3n tambi\u00e9n vislumbra evaluar la alternativa de utilizar gas natural, las hidroel\u00e9ctricas y la energ\u00eda termal, entro otras.<\/p>\n<p>\u201cHablamos (en la reuni\u00f3n de matr\u00edcula) de diversificar nuestra cartera energ\u00e9tica a que utilicemos adem\u00e1s de las placas solares, el gas natural como opci\u00f3n, las plantas hidroel\u00e9ctricas, la energ\u00eda e\u00f3lica, entre otras\u2026 son cosas que vamos a evaluar para mantener un Puerto Rico encendido\u201d, sostuvo.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/la-calle\/20240820\/jenniffer-gonzalez-le-cierra-la-puerta-a-la-cancelacion-del-contrato-de-luma-y-promete-un-zar-de-en\/\" id=\"link-aefceef0017a37968dec6bd776e8e5f0\" target=\"_blank\">Jenniffer Gonz\u00e1lez le cierra la puerta a la cancelaci\u00f3n del contrato de LUMA y promete un \u201czar de energ\u00eda\u201d<\/a><\/p>\n<p>Tambi\u00e9n se inclin\u00f3 a la idea de hacer unas mejoras a dos plantas generatrices y la construcci\u00f3n de una nueva planta.<\/p>\n<p>\u201cLo que s\u00ed se puede hacer de manera inmediata es un upgrade a una de las plantas\u201d, apunt\u00f3.<\/p>\n<p>En cu\u00e1nto a la propuesta de integrar el gas natural, Gonz\u00e1lez Col\u00f3n dijo que es m\u00e1s limpia y econ\u00f3mica.<\/p>\n<p>\u201cLa que las plantas est\u00e1n quemando hoy, se pudieran convertir, porque tenemos que tomar en consideraci\u00f3n que tenemos unas plantas viejas\u2026estas se pudieran convertir y  bajar\u00edan los costos porque la quema de combustible cuesta mucho m\u00e1s y tambi\u00e9n tiene un efecto nefasto en los pulmones de la gente que vive cerca de ah\u00ed\u201d, destac\u00f3.<\/p>\n<p>Tambi\u00e9n dijo que no est\u00e1 de acuerdo a que se le apueste todo al tema de las placas solares, tras ser un sistema que no se puede utilizar en todas las infraestructuras. Por ejemplo: en los residenciales y condominios.<\/p>\n<p>Esta conversaci\u00f3n se dio tras la participaci\u00f3n de la comisionada residente en la reuni\u00f3n de matr\u00edcula de la federaci\u00f3n, quien fue invitada para tocar el tema del plan energ\u00e9tico.<\/p>\n<p>\u201cQue sepa el pueblo que este partido va a velar porque tengan luz y si eso conlleva levantar data y hacer la fiscalizaci\u00f3n, la vamos a tomar\u2026 Yo no le voy a bajar la guardia, no le voy a bajar el guante\u2026\u201d, coment\u00f3.<\/p>\n<p>Otros temas discutidos por parte de los alcaldes federados, es la urgencia para que se resuelva las denuncias a las supuesta desaparici\u00f3n de querellas, as\u00ed como alternativas para que se restablezcan los servicios de energ\u00eda los antes posible.<\/p>\n<p>Gabriel Hern\u00e1ndez, presidente de la matr\u00edcula federada, tambi\u00e9n le dijo a <strong id=\"strong-2c91905fc057930008d1d634d0076ffe\">NotiCel<\/strong> que no descartan las acciones legales contra el operador privado, pero m\u00e1s que nada solicitaban al Negociado de Manejo de Emergencias (NMEAD) que iniciara un proceso con el Gobierno para que se le desembolsara a los municipios dinero del Fondo de Emergencia Estatal, para sobrellevar la emergencia.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20240821\/secretaria-de-la-gobernacion-no-hace-falta-un-zar-ya-hay-ocho\/\" id=\"link-1808d61704ee3045030ce4399782b55c\" target=\"_blank\">Secretaria de la Gobernaci\u00f3n: \u201cNo hace falta un zar, ya hay ocho\u201d<\/a><\/p>\n<p>\u201cSe supone que una vez el gobernador declar\u00f3 estado de emergencia por el paso de la tormenta Ernesto, el Negociado de Emergencias y su comisionado, Nino Correa, estuviesen evaluando cada una de las formas 113, que es para que los municipios podamos acceder al fondo de emergencia\u201d, explic\u00f3.<\/p>\n<p>\u201cNecesitamos eficiencia en el Negociado y el comisionado tiene que darle prioridad a cada una de estas peticiones\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La Federaci\u00f3n de Alcaldes solicit\u00f3 que se realizara un desembolso de $500,000 como adelanto.<\/p>\n<p>\u201cCon eso pod\u00edamos resolver ciertas situaciones y no tendr\u00edamos que estar esperando que la burocracia del NMEAD provocara lo que est\u00e1 pasando en estos momentos\u2026\u201d, coment\u00f3 Hern\u00e1ndez.<\/p>\n<p>Los federados, tambi\u00e9n mostraron su apoyo a los alcaldes asociados tras contemplar un pleito legal contra LUMA y enviar una misiva al operador privado, a la Junta de Supervisi\u00f3n Fiscal (JSF) y al gobernador para que agilice los trabajos de restablecimiento del sistema energ\u00e9tico.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/politica\/gobierno\/ahora\/top-stories\/20240821\/georgie-navarro-defiende-la-propuesta-del-zar-de-jenniffer-gonzalez\/\" id=\"link-ebc90c9e60dd9676abce6a5b0b3adf89\" target=\"_blank\">Georgie Navarro defiende la propuesta del zar de Jenniffer Gonz\u00e1lez<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Tambi\u00e9n asegur\u00f3 que en los primeros 45 d\u00edas de su mandato como gobernadora, legislar\u00e1 para que se convierta en ley el zar de energ\u00eda. La candidata a la gobernaci\u00f3n por el Partido Nuevo Progresista (PNP), Jenniffer Gonz\u00e1lez Col\u00f3n, asegur\u00f3 que LUMA Energy manipula la informaci\u00f3n de las querellas recibidas para su conveniencia. Dijo que est\u00e1 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":226912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-208840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=208840"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208840\/revisions"}],"predecessor-version":[{"id":226913,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208840\/revisions\/226913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/226912"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=208840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=208840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=208840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}