{"id":208643,"date":"2024-08-21T13:59:00","date_gmt":"2024-08-21T17:59:00","guid":{"rendered":"https:\/\/www.noticel.com\/elecciones\/20240821\/jenniffer-gonzalez-defiende-su-propuesta-del-zar-de-energia-y-asegura-que-no-esta-satisfecha-con-lum\/"},"modified":"2025-07-11T13:41:33","modified_gmt":"2025-07-11T13:41:33","slug":"jenniffer-gonzalez-defiende-su-propuesta-del-zar-de-energia-y-asegura-que-no-esta-satisfecha-con-lum","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/elecciones\/elecciones-2024\/20240821\/jenniffer-gonzalez-defiende-su-propuesta-del-zar-de-energia-y-asegura-que-no-esta-satisfecha-con-lum\/","title":{"rendered":"Jenniffer Gonz\u00e1lez defiende su propuesta del zar de energ\u00eda y asegura que no est\u00e1 satisfecha con LUM"},"content":{"rendered":"<h3>\u201cHay que demostrar el incumplimiento con el contrato\u201d, dijo. \u201cNo he cambiado de postura. Me reafirmo en lo que he estado diciendo\u201d, insisti\u00f3 al se\u00f1alar que la determinaci\u00f3n sobre cancelar o mantener el contrato de LUMA se tomar\u00eda durante el segundo semestre del 2025.<\/h3>\n<p>La candidata a la gobernaci\u00f3n por el Partido Nuevo Progresista (PNP) Jenniffer Gonz\u00e1lez, defendi\u00f3 hoy al mediod\u00eda su propuesta de crear un nuevo ente fiscalizador de LUMA Energy, el llamado zar de energ\u00eda.<\/p>\n<p>Tambi\u00e9n dijo que no est\u00e1 satisfecha con el desempe\u00f1o de LUMA y que el llamado zar, entre otras cosas, levantar\u00eda el caso para la posible cancelaci\u00f3n del contrato.<\/p>\n<p>\u201cLa meta final no es buscar una cancelaci\u00f3n. La meta final es resolverle a la gente. Que la gente tenga luz\u2026 si ese incumplimiento se sigue dando, se sigue demostrando, se env\u00eda la carta y con la carta se mejora la situaci\u00f3n, pues que bueno y si no mejora, pedimos la cancelaci\u00f3n\u201d, dijo.<\/p>\n<p>Seg\u00fan Gonz\u00e1lez, la determinaci\u00f3n sobre cancelar o mantener el contrato se tomar\u00eda durante el segundo semestre del 2025.<\/p>\n<p>Igualmente anticip\u00f3 que impulsar\u00e1 una \u201cnueva pol\u00edtica energ\u00e9tica\u201d, pero no entr\u00f3 en detalles. Dej\u00f3 claro que eliminar\u00e1 la posici\u00f3n del Secretario Auxiliar de Asuntos Energ\u00e9ticos en La Fortaleza, figura que Gonz\u00e1lez describi\u00f3 como un ayudante del gobernador.<\/p>\n<p>\u201cEl que diga que he cambiado de postura no ha hecho su trabajo de revisar todas mis expresiones desde el d\u00eda uno\u201d, dijo Gonz\u00e1lez. \u201cPropongo hacer una fiscalizaci\u00f3n y hacer cumplir las m\u00e9tricas del contrato\u201d, dijo.<\/p>\n<p>La creaci\u00f3n del zar de energ\u00eda requerir\u00eda la aprobaci\u00f3n de legislaci\u00f3n a partir de enero, dijo el representante V\u00edctor Par\u00e9s Otero, quien acompa\u00f1\u00f3 a Gonz\u00e1lez en una conferencia de prensa hoy. Tambi\u00e9n estuvieron presentes el candidato a la comisar\u00eda residente penep\u00e9, William Villafa\u00f1e y el alcalde de Bayam\u00f3n, Ram\u00f3n Luis Rivera.<\/p>\n<p>La posici\u00f3n del zar de energ\u00eda ser\u00eda creada dentro de los primeros 60 d\u00edas del 2025. Gonz\u00e1lez nunca precis\u00f3 cu\u00e1nto dinero costar\u00eda este nuevo puesto y tampoco el reclutamiento de su equipo.<\/p>\n<p>Sobre la selecci\u00f3n del zar, la candidata insisti\u00f3 en que no est\u00e1 reclutando a nadie, pero tampoco explic\u00f3 el proceso para seleccionar esta figura, si fuera la gobernadora.<\/p>\n<p>A preguntas sobre c\u00f3mo ejecutar\u00eda el zar de energ\u00eda, Gonz\u00e1lez sostuvo que se le reconocer\u00edan poderes espec\u00edficos en la ley con que se cree y que se establecer\u00edan los requisitos de los otros miembros de su equipo. Indic\u00f3 que la Autoridad de las Alianzas P\u00fablico Privadas seguir\u00eda existiendo, pero ser\u00eda modificando para supuestamente darle \u201cgarras\u201d.<\/p><div class=\"notic-content-middle\" id=\"notic-1480217685\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Gonz\u00e1lez indic\u00f3 que la figura del zar tendr\u00eda la capacidad en ley de fiscalizar, con un equipo capaz de medir m\u00e9tricas de cumplimento como servicio al cliente, n\u00famero de apagones, las contrataciones \u201cy que las compa\u00f1\u00edas no se autocontraten con fondos p\u00fablicos, generando m\u00e1s ganancias para ellos\u201d.<\/p>\n<p>Gonz\u00e1lez insisti\u00f3 en que no se puede ser \u201cirresponsable\u201d al cancelar un contrato y que \u201cantes de cancelar un contrato, hay que hacerlos cumplir\u201d. Alert\u00f3 que para cancelar el contrato se tendr\u00eda que enmendar el Plan Fiscal, lo que requerir\u00eda la autorizaci\u00f3n de la Junta de Supervisi\u00f3n Fiscal.<\/p>\n<p>\u201cHay que demostrar el incumplimiento con el contrato\u201d, dijo. \u201cNo he cambiado de postura. Me reafirmo en lo que he estado diciendo\u2026 todas mis expresiones fueron antes de las primarias\u201d, insisti\u00f3.<\/p>\n<p>Indic\u00f3 que el llamado zar podr\u00eda, entre otras cosas, \u201crevisar toda la pol\u00edtica p\u00fablica energ\u00e9tica del pa\u00eds\u201d, lo que chocar\u00eda con el rol del Negociado de Energ\u00eda de Puerto Rico (NEPR). A preguntas de una periodista, Gonz\u00e1lez sostuvo que el NEPR tiene una independencia legal cuando se le pregunt\u00f3 si chocar\u00eda con la figura del zar, pero no explic\u00f3 entonces c\u00f3mo podr\u00edan coexistir. Sostuvo que no est\u00e1 evaluando en estos momentos el desempe\u00f1o del NEPR.<\/p>\n<p>De hecho, se\u00f1al\u00f3 que el NEPR no representa al pueblo de Puerto Rico, pero el zar de la energ\u00eda s\u00ed. Se\u00f1al\u00f3 que la figura que propone ser\u00eda un \u201cenlace\u201d en asuntos como permisos en diferentes entidades de gobierno y fiscalizar\u00eda, como el NEPR. Agreg\u00f3, sin entrar en detalles, que tendr\u00eda contacto con entidades federales y que tendr\u00eda m\u00e1s poder que el director de la Autoridad de las Alianzas P\u00fablico Privadas.<\/p>\n<p>\u201cHay que saber levantar el caso. Hay que probar que ha habido incumplimiento de la parte contratante y eso no se ha hecho\u201d, dijo Gonz\u00e1lez al rechazar el argumento de la secretaria de la gobernaci\u00f3n, Noelia Garc\u00eda, quien dijo hoy que ocho entidades del gobierno fiscalizan a la empresa.<\/p>\n<p>\u201cSi lo hubi\u00e9ramos hecho, no estar\u00edamos aqu\u00ed\u201d, dijo la comisionada residente.<\/p>\n<p>Gonz\u00e1lez que LUMA est\u00e1 \u201cpor la libre\u201d y que ninguna entidad del gobierno la fiscaliza. Reconoci\u00f3 que en agosto de 2022 dijo que favorec\u00eda la cancelaci\u00f3n del contrato de la empresa. De hecho, insisti\u00f3 en que el contrato sigue siendo \u201cleonino\u201d, como antes hab\u00eda se\u00f1alado, que se negoci\u00f3 mal y que es \u201cmalo para Puerto Rico\u201d.<\/p>\n<p>Sin embargo, reconoci\u00f3 que el contrato contiene cl\u00e1usulas de cancelaci\u00f3n que podr\u00edan costarle al pa\u00eds entre $300 millones y $600 millones si no se establecen las bases para la cancelaci\u00f3n.<\/p>\n<p>\u201cLos tendr\u00edan que pagar el pueblo de Puerto Rico\u201d, dijo.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cHay que demostrar el incumplimiento con el contrato\u201d, dijo. \u201cNo he cambiado de postura. Me reafirmo en lo que he estado diciendo\u201d, insisti\u00f3 al se\u00f1alar que la determinaci\u00f3n sobre cancelar o mantener el contrato de LUMA se tomar\u00eda durante el segundo semestre del 2025. La candidata a la gobernaci\u00f3n por el Partido Nuevo Progresista (PNP) [&hellip;]<\/p>","protected":false},"author":0,"featured_media":227339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-208643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=208643"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208643\/revisions"}],"predecessor-version":[{"id":227340,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208643\/revisions\/227340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/227339"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=208643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=208643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=208643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}