{"id":208117,"date":"2024-08-07T12:25:09","date_gmt":"2024-08-07T16:25:09","guid":{"rendered":"https:\/\/www.noticel.com\/vida\/20240807\/arzobispo-ofrecera-misa-dedicada-a-venezuela\/"},"modified":"2025-07-11T14:20:48","modified_gmt":"2025-07-11T14:20:48","slug":"arzobispo-ofrecera-misa-dedicada-a-venezuela","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20240807\/arzobispo-ofrecera-misa-dedicada-a-venezuela\/","title":{"rendered":"Arzobispo ofrecer\u00e1 misa dedicada a Venezuela"},"content":{"rendered":"<h3>El pa\u00eds est\u00e1 inmerso en una profunda crisis dese sus elecciones generales.<\/h3>\n<p>El Arzobispo de San Juan de Puerto Rico, Roberto Octavio Gonz\u00e1lez Nieves ofrecer\u00e1 la Misa este domingo en la Catedral de San Juan por lo que se ha descrito en un comunicado de prensa como \u201cuna resoluci\u00f3n justa y pac\u00edfica\u201d de la crisis en Venezuela.<\/p>\n<p>\u201cInvitamos especialmente a la comunidad venezolana a esta misa. Invitamos a todo el pueblo cat\u00f3lico y cristiano a unirse en oraci\u00f3n por nuestros hermanos y hermanas de toda la naci\u00f3n venezolana. Invitamos a orar en la oraci\u00f3n de los fieles de este domingo por esta petici\u00f3n: \u201cPara que la crisis en Venezuela se resuelva justa y pac\u00edficamente\u201d, expres\u00f3 el Arzobispo.<\/p>","protected":false},"excerpt":{"rendered":"<p>El pa\u00eds est\u00e1 inmerso en una profunda crisis dese sus elecciones generales. El Arzobispo de San Juan de Puerto Rico, Roberto Octavio Gonz\u00e1lez Nieves ofrecer\u00e1 la Misa este domingo en la Catedral de San Juan por lo que se ha descrito en un comunicado de prensa como \u201cuna resoluci\u00f3n justa y pac\u00edfica\u201d de la crisis [&hellip;]<\/p>","protected":false},"author":0,"featured_media":228442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-208117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=208117"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208117\/revisions"}],"predecessor-version":[{"id":228443,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/208117\/revisions\/228443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/228442"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=208117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=208117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=208117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}