{"id":207312,"date":"2024-07-15T07:22:21","date_gmt":"2024-07-15T11:22:21","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/la-calle\/policiacas\/20240715\/dos-personas-mueren-en-accidente-de-transito-en-hatillo\/"},"modified":"2025-07-11T15:11:28","modified_gmt":"2025-07-11T15:11:28","slug":"dos-personas-mueren-en-accidente-de-transito-en-hatillo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20240715\/dos-personas-mueren-en-accidente-de-transito-en-hatillo\/","title":{"rendered":"Dos personas mueren en accidente de tr\u00e1nsito en Hatillo"},"content":{"rendered":"<h3>El accidente se produjo a las 4:48 de la madrugada del domingo en el barrio Corcovado.<\/h3>\n<p><strong id=\"strong-332ef5ebd49c2476f521c53711ba7a7e\">HATILLO<\/strong> \u2014 Dos personas murieron en un accidente de tr\u00e1nsito a eso de las 4:48 de la madrugada del domingo, en la carretera PR-453 intersecci\u00f3n con la carretea PR-493, en el barrio Corcovada en Hatillo.<\/p>\n<p>Seg\u00fan el reporte de la Polic\u00eda, se recibi\u00f3 una llamada a trav\u00e9s del Sistema de Emergencias 9-1-1, sobre un accidente en el lugar<\/p>\n<p>Seg\u00fan el reporte de la Polic\u00eda,  el conductor que a\u00fan no ha sido identificado conduc\u00eda un veh\u00edculo Jeep, Cherokee de color blanco a exceso de velocidad. Perdi\u00f3 el control y dominio del volante e impact\u00f3 una barra de seguridad en mental a orillas de la carretera y un poste del alumbrado en aluminio. Como consecuencia, el veh\u00edculo se  incendi\u00e1ndose y se quem\u00f3 casi en su totalidad.  El conductor y el pasajero, fallecieron en el lugar.<\/p><div class=\"notic-content-middle\" id=\"notic-1217977183\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>El personal de Negociado de Bomberos y Emergencias M\u00e9dicas atendieron la situaci\u00f3n.<\/p>\n<p>La agente Iriana Hern\u00e1ndez Rom\u00e1n, adscrita a la divisi\u00f3n de Patrullas de Carreteras de Arecibo, y la fiscal Yolanda Pitino Acevedo investigan.<\/p>","protected":false},"excerpt":{"rendered":"<p>El accidente se produjo a las 4:48 de la madrugada del domingo en el barrio Corcovado. HATILLO \u2014 Dos personas murieron en un accidente de tr\u00e1nsito a eso de las 4:48 de la madrugada del domingo, en la carretera PR-453 intersecci\u00f3n con la carretea PR-493, en el barrio Corcovada en Hatillo. Seg\u00fan el reporte de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":230074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15,2],"tags":[],"class_list":["post-207312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/207312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=207312"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/207312\/revisions"}],"predecessor-version":[{"id":230075,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/207312\/revisions\/230075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/230074"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=207312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=207312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=207312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}