{"id":20729,"date":"2018-05-28T00:00:00","date_gmt":"2018-05-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/baloncesto\/bsn\/deportes\/20180528\/capitanes-empatan-en-el-primer-puesto\/"},"modified":"2025-07-16T12:52:43","modified_gmt":"2025-07-16T12:52:43","slug":"capitanes-empatan-en-el-primer-puesto","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20180528\/capitanes-empatan-en-el-primer-puesto\/","title":{"rendered":"Capitanes empatan en el primer puesto"},"content":{"rendered":"<p><i>Derrotaron a los Caciques de Humacao<\/i><\/p>\n<p>Los Capitanes de Arecibo alcanzaron la cima de la tabla de posiciones en el Baloncesto Superior Nacionla (BSN) al dominar anoche a los Caciques de Humacao con marcador de 91-87 en un partido celebrado en el Coliseo Manuel &#8216;Petaca&#8217; Iguina de Arecibo.<\/p>\n<p>Con el triunfo, los subcampeones empataron en la primera posici\u00f3n con los Vaqueros de Bayam\u00f3n, que ambos conjuntos juegan para 7-4.<\/p>\n<p>Los Capitanes dominaron la segunda mitad para vencer a los Caciques, que con la derrota bajan al quinto lugar con 5-5.<\/p>\n<p>Humacao control\u00f3 la primera mitad 48-36, contando con 16 puntos de Kyle Vi\u00f1ales y ocho de Melsahn Basabe.<\/p>\n<p>Los locales reaccionaron en el tercer parcial gracias a un avance de 14-0 a mediados del mismo para tomar el comando 56-53. En esos diez minutos, Arecibo domin\u00f3 el marcador 33-11 y acab\u00f3 arriba 69-59. Su mejor anotador en ese parcial fue Denis Clemente con siete.<\/p>\n<p>En el cuarto parcial, Humacao recuper\u00f3 su ritmo ofensivo y pudo tomar la ventaja nuevamente 80-78 gracias a un avance de 11-0 que incluy\u00f3 tres triples. El marcador se mantuvo cerrado y en el minuto final, un donqueo de Jeleel Akindele y dos tiros libres de Johwen Villegas sell\u00f3 el juego.<\/p>\n<p>Akindele termin\u00f3 con 22 puntos, mientras que Guillermo D\u00edaz y David Huertas anotaron 17 cada uno. En causa perdida, Vi\u00f1ales anot\u00f3 21 puntos y Brandon Costner 19. Alonzo Gee no pudo jugar por lesi\u00f3n.<\/p>\n<p>De otro lado, en el Coliseo Tom\u00e1s Dones de Fajardo, los Santeros de Aguada le propinaron una derrota a los Cariduros con pizarr\u00f3n de 82-76.<\/p>\n<p>Los Santeros llevan tres victorias al hilo y suben al sexto lugar con marca de 5-6. Fajardo baja al septimo lugar con marca de 4-6.<\/p>\n<p>Aguada no cont\u00f3 con T.J. Williams por una lesi\u00f3n muscular en su pierna y Chris Gast\u00f3n tiene una torcedura en el tobillo.<\/p><div class=\"notic-content-middle\" id=\"notic-2412173478\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El cuadro santero cont\u00f3 con cuatro jugadores en doble figura, siendo Gilberto Clavell el m\u00e1ximo con 19 puntos. El importado Josh Powell sum\u00f3 16 puntos y 13 rebotes, dominando la pintura ante las torres de Fajardo. El banco tambien fue clave anotando 22 puntos para balancear el ataque.<\/p>\n<p>La segunda mitad fue donde Aguada mejor\u00f3 su nivel ofensivo tirando de 8-4 en triples y aprovechando su ventaja en velocidad.<\/p>\n<p>Dos canastos al hilo de Powell colocaron el juego 71-65 a favor de los Santeros quedando 3:39 del partido. Aguada se mantuvo anotando, mientras que Fajardo se apoy\u00f3 del armador, Carlos Arroyo, que hizo 9 puntos al hilo para pegar a su equipo 75-74. El avance cariduro se qued\u00f3 ah\u00ed, mientras que Aguada asegur\u00f3 con anotaciones de Clavell, Han y Rodr\u00edguez.<\/p>\n<p>El Baloncesto Superior Nacional (BSN) anunci\u00f3 hoy que el p\u00edvot de los Vaqueros de Bayam\u00f3n, Devin Williams, fue seleccionado como el Jugador M\u00e1s Valioso de la tercera semana de acci\u00f3n que incluye los partidos del 19 al 25 de mayo.<\/p>\n<p>Williams fue clave en el despertar de los Vaqueros en la tercera semana al promediar 23.3 puntos y 10 rebotes en tres partidos. El p\u00edvot fue eficiente en la pintura anotando un 72.4% de sus intentos.<\/p>\n<p>Su mejor partido en la semana fue contra San Germ\u00e1n al conseguir 31 puntos y 11 rebotes en la victoria 112-91. En ese partido tir\u00f3 de 11-10 en canastos de dos puntos y de 13-11 del tiro libre.<\/p>\n<p>El p\u00edvot vaquero lidera tambien el quinteto ideal para esta semana que incluye a Carlos Arroyo (Fajardo), Kyle Vi\u00f1ales (Humacao), Mike Young (Ponce) y Reyshawn Terry (Quebradillas).<\/p>\n<p>Arroyo aument\u00f3 su producci\u00f3n en la tercera semana con media de 18.3 puntos y 6.3 asistencias en tres partidos para Fajardo.<\/p>\n<p>Por su parte, Vi\u00f1ales siempre ha estado en el quinteto ideal durante las primeras tres semanas de acci\u00f3n. En la tercera semana tuvo media de 20.75 puntos y anot\u00f3 un 52.6% de sus intentos de tres puntos.<\/p>\n<p>Young promedi\u00f3 23 puntos durante la semana con Ponce y Terry lider\u00f3 a Quebradillas con 18.6 puntos por juego.<\/p>\n<p>El dirigente de la semana lo fue Nelson Col\u00f3n, de los Vaqueros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Derrotaron a los Caciques de Humacao Los Capitanes de Arecibo alcanzaron la cima de la tabla de posiciones en el Baloncesto Superior Nacionla (BSN) al dominar anoche a los Caciques de Humacao con marcador de 91-87 en un partido celebrado en el Coliseo Manuel &#8216;Petaca&#8217; Iguina de Arecibo. Con el triunfo, los subcampeones empataron en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":443055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-20729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=20729"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20729\/revisions"}],"predecessor-version":[{"id":443058,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20729\/revisions\/443058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/443055"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=20729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=20729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=20729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}