{"id":20664,"date":"2015-08-31T00:00:00","date_gmt":"2015-08-31T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20150831\/sonido-boricua-se-cuela-en-proximo-disco-de-jesse-y-joy\/"},"modified":"2025-07-16T12:57:20","modified_gmt":"2025-07-16T12:57:20","slug":"sonido-boricua-se-cuela-en-proximo-disco-de-jesse-y-joy","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20150831\/sonido-boricua-se-cuela-en-proximo-disco-de-jesse-y-joy\/","title":{"rendered":"Sonido boricua se cuela en pr\u00f3ximo disco de Jesse y Joy"},"content":{"rendered":"<p>La cantante mexicana Joy, del d\u00fao de Jesse y Joy, dijo hoy lunes que para la pr\u00f3xima producci\u00f3n del grupo se aventuraron a expandir la fusi\u00f3n de ritmos con el prop\u00f3sito de impulsar sus propios l\u00edmites musicales.<\/p>\n<p>En entrevista telef\u00f3nica con Efe, Tirzah Joy Huerta Uecke, nombre verdadero de Joy, explic\u00f3 que aunque para todos sus pasados siempre han permanecido en su &#8216;zona de confort&#8217; en este nuevo \u00e1lbum exploraron &#8216;un poco m\u00e1s&#8217; en la fusi\u00f3n de ritmos, incluyendo algunos puertorrique\u00f1os.<\/p>\n<p>&#8216;Quisimos jugar con m\u00e1s elementos posibles y que la mezcla de cultura que llevamos trascienda esa esencia musical&#8217;, sostuvo la menor de ambos hermanos, de 29 a\u00f1os, de padre mexicano y madre estadounidense.<\/p>\n<p>Joy record\u00f3 que en su casa de peque\u00f1a escuchaba una mezcla de g\u00e9neros musicales bastante marcada, ya que su padre escuchaba al grupo estadounidense The Carpenters y su madre a los legendarios cantantes mexicanos Pedro Infante y Jos\u00e9 Jos\u00e9.<\/p>\n<p>&#8216;En el subconsciente fuimos almacenando estas melod\u00edas. Igualmente pas\u00f3 con la comida y todo eso tuvo un impacto en nuestra formaci\u00f3n&#8217;, dijo Joy, de cuyo disco mencion\u00f3 que se grab\u00f3 en Londres a principio de a\u00f1o y que se lanzar\u00e1 al mercado a finales del corriente.<\/p><div class=\"notic-content-middle\" id=\"notic-543546714\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Agreg\u00f3 que el cantautor puertorrique\u00f1o Tommy Torres colabor\u00f3 en la fase de producci\u00f3n del nuevo \u00e1lbum, el cual dijo que incluir\u00e1 &#8216;cositas&#8217; o sonidos aut\u00f3ctonos puertorrique\u00f1os como toques del cuatro boricua del cuatrista Christian Nieves.<\/p>\n<p>&#8216;Siempre hemos usado elementos de regiones anteriores, pero ahora vamos a sorprender m\u00e1s&#8217;, se\u00f1al\u00f3 Joy, quien hasta el momento ya promociona el primer sencillo de la nueva producci\u00f3n, &#8216;Ecos de amor&#8217;, trabajado por su hermano, Jesse, y el brit\u00e1nico Fraser T. Smith.<\/p>\n<p>Seg\u00fan un comunicado de prensa de la disquera Warner Music Latin, &#8216;Ecos De Amor&#8217;, interpretado por Joy, &#8216;habla sobre un amor eterno que traspasa cualquier l\u00edmite y que perdura para siempre&#8217;.<\/p>\n<p>Los otros tres discos de Jesse y Joy son &#8216;Esta es mi vida&#8217; (2007), &#8216;Electricidad&#8217; (2009) y &#8216;Con quien se queda el perro&#8217;. Este \u00faltimo gan\u00f3 cinco premios Grammy Latinos y fue nominado a un Grammy anglosaj\u00f3n en 2013.<\/p>","protected":false},"excerpt":{"rendered":"<p>La cantante mexicana Joy, del d\u00fao de Jesse y Joy, dijo hoy lunes que para la pr\u00f3xima producci\u00f3n del grupo se aventuraron a expandir la fusi\u00f3n de ritmos con el prop\u00f3sito de impulsar sus propios l\u00edmites musicales. En entrevista telef\u00f3nica con Efe, Tirzah Joy Huerta Uecke, nombre verdadero de Joy, explic\u00f3 que aunque para todos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":443409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-20664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=20664"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20664\/revisions"}],"predecessor-version":[{"id":443412,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20664\/revisions\/443412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/443409"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=20664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=20664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=20664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}