{"id":206249,"date":"2024-06-13T07:39:04","date_gmt":"2024-06-13T11:39:04","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/la-calle\/top-stories\/20240613\/luma-identifico-la-causa-del-apagon\/"},"modified":"2025-07-11T16:25:44","modified_gmt":"2025-07-11T16:25:44","slug":"luma-identifico-la-causa-del-apagon","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20240613\/luma-identifico-la-causa-del-apagon\/","title":{"rendered":"LUMA identific\u00f3 la causa del apag\u00f3n"},"content":{"rendered":"<h3>Anoche, el apag\u00f3n registrado dej\u00f3 a sobre 360 mil abonados sin el servicio de energ\u00eda.<\/h3>\n<p>La empresa LUMA Energy inform\u00f3 en la ma\u00f1ana del jueves que se identificaron las fallas en las dos l\u00edneas averiadas que provocaron el apag\u00f3n masivo.<\/p>\n<p>\u201cIdentificamos la causa de la interrupci\u00f3n como fallas en dos l\u00edneas de transmisi\u00f3n entre San Juan y Aguas Buenas. Nuestro equipo de aviaci\u00f3n y operaciones continuar\u00e1n patrullando la l\u00ednea en la ma\u00f1ana\u00bb, public\u00f3 la empresa en su cuenta de X.<\/p>\n<p>\u00abNuestro equipo en el Centro de Operaciones de Transmisi\u00f3n restableci\u00f3 a la mayor\u00eda de los clientes afectados en el \u00e1rea metropolitana y el noreste de la isla a las 2:36 a.m\u00bb, indic\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-355007075\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u00abActualmente, el 99% de nuestros clientes est\u00e1n en servicio y nuestros equipos contin\u00faan trabajando para restaurar el servicio a los clientes restantes. Es importante se\u00f1alar que Aibonito, Coamo y Santa Isabel no se vieron afectados\u201d, agreg\u00f3 el consorcio.<\/p>\n<p>Seg\u00fan el portal de la empresa, a las 7:30 de esta ma\u00f1ana hay 8,368 clientes sin servicio. Pero anoche, el apag\u00f3n registrado dej\u00f3 a sobre 360 mil abonados sin el servicio de energ\u00eda.<\/p>\n<p>Lea tambi\u00e9n: <a href=\"https:\/\/noticel.com\/en\/la-calle\/top-stories\/20240612\/tomo-un-mega-apagon-para-que-pierluisi-le-reclamara-publicamente-luma-y-a-genera\/\" id=\"link-1752c294a6fe170bc5490a422c00d3ad\" target=\"_blank\">Tras mega apag\u00f3n Pierluisi reclama p\u00fablicamente a LUMA y a Genera<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Anoche, el apag\u00f3n registrado dej\u00f3 a sobre 360 mil abonados sin el servicio de energ\u00eda. La empresa LUMA Energy inform\u00f3 en la ma\u00f1ana del jueves que se identificaron las fallas en las dos l\u00edneas averiadas que provocaron el apag\u00f3n masivo. \u201cIdentificamos la causa de la interrupci\u00f3n como fallas en dos l\u00edneas de transmisi\u00f3n entre San [&hellip;]<\/p>","protected":false},"author":0,"featured_media":232289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-206249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/206249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=206249"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/206249\/revisions"}],"predecessor-version":[{"id":232290,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/206249\/revisions\/232290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/232289"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=206249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=206249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=206249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}