{"id":205571,"date":"2024-05-25T06:00:00","date_gmt":"2024-05-25T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=205571"},"modified":"2025-07-11T17:16:27","modified_gmt":"2025-07-11T17:16:27","slug":"a-votar-por-el-boricua-en-la-competencia-de-google","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20240525\/a-votar-por-el-boricua-en-la-competencia-de-google\/","title":{"rendered":"\u00a1A votar por el boricua en la competencia de Google!"},"content":{"rendered":"<h3>Las votaciones est\u00e1n abiertas hasta el pr\u00f3ximo 4 de junio.<\/h3>\n<p>Un pueblo unido logra todo lo que se proponga y en esta ocasi\u00f3n, el joven puertorrique\u00f1o Luis Javier Corrada Fern\u00e1ndez necesita tu voto. Est\u00e1 participando en la competencia \u00abDoodle for Google\u00bb para lograr ganar una beca universitaria que lo llevar\u00e1 a cumplir su sue\u00f1o de estudiar ingenier\u00eda biom\u00e9dica.<\/p>\n<p>El joven actualmente cursa el duod\u00e9cimo grado en el Colegio Marista de Guaynabo.<\/p>\n<p>Los participantes ten\u00edan la encomienda de realizar un dibujo de Google bajo el concepto de: \u00abMis deseos para los pr\u00f3ximos 25 a\u00f1os\u00bb.<\/p>\n<p>El programa de \u00abDoodle for Google\u00bb, es una competencia que va desde kinder hasta duod\u00e9cimo grado y que se lleva a cabo anualmente.<\/p>\n<p>Para este 2024, se escogieron 55 finalistas y el boricua es parte de ellos.<\/p>\n<p>El dibujo que realiz\u00f3 Corrada Fern\u00e1ndez est\u00e1 inspirado en su amor por la ciencia, el medio ambiente y por supuesto, en la cultura de Puerto Rico.<\/p><div class=\"notic-content-middle\" id=\"notic-1906752225\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El estudiante que obtenga el primer lugar nacional, ganar\u00e1 una beca universitaria por $55,000 y el colegio al que pertenece recibir\u00e1 un paquete tecnol\u00f3gico en $50,000 aproximadamente.<\/p>\n<p>Las votaciones est\u00e1n abiertas hasta el pr\u00f3ximo 4 de junio.<\/p>\n<p>Si usted, con orgullo patrio, desea votar por Corrada Fern\u00e1ndez, solo debes entra a: Doodles For Googles Vote 2024.<\/p>\n<p>Buscas la categor\u00eda 10-12 y seleccionas a Puerto Rico.<\/p>\n<p>\u00a1A votar!<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/economia\/top-stories\/20240326\/joven-boricua-listo-para-ser-el-enlace-de-negocios-entre-china-y-puerto-rico\/\" id=\"link-bf4279012634fc0dd37579d25429ac8b\" target=\"_blank\">Joven boricua listo para ser el enlace de negocios entre China y Puerto Rico<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Las votaciones est\u00e1n abiertas hasta el pr\u00f3ximo 4 de junio. Un pueblo unido logra todo lo que se proponga y en esta ocasi\u00f3n, el joven puertorrique\u00f1o Luis Javier Corrada Fern\u00e1ndez necesita tu voto. Est\u00e1 participando en la competencia \u00abDoodle for Google\u00bb para lograr ganar una beca universitaria que lo llevar\u00e1 a cumplir su sue\u00f1o de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":233749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-205571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/205571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=205571"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/205571\/revisions"}],"predecessor-version":[{"id":233750,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/205571\/revisions\/233750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/233749"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=205571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=205571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=205571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}