{"id":204797,"date":"2024-05-01T12:19:16","date_gmt":"2024-05-01T16:19:16","guid":{"rendered":"https:\/\/www.noticel.com\/elecciones\/20240501\/la-oposicion-del-pnp-es-jenniffer-gonzalez-dice-edwin-mundo\/"},"modified":"2025-07-11T18:15:24","modified_gmt":"2025-07-11T18:15:24","slug":"la-oposicion-del-pnp-es-jenniffer-gonzalez-dice-edwin-mundo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/elecciones\/elecciones-2024\/20240501\/la-oposicion-del-pnp-es-jenniffer-gonzalez-dice-edwin-mundo\/","title":{"rendered":"\u201cLa oposici\u00f3n del PNP es Jenniffer Gonz\u00e1lez\u201d, dice Edwin Mundo"},"content":{"rendered":"<h3>\u201cEn los otros lados (partidos) no hay chavos ni oposici\u00f3n\u201d, dijo.<\/h3>\n<p>El director de campa\u00f1a de Pedro Pierluisi, Edwin Mundo, acus\u00f3 a Jenniffer Gonz\u00e1lez de ser la \u00fanica figura que representa la oposici\u00f3n al gobernador.<\/p>\n<p>La \u00fanica otra figura que ha sido vocal en contra de Pierluisi es el expenep\u00e9 Carlos D\u00edaz S\u00e1nchez, quien ahora quiere agenciarse un cargo p\u00fablico con el Partido Popular Democr\u00e1tico.<\/p>\n<p>\u201cEn los otros lados (partidos) no hay chavos ni oposici\u00f3n\u201d, dijo Mundo en una entrevista en WKAQ. \u201cLa oposici\u00f3n del PNP (Partido Nuevo Progresista) es Jenniffer Gonz\u00e1lez\u201d, agreg\u00f3 al tratar de indisponerla con el electorado que decidir\u00e1 la primaria: los novoprogresistas.<\/p>\n<p>Mundo sostuvo, por ejemplo, que ni el precandidato popular Jes\u00fas Manuel Ortiz ni el candidato a la gobernaci\u00f3n por la Alianza, Juan Dalmau Ram\u00edrez, hablan de Pierluisi.<\/p><div class=\"notic-content-middle\" id=\"notic-35427059\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Mundo, quien sostuvo que la gobernaci\u00f3n se decide el 2 de junio con la primaria del PNP, indic\u00f3 que esperan unos 400,000 electores.<\/p>\n<p>\u201cSi quieren continuar con el PNP el gobierno, la estabilidad, continuar con la seguridad y la viabilidad de la estadidad en Puerto Rico tienen que votar por Pedro Pierluisi\u201d, dijo.<\/p>\n<p>Sobre las posibilidades de la estadidad, Mundo recalc\u00f3 que no hay republicanos apoy\u00e1ndola, cuando ese es precisamente el partido de Gonz\u00e1lez. Ayer se anunci\u00f3 que el l\u00edder dem\u00f3crata en el Senado federal, Chuck Schumer, apoya el proyecto de estatus.<\/p>\n<p>\u201cLa estadidad est\u00e1 en buen camino\u201d, dijo Mundo al aludir al apoyo de Schumer. Sostuvo que los estadistas necesitan m\u00e1s de la mitad de los votos en el Senado para evitar t\u00e1cticas de filibusterismo.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cEn los otros lados (partidos) no hay chavos ni oposici\u00f3n\u201d, dijo. El director de campa\u00f1a de Pedro Pierluisi, Edwin Mundo, acus\u00f3 a Jenniffer Gonz\u00e1lez de ser la \u00fanica figura que representa la oposici\u00f3n al gobernador. La \u00fanica otra figura que ha sido vocal en contra de Pierluisi es el expenep\u00e9 Carlos D\u00edaz S\u00e1nchez, quien ahora [&hellip;]<\/p>","protected":false},"author":0,"featured_media":235439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-204797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2024"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/204797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=204797"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/204797\/revisions"}],"predecessor-version":[{"id":235440,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/204797\/revisions\/235440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/235439"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=204797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=204797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=204797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}