{"id":203796,"date":"2024-03-28T20:49:50","date_gmt":"2024-03-29T00:49:50","guid":{"rendered":"https:\/\/www.noticel.com\/beisbol\/deportes\/mlb\/top-stories\/20240328\/freeman-y-betts-producen-y-los-dodgers-ganan-en-el-debut-de-ohtani-en-los-angeles\/"},"modified":"2025-07-11T19:30:07","modified_gmt":"2025-07-11T19:30:07","slug":"freeman-y-betts-producen-y-los-dodgers-ganan-en-el-debut-de-ohtani-en-los-angeles","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20240328\/freeman-y-betts-producen-y-los-dodgers-ganan-en-el-debut-de-ohtani-en-los-angeles\/","title":{"rendered":"Freeman y Betts producen y los Dodgers ganan en el debut de Ohtani en Los \u00c1ngeles"},"content":{"rendered":"<h3>Mookie Betts peg\u00f3 un jonr\u00f3n y anot\u00f3 tres veces para que los Dodgers vencieran este jueves a los Cardenales de San Luis.<\/h3>\n<p>Freddie Freeman dispar\u00f3 un cuadrangular y remolc\u00f3 tres carreras y Mookie Betts peg\u00f3 un jonr\u00f3n y anot\u00f3 tres veces para que los Dodgers de Los \u00c1ngeles vencieran este jueves a los Cardenales de San Luis, en el debut del japon\u00e9s Shohei Ohtani en el Dodger Stadium.<\/p>\n<p>A Ohtani, que fue la principal firma de los Dodgers en el mercado de agentes libres y quien ha tenido que lidiar con el esc\u00e1ndalo de apuestas deportivas que lo ha rodeado, se le vio relajado y siendo ovacionado en sus apariciones al plato, para concluir este primer encuentro en Los \u00c1ngeles con dos imparables en tres turnos al bate y una carrera anotada.<\/p>\n<p>Los Dodgers tambi\u00e9n contaron con una gran actuaci\u00f3n monticular del derecho Tyler Glasnow (1-0), quien lanz\u00f3 seis entradas de apenas dos indiscutibles y una carrera, mientras ponch\u00f3 a cinco bateadores para conquistar su primera victoria de la temporada.<\/p>\n<p>El tridente de Jugadores M\u00e1s Valiosos de los Dodgers comenz\u00f3 a mostrar resultados desde la misma primera entrada, cuando, tras base por bolas a Betts, Ohtani conect\u00f3 un doble al jard\u00edn derecho, siendo atrapado entre segunda y tercera base y Freeman lo sigui\u00f3 con sencillo al jard\u00edn derecho para llevar a Betts al plato con la primera carrera del partido.<\/p>\n<p>Freeman anot\u00f3 la segunda de ese primer episodio por elevado de sacrificio de Max Muncy.<\/p>\n<p>El poderoso ataque de Los \u00c1ngeles volvi\u00f3 a hacerse presente en el tercer cap\u00edtulo, cuando Betts conect\u00f3 un batazo que se fue por encima de la pared del bosque izquierdo sin corredores en las bases ante Miles Mikolas.<\/p>\n<p>Tras el jonr\u00f3n de Betts, Ohtani recibi\u00f3 una base por bolas y, con \u00e9l en la inicial, Freeman deposit\u00f3 la pelota en las grader\u00edas del jard\u00edn derecho, para sumar dos carreras m\u00e1s para el conjunto de Los \u00c1ngeles.<\/p><div class=\"notic-content-middle\" id=\"notic-3338169404\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La respuesta de los Cardenales lleg\u00f3 en el cuarto acto, cuando Paul Goldschmidt, quien fue el \u00fanico en pegar de hit en el partido, dispar\u00f3 un vuelacercas solitario, para producir la \u00fanica carrera de los de San Luis.<\/p>\n<p>El jonr\u00f3n de Goldschmidt fren\u00f3 una cadena de ocho bateadores retirados de manera consecutiva por parte de Clasnow.<\/p>\n<p>En la parte baja de la sexta entrada James Outman impuls\u00f3 la sexta carrera de los Dodgers, al disparar un indiscutible al jard\u00edn derecho que permiti\u00f3 que el dominicano Teoscar Hern\u00e1ndez anotara desde la intermedia.<\/p>\n<p>Los Dodgers volvieron a pisar la registradora en el s\u00e9ptimo inning por imparable de Muncy al prado derecho, para impulsar a Betts desde la antesala.<\/p>\n<p>Mikolas (0-1) no tuvo secretos ante los bates de los Dodgers y abandon\u00f3 el mont\u00edculo tras 4.1 entradas en las que le anotaron cinco carreras, cargando con la derrota por los Cardenales.<\/p>\n<p>Por los Dodgers, el dominicano Hern\u00e1ndez anot\u00f3 una carrera, mientras el venezolano Miguel Rojas y el puertorrique\u00f1o Kik\u00e9 Hern\u00e1ndez fallaron en un turno al bate.<\/p>\n<p>Por los Cardenales, el venezolano Willson Contreras fall\u00f3 en tres apariciones al plato.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mookie Betts peg\u00f3 un jonr\u00f3n y anot\u00f3 tres veces para que los Dodgers vencieran este jueves a los Cardenales de San Luis. Freddie Freeman dispar\u00f3 un cuadrangular y remolc\u00f3 tres carreras y Mookie Betts peg\u00f3 un jonr\u00f3n y anot\u00f3 tres veces para que los Dodgers de Los \u00c1ngeles vencieran este jueves a los Cardenales de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":237625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[32,31],"tags":[],"class_list":["post-203796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=203796"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203796\/revisions"}],"predecessor-version":[{"id":237626,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203796\/revisions\/237626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/237625"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=203796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=203796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=203796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}