{"id":203722,"date":"2024-03-26T19:39:52","date_gmt":"2024-03-26T23:39:52","guid":{"rendered":"https:\/\/www.noticel.com\/noticel-fact-check-la-verdad\/20240326\/elecciones-2024-vuelan-las-mentiras-los-datos-incorrectos-y-las-exageraciones\/"},"modified":"2025-11-27T01:36:34","modified_gmt":"2025-11-27T05:36:34","slug":"elecciones-2024-vuelan-las-mentiras-los-datos-incorrectos-y-las-exageraciones","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/noticel-factcheck\/20240326\/elecciones-2024-vuelan-las-mentiras-los-datos-incorrectos-y-las-exageraciones\/","title":{"rendered":"Elecciones 2024: Vuelan las mentiras, los datos incorrectos y las exageraciones"},"content":{"rendered":"<h3>La Verdad como es\u2026 NotiCel repasa los recientes comentarios de los candidatos presidenciales.<\/h3>\n<p><strong id=\"strong-095896ff5e8f18aa8cb78adc84e314d7\">Joe Biden: Hemos logrado \u201cla tasa de desempleo m\u00e1s baja para los latinos en mucho, mucho tiempo\u201d. FALSO<\/strong><\/p>\n<p>Est\u00e1 expresi\u00f3n del presidente Biden es falsa desde varios puntos de vista. Primeramente, los datos del U.S. Bureau of Labor Statistics, entidad que brinda las tasas oficiales del desempleo en los Estados Unidos, y que en efecto responde a la administraci\u00f3n Biden, desmienten totalmente la aseveraci\u00f3n del Presidente. El presidente Biden posiblemente intentaba hacer referencia al hecho que en septiembre del a\u00f1o 2022 su administraci\u00f3n logr\u00f3 una reducci\u00f3n en la tasa de desempleo de los latinos a 3.9%. Esa no es la tasa \u201cm\u00e1s baja para los latinos en mucho, mucho tiempo\u201d. De hecho, tres a\u00f1os antes, en septiembre del 2019, el U.S. Bureau of Labor Statistics report\u00f3 igualmente una tasa de 3.9%.<\/p>\n<p>Seg\u00fan datos m\u00e1s recientes del U.S. Bureau of Labor Statistics, se establece que el desempleo en la comunidad latina fue de 5.01% en febrero del 2024, y se ha mantenido en ese nivel desde noviembre del 2023. Estas tasas son fluctuantes, por lo que se debe destacar que en el 2023 el n\u00famero se hab\u00eda reducido levemente, aunque se ha mantenido estable en comparaci\u00f3n con el mes de febrero de 2023 que presento una tasa de 5.4%.<\/p>\n<p>Por tanto, las expresiones del presidente Biden son falsas ya que el nivel de desempleo de 3.9% no fue el bajo para los latinos en \u201cmucho, mucho tiempo\u201d, sino que fue similar al de tres a\u00f1os antes. Por otro lado, el tratar de impresionar a su audiencia con datos del a\u00f1o 2022, cuando la tasa actual del desempleo a aumentado significativamente pudiera interpretarse como enga\u00f1oso.<\/p>\n<p>_______________________<\/p>\n<p><strong id=\"strong-0c650f2ed58ebf7dadb1bfde38efffe5\">Donald Trump: \u201clos oficiales de en la bolsa de valores de Nueva York quieren desesperadamente que intercambie los valores de mi compa\u00f1\u00eda a trav\u00e9s de ellos\u201d. FALSO<\/strong><\/p>\n<p>El d\u00eda de ayer, Donald Trump, relat\u00f3 a la prensa su reciente experiencia con oficiales del New York Stock Exchange (NYSE) y la alegada insistencia en que su empresa Trump Media &amp; Technology Group hiciera disponible sus acciones a trav\u00e9s del NYSE.  Trump dijo haber hablado recientemente con \u201cla persona de mayor jerarqu\u00eda\u201d en el NYSE y le confirmaron que \u201clos oficiales de en la bolsa de valores de Nueva York quieren desesperadamente que intercambie los valores de mi compa\u00f1\u00eda a trav\u00e9s de ellos\u201d. Seg\u00fan Trump, su respuesta fue en la negativa \u201cporque los empresarios son tratados demasiado mal en Nueva York\u00bb y \u00abno quieren ser atacados por un maleante como el horrible fiscal general que tienen en Nueva York\u00bb. Trump se refiri\u00f3 as\u00ed a la fiscal general de New York Letitia James y a Alvin Bragg fiscal del distrito de Manhattan.<\/p>\n<p>El expresidente dijo tambi\u00e9n que hab\u00eda sostenido una conversaci\u00f3n con el jefe a cargo del NYSE, y asegur\u00f3 que \u00abla gente de la bolsa de valores est\u00e1 muy molesta\u00bb porque no lograron participar de la transacci\u00f3n de su empresa. Trump abund\u00f3 al afirmar que, \u201c\u00c9l me dijo que est\u00e1n perdiendo negocios por culpa de [el gobierno de] Nueva York, porque la gente no quiere estar en Nueva York, y no quiere ir a la Bolsa de Valores de Nueva York\u201d.<\/p>\n<p>Estos comentarios tienen varios elementos falsos:<\/p>\n<p>&#8211;\tTrump alega que no desea que sus valores se coticen en Nueva York, por lo que, en vez de utilizar el New York Stock Exchange, utiliz\u00f3 a NASDAQ.  Sin embargo, es v\u00e1lido establecer que el Nasdaq, tambi\u00e9n tiene su sede tambi\u00e9n en Nueva York, ir\u00f3nicamente a solo pasos del NYSE. Por tanto, el fiscal general y de distrito, las leyes, las entidades reguladoras, y los Tribunales que se habr\u00edan aplicado a la empresa si cotizara en la NYSE, se aplicar\u00e1n a la empresa de Trump cuando cotice en el Nasdaq.<\/p>\n<p>&#8211;\tEs relevante se\u00f1alar que \u201cla persona de mayor jerarqu\u00eda\u201d en las operaciones de NYSE es una mujer de nombre Lynn Martin, al igual que en la Junta de Directores que es presidida por otra mujer de nombre Sharon Bowen. Trump insisti\u00f3 que hab\u00eda hablado con la persona de mayor jerarqu\u00eda y lo describi\u00f3 como un hombre. Esto pudo haber sido una simple equivocaci\u00f3n o una mentira. A pesar de esto, los oficiales de NYSE han negado haber conversado con Trump, pero est\u00e1n abiertos a cotizar las acciones de su empresa si as\u00ed lo deseara.<\/p>\n<p>________________________<\/p>\n<p><strong id=\"strong-068c0e46d369e7d02b8579fcaf9bd6a8\">Nota Aclaratoria<\/strong><\/p>\n<p>NotiCel pudo revisar las expresiones p\u00fablicas de Biden y Trump, la data estad\u00edstica del desempleo que p\u00fablica el U.S. Bureau of Labor Statistics, as\u00ed como la reglamentaria del NYSE y NASDAQ. Trump es el propietario mayoritario de Truth Social cuya empresa opera bajo en nombre Trump Media &amp; Technology Group.  La empresa tom\u00f3 la determinaci\u00f3n de convertir la empresa en una p\u00fablica y vender sus acciones a trav\u00e9s del mercado de valores.  Con esta estrategia comercial, Trump debe poder duplicar su patrimonio neto, lo que ya le ha ganado ser incluido en la lista de Bloomberg de las 500 personas m\u00e1s ricas del mundo.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Verdad como es\u2026 NotiCel repasa los recientes comentarios de los candidatos presidenciales. Joe Biden: Hemos logrado \u201cla tasa de desempleo m\u00e1s baja para los latinos en mucho, mucho tiempo\u201d. FALSO Est\u00e1 expresi\u00f3n del presidente Biden es falsa desde varios puntos de vista. Primeramente, los datos del U.S. Bureau of Labor Statistics, entidad que brinda [&hellip;]<\/p>","protected":false},"author":100,"featured_media":237776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-203722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticel-factcheck"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=203722"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203722\/revisions"}],"predecessor-version":[{"id":237777,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203722\/revisions\/237777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/237776"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=203722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=203722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=203722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}