{"id":203491,"date":"2024-03-19T05:45:00","date_gmt":"2024-03-19T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=203491"},"modified":"2025-07-11T19:51:28","modified_gmt":"2025-07-11T19:51:28","slug":"le-dan-paso-a-medida-para-que-se-otorgue-licencia-de-duelo-gestacional","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20240319\/le-dan-paso-a-medida-para-que-se-otorgue-licencia-de-duelo-gestacional\/","title":{"rendered":"Le dan paso a medida para que se otorgue licencia de duelo gestacional"},"content":{"rendered":"<h3>Con esta medida, la persona que sufra un aborto puede reclamar hasta un m\u00e1ximo de cuatro semanas de licencia de maternidad y dos semanas adicionales de licencia de duelo gestacional.<\/h3>\n<p>El Senado aprob\u00f3 por v\u00eda de descargue una medida que enmienda la Ley para la Administraci\u00f3n y Transformaci\u00f3n de los Recursos Humanos  y la Ley de Cumplimiento con el Plan Fiscal  para conceder una licencia de duelo gestacional de dos semanas a toda persona empleada que haya sufrido un aborto. Esta licencia tambi\u00e9n se le otorgar\u00eda al c\u00f3nyuge o pareja consensual.<\/p>\n<p>El Proyecto del Senado 489 en su reconsideraci\u00f3n, es de la autor\u00eda de las senadoras Migdalia Gonz\u00e1lez Arroyo, Gretchen Hau y Elizabeth Rosa V\u00e9lez y no tuvo discusi\u00f3n en el hemiciclo.<\/p>\n<p>La medida hab\u00eda sido aprobada y enviada al gobernador Pedro Pielruisi Urrutia en agosto pasado pero luego se solicit\u00f3 la devoluci\u00f3n de la medida.<\/p>\n<p>La Fortaleza la devolvi\u00f3 el 31 de agosto. Volvi\u00f3 a enviarse el 2 de noviembre al gobernador, pero la misma semana se aprueba en la Asamblea Legislativa la solicitud para que sea nuevamente devuelta.<\/p>\n<p>De acuerdo a la exposici\u00f3n de motivos, la pareja que sufre un aborto, tambi\u00e9n vive un duelo gestacional y seg\u00fan la psic\u00f3loga espa\u00f1ola Ainhoa Plata, \u201cel duelo gestacional en muchas ocasiones es ignorado, minimizado y desautorizado\u201d.<\/p>\n<p>En Puerto Rico se ha reconocido el impacto psicol\u00f3gico que tiene la p\u00e9rdida de un embarazo mediante la pol\u00edtica p\u00fablica establecida en la Ley 184-2016, que ordena la elaboraci\u00f3n e implementaci\u00f3n de un protocolo uniforme en las instituciones hospitalarias y de salud para el manejo de la p\u00e9rdida de un embarazo en etapa temprana y, de una muerte fetal o neonatal.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/20240315\/buscan-que-clinicas-de-aborto-tengan-que-notificar-procedimientos-a-menores\/\" id=\"link-f48b533b52bb89db8b0913613e1fbc91\" target=\"_blank\">Buscan que cl\u00ednicas de aborto tengan que notificar procedimientos a menores<\/a><\/p>\n<p>M\u00faltiples estudios han presentado que en las primeras semanas despu\u00e9s de una p\u00e9rdida, el 36% de las mujeres presentan s\u00edntomas de moderados a severos de depresi\u00f3n que disminuyen gradualmente, pero todav\u00eda pueden estar elevados a los 6 meses.<\/p>\n<p>Tambi\u00e9n indican en la medida que la ansiedad puede ser un factor importante en la p\u00e9rdida de un embarazo en etapa temprana y de la muerte fetal o neonatal.<\/p>\n<p>\u201cUn n\u00famero significativo de mujeres reportan niveles elevados de ansiedad hasta 6 meses despu\u00e9s de aborto involuntario, y tambi\u00e9n pueden estar en mayor riesgo de sufrir s\u00edntomas obsesivos-compulsivos y de trastorno de estr\u00e9s postraum\u00e1tico\u201d, reza la medida.<\/p>\n<p>Con esta medida, la persona que sufra un aborto puede reclamar hasta un m\u00e1ximo de cuatro semanas de licencia de maternidad y dos semanas adicionales de licencia de duelo gestacional.<\/p>\n<p>Sin embargo, para aplicar a las cuatro semanas, de licencia de maternidad, el aborto debe ser de tal naturaleza que le produzca los mismos efectos fisiol\u00f3gicos que regularmente surgen como consecuencia del parto, de acuerdo a la certificaci\u00f3n del m\u00e9dico que la atiende durante el aborto.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/salud\/top-stories\/20230516\/50-casos-de-abortos-de-ninas-de-15-anos-o-menos-en-dos-anos\/\" id=\"link-2cce49d48a74ea7830f856ae8e2d2030\" target=\"_blank\">50 casos de abortos de ni\u00f1as de 15 a\u00f1os o menos en dos a\u00f1os<\/a><\/p><div class=\"notic-content-middle\" id=\"notic-1908298693\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Lo anterior no aplicar\u00e1 a las dos semanas de la licencia de duelo gestacional, en cuyo caso se conceder\u00e1n con la mera notificaci\u00f3n al patrono del documento m\u00e9dico que acredite la p\u00e9rdida del embarazo.<\/p>\n<p>La licencia de duelo gestacional tambi\u00e9n ser\u00e1 concedida a la persona empleada que se encuentre en un proceso de maternidad subrogada en caso de que se haya perdido el embarazo.<\/p>\n<p>Este beneficio se conceder\u00e1 tanto a la persona empleada con v\u00ednculo gen\u00e9tico  como aquella persona empleada que act\u00fae como gestante.<\/p>\n<p>Tambi\u00e9n, la persona empleada cuya c\u00f3nyuge o pareja consensual haya sufrido un aborto ,ser\u00e1 acreedor de una licencia de duelo gestacional de dos semanas, las cuales se conceder\u00e1n con la mera notificaci\u00f3n al patrono del documento m\u00e9dico que acredite tal hecho.<\/p>\n<p>La licencia de duelo gestacional tambi\u00e9n ser\u00e1 concedida a la persona empleada cuya c\u00f3nyuge o pareja consensual gestante haya perdido el embarazo.<\/p>\n<p>Las dos semanas de la licencia de duelo gestacional no tienen que ser concurrentes, pero s\u00ed deben ser ejercitadas en un periodo de seis meses, luego de las cuatro semanas de licencia de maternidad.<\/p>\n<p>Ning\u00fan patrono podr\u00e1 tomar represalias contra la persona empleada que utilice las referidas licencias. Los patronos tienen que proveer un taller de sensibilizaci\u00f3n al personal de Recursos Humanos de, al menos, dos horas al a\u00f1o.<\/p>\n<p>Estas enmiendas entrar\u00edan en vigor 30 d\u00edas despu\u00e9s de su aprobaci\u00f3n.<\/p>\n<p>El P de la S 489 obtuvo 18 votos a favor y seis en contra por parte de los senadores Gregorio Mat\u00edas Rosario, Carmelo R\u00edos Santiago, Keren Riquelme Cabrera, Thomas Rivera Schatz, Migdalia Padilla Alvelo y Juan Oscar Morales.<\/p>\n<p>Los senadores Nitza Mor\u00e1n Trinidad, Marissa Jim\u00e9nez Santoni y Wanda Soto Tolentino se abstuvieron.<\/p>\n<p>El Senado reces\u00f3 sus trabajos hasta la primera semana de abril.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20230525\/justicia-confirma-investigacion-a-clinicas-de-aborto\/\" id=\"link-776c5dbc4a25d5736615b84c30f13d3d\" target=\"_blank\">Justicia confirma investigaci\u00f3n a cl\u00ednicas de aborto<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Con esta medida, la persona que sufra un aborto puede reclamar hasta un m\u00e1ximo de cuatro semanas de licencia de maternidad y dos semanas adicionales de licencia de duelo gestacional. El Senado aprob\u00f3 por v\u00eda de descargue una medida que enmienda la Ley para la Administraci\u00f3n y Transformaci\u00f3n de los Recursos Humanos y la Ley [&hellip;]<\/p>","protected":false},"author":0,"featured_media":238268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-203491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=203491"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203491\/revisions"}],"predecessor-version":[{"id":238269,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/203491\/revisions\/238269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/238268"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=203491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=203491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=203491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}