{"id":20043,"date":"2020-03-03T13:22:00","date_gmt":"2020-03-03T17:22:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20200303\/en-imagenes-la-destruccion-dejada-por-tornados-en-tenessee\/"},"modified":"2025-07-16T14:20:31","modified_gmt":"2025-07-16T14:20:31","slug":"en-imagenes-la-destruccion-dejada-por-tornados-en-tenessee","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20200303\/en-imagenes-la-destruccion-dejada-por-tornados-en-tenessee\/","title":{"rendered":"En im\u00e1genes: la destrucci\u00f3n dejada por tornados en Tenessee"},"content":{"rendered":"<p>El numero de personas que fallecieron como consecuencia del paso de varios tornados que tocaron tierra esta pasada madrugada en el estado sure\u00f1o de Tenessee (EE.UU.) ascienden a por lo menos 19, informaron autoridades estatales, citadas por medios locales.<\/p>\n<p>La Agencia de Manejo de Emergencias de Tennessee (TEMA) dio cuenta de la nueva cifra de fallecidos en un actualizaci\u00f3n de la situaci\u00f3n en este estado sure\u00f1o, donde se ha declarado el estado de emergencia tras la tormenta que ha causado severos da\u00f1os en el centro de Nashville, capital del estado, y otras localidades cercanas.<\/p>\n<p>La agencia estatal actualiz\u00f3 la cifra de v\u00edctimas mortales luego de que los rescatistas encontraran varios cuerpos entre los escombros de edificios y viviendas que derrumbaron los tornados que azotaron el estado.<\/p><div class=\"notic-content-middle\" id=\"notic-1546302254\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Al menos 40 estructuras colapsaron en el \u00e1rea de Nashville, donde uno de los tornados sorprendi\u00f3 en horas de la madrugada, seg\u00fan confirm\u00f3 la Polic\u00eda Metropolitana de la ciudad en su cuenta de Twitter.<\/p>\n<p>Del total de fallecidos reportados hasta el momento, 14 se han registrado en el Condado de Putnam, al este de Nashville, a causa de los tornados y las tormentas que han ocasionado por lo menos una veintena de heridos, adem\u00e1s de viviendas y estructuras severamente da\u00f1adas, seg\u00fan ha informado la portavoz de TEMA Maggie Hannan.<\/p>\n<p>La Oficina del Alguacil del condado de Putnam indic\u00f3 que la tormenta azot\u00f3 especialmente fuerte la zona entre las ciudades de Cookeville y Baxter, donde varias viviendas resultaron destruidas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El numero de personas que fallecieron como consecuencia del paso de varios tornados que tocaron tierra esta pasada madrugada en el estado sure\u00f1o de Tenessee (EE.UU.) ascienden a por lo menos 19, informaron autoridades estatales, citadas por medios locales. La Agencia de Manejo de Emergencias de Tennessee (TEMA) dio cuenta de la nueva cifra de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":448968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-20043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=20043"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20043\/revisions"}],"predecessor-version":[{"id":448975,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/20043\/revisions\/448975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/448968"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=20043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=20043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=20043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}