{"id":200328,"date":"2023-12-06T09:17:33","date_gmt":"2023-12-06T13:17:33","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20231206\/listo-el-plan-de-accion-de-venezuela-sobre-zona-disputada-con-guyana\/"},"modified":"2025-07-11T23:39:06","modified_gmt":"2025-07-11T23:39:06","slug":"listo-el-plan-de-accion-de-venezuela-sobre-zona-disputada-con-guyana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20231206\/listo-el-plan-de-accion-de-venezuela-sobre-zona-disputada-con-guyana\/","title":{"rendered":"Listo el plan de acci\u00f3n de Venezuela sobre zona disputada con Guyana"},"content":{"rendered":"<h3>El plan del presidente Maduro no contempla una incursi\u00f3n inmediata en la zona del Esequibo.<\/h3>\n<p>Caracas.- El presidente de Venezuela, Nicol\u00e1s Maduro, lanz\u00f3 este martes un plan de acci\u00f3n sobre el territorio en disputa con Guyana, que incluye el otorgamiento de licencias para la explotaci\u00f3n petrolera y despliegues militares en localidades cercanas al \u00e1rea bajo pleito, sin anunciar, de momento, una incursi\u00f3n en la zona en litigio.<\/p>\n<p>\u00abGuyana debe saber que arreglamos este problema por las buenas o lo arreglamos\u00bb, dijo el mandatario -aplaudido por ministros, militares, alcaldes y gobernadores-, tras anunciar nueve decisiones que marcan el nuevo rumbo de Caracas en el pleito con Georgetown por los casi 160,000 kil\u00f3metros cuadrados del Esequibo.<\/p>\n<p>El acto, al que tambi\u00e9n asistieron diplom\u00e1ticos y opositores, se produjo dos d\u00edas despu\u00e9s del referendo unilateral en el que los ciudadanos, animados por el Ejecutivo, aprobaron anexionarse el \u00e1rea en disputa, en la que Venezuela no ejerce control desde 1899.<\/p>\n<p><strong id=\"strong-0ceec6363f4cc0ff1a992b2b618cb873\">Defensa y petr\u00f3leo<\/strong><\/p>\n<p>El presidente orden\u00f3 la creaci\u00f3n de una divisi\u00f3n militar para atender la zona en cuesti\u00f3n, sin anunciar ninguna incursi\u00f3n armada en el territorio, pues orden\u00f3 a la Fuerza Armada asentarse en una localidad pr\u00f3xima, pero no fronteriza, con el Esequibo, al menos de manera \u00abprovisional\u00bb.<\/p>\n<p>Esto, adelant\u00f3, cambiar\u00e1 una vez que el Parlamento, controlado por el chavismo, apruebe la ley de anexi\u00f3n de este territorio, lo que podr\u00eda ocurrir pronto, pues los diputados comenzar\u00e1n a debatir el asunto ma\u00f1ana.<\/p>\n<p>Maduro tambi\u00e9n pidi\u00f3 a los legisladores establecer una norma que proh\u00edba la contrataci\u00f3n de empresas \u00abque operen o colaboren en las concesiones\u00bb dadas por Guyana en el mar que Venezuela considera \u00abpendiente por delimitar\u00bb, y sugiri\u00f3 dar un lapso de tres meses a estas compa\u00f1\u00edas para que abandonen sus trabajos, relacionados principalmente con hidrocarburos.<\/p>\n<p>A la vez, pidi\u00f3 a la estatal petrolera Pdvsa que, \u00abde inmediato\u00bb, empiece a \u00abconceder licencias operativas para la exploraci\u00f3n y explotaci\u00f3n de petr\u00f3leo, gas y minas\u00bb en la Guayana Esequiba, nombre que llevar\u00e1 el estado que prev\u00e9n crear en la zona disputada.<\/p>\n<p>Aunque la orden fue girada con efecto inmediato, el mandatario no estim\u00f3 el tiempo que tardar\u00e1 en concretarse la primera concesi\u00f3n, lo que supondr\u00eda, en caso de producirse, la primera acci\u00f3n de Venezuela dentro del \u00e1rea desde el siglo XIX.<\/p>\n<p><strong id=\"strong-027ab41d3fa8a88e4fa57a1a304818a3\">Identidad y ambiente<\/strong><\/p>\n<p>Las resoluciones de Maduro tambi\u00e9n incluyeron la publicaci\u00f3n de un nuevo mapa nacional, que ser\u00e1 distribuido en todas las instituciones del Estado as\u00ed como en centros educativos, en el que la llamada \u00abzona en reclamaci\u00f3n\u00bb deja de serlo, \u00fanicamente para Venezuela, y se convierte en el estado Guayana Esequiba, despojando a Guyana de dos tercios de su geograf\u00eda.<\/p>\n<p>As\u00ed, Venezuela, que con la anexi\u00f3n pretendida superar\u00eda el mill\u00f3n de kil\u00f3metros cuadrados, prev\u00e9 empezar a entregar la nacionalidad a las 125,000 personas que habitan en el Esequibo, en su mayor\u00eda comunidades ind\u00edgenas, quienes no fueron consultados sobre las decisiones de Caracas ni se les ha otorgado la oportunidad de decidir sobre su futuro.<\/p>\n<p>Se trata -seg\u00fan el jefe del Estado- de \u00abla activaci\u00f3n inmediata de un plan de atenci\u00f3n humana y social\u00bb para esta poblaci\u00f3n que esperan someter a un censo, del que no se tienen detalles, y empezar a entregar c\u00e9dulas de identidad venezolanas.<\/p>\n<p>Asimismo, el pa\u00eds abrir\u00e1 una oficina del Servicio de Identificaci\u00f3n, Migraci\u00f3n y Extranjer\u00eda (Saime) en la localidad minera de Tumeremo, territorio venezolano, \u00abpara dirigir todos estos esfuerzos de identidad\u00bb.<\/p>\n<p>Maduro tambi\u00e9n propuso al Parlamento crear una ley para decretar \u00ab\u00e1reas de protecci\u00f3n especial\u00bb y la conformaci\u00f3n de \u00abnuevos parques protegidos que sean un centro de turismo\u00bb.<\/p>\n<p>Seg\u00fan dijo, este territorio -rico en minerales ha sido \u00abdescuartizado\u00bb por Guyana, por lo que \u00abamerita un plan especial para su recuperaci\u00f3n\u00bb, aunque no ofreci\u00f3 detalles al respecto.<\/p>\n<p><strong id=\"strong-d6cf29ba2eedc46b95fecf9323c1f42d\">La disputa<\/strong><\/p>\n<p>El l\u00edder chavista asumi\u00f3 la responsabilidad de las acciones anunciadas, entre las que se encuentra la creaci\u00f3n de una \u00abalta comisi\u00f3n por la defensa de la Guayana Esequiba\u00bb para escuchar a \u00abtodas las voces\u00bb del pa\u00eds, entre ellos universidades y sectores religiosos, para conocer sus puntos de vista sobre la disputa, que tampoco contempla tener en cuenta la postura de los esequibanos.<\/p>\n<p>Tras designar a un general como autoridad \u00fanica del territorio, sobre el que regir\u00e1 desde afuera \u00abprovisionalmente\u00bb, reiter\u00f3 que quiere la paz con Guyana.<\/p>\n<p>La controversia por este territorio data del siglo XIX, pero desde 2018 ha cobrado vigor en vista de la admisi\u00f3n del caso por parte de la Corte Internacional de Justicia (CIJ), que ha pedido a Venezuela no completar acciones que alteren la din\u00e1mica actual sobre el \u00e1rea, administrada por Guyana.<\/p>\n<p>Sin embargo, Maduro rechaza la mediaci\u00f3n de la CIJ en este asunto, un alegato que tambi\u00e9n se vio reforzado con el referendo, en el que los venezolanos acordaron no reconocer la jurisdicci\u00f3n del tribunal internacional que, de cualquier modo, emitir\u00e1 una decisi\u00f3n vinculante para las dos naciones en los meses por venir.<\/p>","protected":false},"excerpt":{"rendered":"<p>El plan del presidente Maduro no contempla una incursi\u00f3n inmediata en la zona del Esequibo. Caracas.- El presidente de Venezuela, Nicol\u00e1s Maduro, lanz\u00f3 este martes un plan de acci\u00f3n sobre el territorio en disputa con Guyana, que incluye el otorgamiento de licencias para la explotaci\u00f3n petrolera y despliegues militares en localidades cercanas al \u00e1rea bajo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":244971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-200328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=200328"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200328\/revisions"}],"predecessor-version":[{"id":244972,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200328\/revisions\/244972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/244971"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=200328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=200328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=200328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}