{"id":200210,"date":"2023-12-01T17:53:21","date_gmt":"2023-12-01T21:53:21","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/gobierno\/policia\/20231201\/la-policia-interviene-con-63-personas-con-estado-migratorio-no-definido-cerca-de-mayaguez\/"},"modified":"2025-07-11T23:46:54","modified_gmt":"2025-07-11T23:46:54","slug":"la-policia-interviene-con-63-personas-con-estado-migratorio-no-definido-cerca-de-mayaguez","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20231201\/la-policia-interviene-con-63-personas-con-estado-migratorio-no-definido-cerca-de-mayaguez\/","title":{"rendered":"La Polic\u00eda interviene con 63 personas con estado migratorio no definido cerca de Mayag\u00fcez"},"content":{"rendered":"<h3>Fueron entregados a efectivos del Border Patrol Aguadilla, los cuales se hicieron cargo del proceso investigativo.<\/h3>\n<p>La Polic\u00eda intervino poco despu\u00e9s del mediod\u00eda con 63 personas con estado migratorio no definido a 10 millas n\u00e1uticas de la antigua Correccional Guanajibo de Mayag\u00fcez.<\/p>\n<p>La intervenci\u00f3n fue realizada por personal de la Unidad Mar\u00edtima F.U.R.A. de Cabo Rojo, adscritos al Negociado de la Polic\u00eda de Puerto Rico. El grupo se divide en 56 hombres y 7 mujeres (dos de ellas embarazadas) e intentaban arribar a la isla.<\/p><div class=\"notic-content-middle\" id=\"notic-2355238716\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese Noticel_JUL-AGO 300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30143204\/Acodese-Noticel_JUL-AGO-300x250-1-1.png\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30143204\/Acodese-Noticel_JUL-AGO-300x250-1-1.png 300w, https:\/\/cdn.noticel.com\/2026\/07\/30143204\/Acodese-Noticel_JUL-AGO-300x250-1-1-14x12.png 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La intervenci\u00f3n se produjo como producto de un patrullaje de vigilancia mar\u00edtimo preventivo, en el que fue detectada la citada embarcaci\u00f3n, descrita como de fabricaci\u00f3n casera, azul, de unos 30 pies de eslora, con un motor fuera de borda, en la que viajaba el mencionado grupo de personas, que fueron entregados por los agentes federales del CBP, a efectivos del Border Patrol Aguadilla, los cuales se hicieron cargo del proceso investigativo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Fueron entregados a efectivos del Border Patrol Aguadilla, los cuales se hicieron cargo del proceso investigativo. La Polic\u00eda intervino poco despu\u00e9s del mediod\u00eda con 63 personas con estado migratorio no definido a 10 millas n\u00e1uticas de la antigua Correccional Guanajibo de Mayag\u00fcez. La intervenci\u00f3n fue realizada por personal de la Unidad Mar\u00edtima F.U.R.A. de Cabo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":245215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-200210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=200210"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200210\/revisions"}],"predecessor-version":[{"id":245216,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/200210\/revisions\/245216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/245215"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=200210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=200210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=200210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}