{"id":198616,"date":"2023-10-13T12:51:57","date_gmt":"2023-10-13T16:51:57","guid":{"rendered":"https:\/\/www.noticel.com\/article\/20231013\/tribunal-de-apelaciones-de-boston-atendera-pleito-del-municipio-de-morovis-contra-la-aaa\/"},"modified":"2025-07-12T01:36:32","modified_gmt":"2025-07-12T01:36:32","slug":"tribunal-de-apelaciones-de-boston-atendera-pleito-del-municipio-de-morovis-contra-la-aaa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20231013\/tribunal-de-apelaciones-de-boston-atendera-pleito-del-municipio-de-morovis-contra-la-aaa\/","title":{"rendered":"Tribunal de Apelaciones de Boston atender\u00e1 pleito del Municipio de Morovis contra la AAA"},"content":{"rendered":"<h3>Ayer, sin embargo, la corporaci\u00f3n p\u00fablica anunci\u00f3 proyectos valorados en $17 millones para dicho pueblo.<\/h3>\n<p>La alcaldesa de Morovis, Carmen Maldonado Gonz\u00e1lez, anunci\u00f3 que la Corte de Apelaciones en Boston acogi\u00f3 el reclamo de la representaci\u00f3n legal del municipio en el contexto de un pleito legal que la ejecutiva ha incoado contra la Autoridad de Acueductos y Alcantarillados (AAA).<\/p>\n<p>\u201cTal como prometido a los morove\u00f1os, el caso contin\u00faa. Precisamente el Tribunal nos concedi\u00f3 hasta inicios de noviembre para presentar los argumentos y estamos trabajando en eso. Siempre hemos estado claros en que esta es una lucha tipo David contra Goliat, pero no vamos a dar un paso atr\u00e1s\u201d, asegur\u00f3 la Alcaldesa en declaraciones escritas.<\/p>\n<p>El pasado 28 de abril, Maldonado inform\u00f3 que estaba apelando la desestimaci\u00f3n que hizo el Tribunal Federal de Distrito de Puerto Rico de la demanda presentada en agosto de 2019, cuando la Alcaldesa llev\u00f3 al tribunal a la AAA ante la crisis de servicio de agua potable en su pueblo. Aleg\u00f3 discrimen e incumplimiento con el deber ministerial.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20221103\/morovis-exige-respuestas-a-la-aaa\/\" id=\"link-f856121ff0f8e20a62be0cf5d6d2d691\" target=\"_blank\"><strong id=\"strong-cd669b8b0675c820cb9960939dc6c3f4\">Morovis exige respuestas a la AAA<\/strong><\/a><\/p>\n<p>\u201cLa desestimaci\u00f3n no se bas\u00f3 en que la AAA cumpliera con otorgar los servicios a los morove\u00f1os, pues los residentes al d\u00eda de hoy contin\u00faan sufriendo la escasez diaria de servicios. La sentencia b\u00e1sicamente da por cierto que los morove\u00f1os sufren los incumplimientos de la AAA, pero el Tribunal interpret\u00f3 que tal incumplimiento no es una violaci\u00f3n a los derechos civiles y al debido proceso. Nosotros diferimos y presentamos la apelaci\u00f3n\u201d, expres\u00f3 Maldonado.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/tribunales\/ahora\/20220602\/alcaldesa-de-morovis-demanda-a-la-aaa\/\" id=\"link-ef6c3e474aaaa3d8d7c564d1f5ad7436\" target=\"_blank\"><strong id=\"strong-7f64962e1500ffc5ee45c644c414b6e4\">Alcaldesa de Morovis demanda a la AAA<\/strong><\/a><\/p>\n<p>\u201cEstamos convencidos que este caso, m\u00e1s all\u00e1 de Morovis, ha de obligar a la AAA a comenzar a dejar atr\u00e1s su p\u00e9simo servicio en todo Puerto Rico y a que deje de perder m\u00e1s del 60% del agua que procesa. Todos los d\u00edas, en todo Puerto Rico se evidencia que la AAA no est\u00e1 cumpliendo, pero sigue cobrando sin fallar\u201d, subray\u00f3 Maldonado.<\/p><div class=\"notic-content-middle\" id=\"notic-130417367\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Desde enero de 2017 hasta el presente, el Municipio de Morovis ha gastado m\u00e1s de $1 mill\u00f3n comprando camiones cisterna para distribuir agua a sus residentes, comprando tanques de agua para abastecer a sus residentes, pagando a sus empleados para que laboren en la distribuci\u00f3n de agua y contrataci\u00f3n de expertos para analizar y asesorar sobre c\u00f3mo resolver el problema del servicio de agua, entre otros gastos\u201d, finaliz\u00f3 la alcaldesa Maldonado Gonz\u00e1lez.<\/p>\n<p>Tan reciente como ayer, la AAA anunci\u00f3 que estaba invirtiendo aproximadamente $17 millones en la etapa de dise\u00f1o el proyecto de mejoras al sistema de distribuci\u00f3n de Morovis.<\/p>\n<p>Sobre esta obra, la ejecutiva de la AAA expres\u00f3 que, \u201clos planes de trabajo para mejorar la infraestructura de la Autoridad en Morovis contin\u00faan avanzando. Actualmente se encuentra en dise\u00f1o un importante proyecto que rehabilitar\u00e1 el sistema de distribuci\u00f3n para beneficio de los clientes en Morovis. Esta obra incluye rehabilitaci\u00f3n de tanques, pozos, redes de distribuci\u00f3n, estaciones de bombas, entre otras\u201d.<\/p>\n<p>Entre las instalaciones beneficiadas se encuentran el tanque Morovis Urbano, el tanque Palmas del Sur, el tanque Pimientos, el tanque Arraijanes y el tanque El Cerro. De igual manera, las estaciones de bombas beneficiadas son El Cocal, Arraijanes y el pozo Arraijanes. Adem\u00e1s, se estar\u00e1n trabajando mejoras en las redes de distribuci\u00f3n de Fr\u00e1nquez, San Lorenzo, Jaguas Ventanas, zona de Mariv\u00ed Apartments, sector Font\u00e1n, El Cerro, entre otras.<\/p>\n<p>Entre las mejoras a los tanques se encuentran el reemplazo de puertas, v\u00e1lvulas, tuber\u00edas, construcci\u00f3n de aceras, construcci\u00f3n de caminos de acceso, sistemas de telemetr\u00eda, iluminaci\u00f3n, mejoras a los sistemas de desinfecci\u00f3n, pintura, sellado, entre otras.<\/p>\n<p>Este proyecto tiene un beneficio directo para aproximadamente 8,862 familias en Morovis y su fuente de financiamiento proviene de fondos de la Agencia Federal para el Manejo de Emergencias (FEMA, por sus siglas en ingl\u00e9s) bajo el programa FAAST (FEMA\u2019s Accelerated Obligation Strategy).<\/p>","protected":false},"excerpt":{"rendered":"<p>Ayer, sin embargo, la corporaci\u00f3n p\u00fablica anunci\u00f3 proyectos valorados en $17 millones para dicho pueblo. La alcaldesa de Morovis, Carmen Maldonado Gonz\u00e1lez, anunci\u00f3 que la Corte de Apelaciones en Boston acogi\u00f3 el reclamo de la representaci\u00f3n legal del municipio en el contexto de un pleito legal que la ejecutiva ha incoado contra la Autoridad de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":248529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-198616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/198616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=198616"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/198616\/revisions"}],"predecessor-version":[{"id":248530,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/198616\/revisions\/248530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/248529"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=198616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=198616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=198616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}